{"id":1270119,"date":"2024-07-09T23:34:34","date_gmt":"2024-07-09T23:34:34","guid":{"rendered":"https:\/\/teknomers.com\/es\/cuento-de-hadas-de-yamal-es-el-goleador-mas-joven-del-campeonato-de-europa-el-objetivo-queria-ponerlo-ahi-mismo\/"},"modified":"2024-07-09T23:35:42","modified_gmt":"2024-07-09T23:35:42","slug":"cuento-de-hadas-de-yamal-es-el-goleador-mas-joven-del-campeonato-de-europa-el-objetivo-queria-ponerlo-ahi-mismo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/cuento-de-hadas-de-yamal-es-el-goleador-mas-joven-del-campeonato-de-europa-el-objetivo-queria-ponerlo-ahi-mismo\/","title":{"rendered":"Cuento de hadas de Yamal: es el goleador m\u00e1s joven del Campeonato de Europa.  &#8220;\u00bfEl objetivo? Quer\u00eda ponerlo ah\u00ed mismo&#8230;&#8221;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><h2 class=\"is-subtitle\">Con s\u00f3lo 16 a\u00f1os y 362 d\u00edas el astro del Barcelona mejor\u00f3 el r\u00e9cord del suizo Vonlanthen establecido en 2004<\/h2>\n<\/p>\n<div class=\"bck-author-signature gz-hide-in-editor\">\n<div class=\"author-signature__content\">\n<div class=\"author-block\">\n<p>\n                                                    <span class=\"author-name\">Orazio Redi<\/span>\n                            <\/p>\n<p>\n                <time class=\"article-date xlk\" content=\"2024-07-09T23:50:54+02:00\" data-time=\"2024-07-09\"><\/p>\n<p>                    9 de julio de 2024 (modificado a las 23.50 h)  <span class=\"from-location\">&#8211; MIL\u00c1N<\/span><br \/>\n                <\/time>\n            <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"content \" id=\"m22405-22404-22406\">\n<p class=\"paragraph\" spellcheck=\"true\">Autor de una pincelada digna de los m\u00e1s grandes pintores, el jovenc\u00edsimo Lamine Yamal consigui\u00f3 golpear a Maignan con una perla de rara belleza, marcando as\u00ed un r\u00e9cord hist\u00f3rico en el 2-1 con el que Espa\u00f1a venci\u00f3 a Francia y consigui\u00f3 una plaza en la final de la Eurocopa. 2024. Porque con ese gol, Yamal se convirti\u00f3, con 16 a\u00f1os y 362 d\u00edas, en el goleador m\u00e1s joven de la historia de las fases finales de la Eurocopa. <\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m22410-22409-22411\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m22451-22450-22452\">adelantamiento<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">M\u00e1s all\u00e1 del gol y del r\u00e9cord en s\u00ed, lo que impresiona a\u00fan m\u00e1s es el momento en el que el joven espa\u00f1ol decidi\u00f3 escaparse: la semifinal de una Eurocopa.  La curiosidad es que el ex poseedor del r\u00e9cord, el suizo Johan Vonlanthen (18 a\u00f1os 141 d\u00edas), tambi\u00e9n marc\u00f3 su hist\u00f3rico gol contra Francia (en la Eurocopa 2004). <\/p>\n<\/div>\n<p><!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic END--><\/p>\n<div class=\"content content-paragraph \" id=\"m22420-22419-22421\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m22457-22456-22458\">Las palabras de Yamal.<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Veinte a\u00f1os despu\u00e9s, el Campeonato de Europa tiene un nuevo r\u00e9cord y, si tenemos en cuenta la diferencia de edad entre el primero y el segundo en esta clasificaci\u00f3n especial, parece leg\u00edtimo pensar que esta vez ser\u00e1 necesario incluso m\u00e1s para establecer un nuevo r\u00e9cord.  &#8220;Cuando marqu\u00e9 est\u00e1bamos pasando por un momento dif\u00edcil &#8211; palabras de Yamal &#8211; No esperaba marcar tan pronto, pero en ese momento trat\u00e9 de poner el bal\u00f3n exactamente donde entr\u00f3 y por eso tambi\u00e9n estoy tan feliz&#8221;. .  &#8220;Pero ahora trato de no pensar demasiado en ello &#8211; a\u00f1ade -, quiero disfrutar de este momento y ayudar al equipo, esperando seguir siendo feliz. Ahora quiero ganar, y el domingo quiero celebrar mi cumplea\u00f1os ( que es en v\u00edsperas de la final, ndr.) aqu\u00ed en Alemania con todo el equipo.&#8221;<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js fxr-left-center\">\n<div class=\"bck-copyright\">\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/div><\/div>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Europei\/09-07-2024\/lamine-yamal-e-il-marcatore-piu-giovane-di-sempre-nella-storia-degli-europei.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con s\u00f3lo 16 a\u00f1os y 362 d\u00edas el astro del Barcelona mejor\u00f3 el r\u00e9cord del suizo Vonlanthen establecido<\/p>\n","protected":false},"author":1,"featured_media":1270120,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[5178,1914,4503,38,348,13991,4504,4158,16,389,1043,66501,4113,43103],"class_list":["post-1270119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-ahi","tag-campeonato","tag-cuento","tag-del","tag-europa","tag-goleador","tag-hadas","tag-joven","tag-mas","tag-mismo","tag-objetivo","tag-ponerlo","tag-queria","tag-yamal"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1270119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1270119"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1270119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1270120"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1270119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1270119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1270119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}