{"id":1270116,"date":"2024-07-09T23:20:14","date_gmt":"2024-07-09T23:20:14","guid":{"rendered":"https:\/\/teknomers.com\/es\/burberry-tambien-esta-recortando-empleos\/"},"modified":"2024-07-09T23:20:18","modified_gmt":"2024-07-09T23:20:18","slug":"burberry-tambien-esta-recortando-empleos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/burberry-tambien-esta-recortando-empleos\/","title":{"rendered":"\u00bfBurberry tambi\u00e9n est\u00e1 recortando empleos?"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Se dice que la marca de lujo brit\u00e1nica Burberry se est\u00e1 preparando para recortes de empleos.<\/p>\n<p>En el marco de un programa de reestructuraci\u00f3n, como reacci\u00f3n a los resultados insatisfactorios, se eliminar\u00e1n varios centenares de puestos de trabajo, seg\u00fan informan varios medios de comunicaci\u00f3n.  Se cree que la empresa ha perdido un tercio de su valor de mercado desde principios de 2024, lo que la pone en riesgo de ser excluida de la Bolsa de Valores del Financial Times (FTSE) 100, seg\u00fan The Telegraph.  El diario brit\u00e1nico informa que los empleados fueron informados sobre las medidas de austeridad en una reuni\u00f3n por Zoom a principios de junio, aunque a\u00fan no se conoce el n\u00famero exacto de empleados afectados.<\/p>\n<p>En mayo, Burberry inform\u00f3 otra ca\u00edda de ganancias, esta vez para el primer trimestre del a\u00f1o, en el que las ventas cayeron un 12 por ciento.  En todo el pasado ejercicio financiero 23\/24, el beneficio operativo cay\u00f3 un 25 por ciento.<\/p>\n<p>El director ejecutivo de Burberry, Jonathan Akeroyd, dijo en ese momento que la implementaci\u00f3n del plan de recuperaci\u00f3n, que se centr\u00f3 principalmente en cambiar la imagen de la marca, evolucionar los productos y fortalecer la distribuci\u00f3n, se produjo en un contexto de &#8220;debilitamiento de la demanda de art\u00edculos de lujo&#8221;.<\/p>\n<p><em>Esta publicaci\u00f3n traducida y editada apareci\u00f3 anteriormente en FashionUnited.uk.<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/fashionunited.de\/nachrichten\/business\/baut-nun-auch-burberry-stellen-ab\/2024070857263\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-12<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se dice que la marca de lujo brit\u00e1nica Burberry se est\u00e1 preparando para recortes de empleos. En el<\/p>\n","protected":false},"author":1,"featured_media":1270117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[20561,17015,97,53448,733],"class_list":["post-1270116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-burberry","tag-empleos","tag-esta","tag-recortando","tag-tambien"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1270116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1270116"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1270116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1270117"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1270116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1270116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1270116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}