{"id":1269514,"date":"2024-07-09T13:46:17","date_gmt":"2024-07-09T13:46:17","guid":{"rendered":"https:\/\/teknomers.com\/es\/en-tegel-los-bomberos-solucionaran-en-algun-momento-el-problema-de-la-juventud\/"},"modified":"2024-07-09T13:46:22","modified_gmt":"2024-07-09T13:46:22","slug":"en-tegel-los-bomberos-solucionaran-en-algun-momento-el-problema-de-la-juventud","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/en-tegel-los-bomberos-solucionaran-en-algun-momento-el-problema-de-la-juventud\/","title":{"rendered":"En Tegel, los bomberos solucionar\u00e1n en alg\u00fan momento el problema de la juventud"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-4852450\">\n<figure class=\"position-relative mb-3\"><figcaption class=\"small fw-bold mt-1\">\n<p>         Las escaleras rojas de los bomberos en el atrio del nuevo edificio llaman la atenci\u00f3n en la futura academia de bomberos y salvamento en el antiguo aeropuerto de Tegel.                      <span class=\"fw-normal\">Foto de : Henn<\/span><br \/>\n            <\/figcaption><\/figure>\n<div class=\"entry-content col-auto col-lg-8 mx-auto\" style=\"min-width: 70%\">\n<p class=\"fw-bold\">\n<p>    Desde Hildburg-Bruns\n<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p class=\"fw-bold\">La fachada de aspecto muy t\u00e9cnico conecta lo antiguo y lo nuevo en Tegel.  El contrato para la futura academia de bomberos en el antiguo solar de TXL ha sido adjudicado al estudio de arquitectura HENN.<\/p>\n<\/div>\n<p>Adem\u00e1s del nuevo edificio, tambi\u00e9n se utilizar\u00e1n dos hangares catalogados y un nuevo edificio con escaleras rojas para bomberos en el atrio.  Est\u00e1 inundado de luz y conecta todas las plantas.  A trav\u00e9s del vest\u00edbulo, los alumnos y profesores pueden acceder a un comedor, a la terraza exterior, a la cafeter\u00eda y a una cafeter\u00eda. <\/p>\n<p>En las plantas superiores est\u00e1n previstas oficinas y salas de formaci\u00f3n.  Las fachadas este y oeste, as\u00ed como el tejado, cuentan con m\u00f3dulos solares para el suministro de energ\u00eda.<\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720532777_908_En-Tegel-los-bomberos-solucionaran-en-algun-momento-el-problema.jpg\" alt=\"El nuevo edificio previsto para la academia de bomberos con aspecto invernal\" loading=\"lazy\"  class=\"img-4852445 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         El nuevo edificio previsto para la academia de bomberos con aspecto invernal                      <span class=\"fw-normal\">Foto de : Henn<\/span><br \/>\n            <\/figcaption><\/figure>\n<p><strong>Pero, \u00bfcu\u00e1ndo estar\u00e1 lista la construcci\u00f3n h\u00edbrida con madera?  El nuevo edificio (15.000 metros cuadrados) estar\u00e1 listo en 2028.  \u00a1En los c\u00edrculos parlamentarios la fecha para toda la zona de los hangares era incluso del a\u00f1o 2035!  Primero hay que retirar de los hangares el amianto y posibles armas de la \u00faltima guerra mundial.  Costes totales \u00faltimos mencionados: 240 millones de euros.<\/strong><\/p>\n<\/p><\/div>\n<section data-type=\"tag-links\" class=\"d-flex align-items-center gap-2 mt-4 mb-2\">\n            <span class=\"fw-bold text-nowrap\">Asignaturas: <\/span><br \/>\n            <span class=\"d-flex gap-2 overflow-scroll hide-scrollbar\" data-actions=\"scroll-horizontal\"><\/p>\n<p>                            Cuerpo de Bomberos<br \/>\n                        <\/span><br \/>\n        <\/section>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/berlin\/reinickendorf\/tegel-feuerwehr-nachwuchs\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las escaleras rojas de los bomberos en el atrio del nuevo edificio llaman la atenci\u00f3n en la futura<\/p>\n","protected":false},"author":1,"featured_media":1269515,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[11637,22802,16148,36,2602,2349,133417,21761],"class_list":["post-1269514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-algun","tag-bomberos","tag-juventud","tag-los","tag-momento","tag-problema","tag-solucionaran","tag-tegel"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1269514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1269514"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1269514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1269515"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1269514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1269514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1269514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}