{"id":1269496,"date":"2024-07-09T13:32:09","date_gmt":"2024-07-09T13:32:09","guid":{"rendered":"https:\/\/teknomers.com\/es\/intenso-rumor-sobre-gordon-se-agita-en-sbs-6-nunca-confirmado\/"},"modified":"2024-07-09T13:32:14","modified_gmt":"2024-07-09T13:32:14","slug":"intenso-rumor-sobre-gordon-se-agita-en-sbs-6-nunca-confirmado","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/intenso-rumor-sobre-gordon-se-agita-en-sbs-6-nunca-confirmado\/","title":{"rendered":"Intenso rumor sobre Gordon se agita en SBS 6: &#8216;Nunca confirmado&#8217;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Bart Ettekoven ha despertado un picante rumor sobre Gordon en Shownieuws.  \u201c\u00a1Se rumoreaba que lo hab\u00edan cubierto de alquitr\u00e1n y de plumas en el cumplea\u00f1os de Linda de Mol!\u201d<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 SBS<\/span> <\/div>\n<p>El infame presentador Jan Roos grit\u00f3 en 2014 que Gordon esnif\u00f3 abiertamente coca\u00edna en la fiesta del quincuag\u00e9simo cumplea\u00f1os de Linda de Mol, acos\u00f3 a otros invitados con ella y luego fue despedido.  Gordon qued\u00f3 at\u00f3nito en ese momento e incluso consider\u00f3 presentar una demanda contra la estrella de Gossip Talk.<\/p>\n<h2 class=\"wp-block-heading\">rumor de coca<\/h2>\n<p>Las amenazas legales no causaron mucha impresi\u00f3n en Jan, porque repiti\u00f3 el rumor en 2020 y un a\u00f1o despu\u00e9s revel\u00f3 la fuente que supuestamente le susurr\u00f3 esto en ese momento: su sobrina Saskia Noort.  El escritor, con quien Jan est\u00e1 completamente en desacuerdo, tambi\u00e9n estuvo presente en el cumplea\u00f1os de Linda.<\/p>\n<p>Gordon respondi\u00f3 a esto en 2021 en su entonces podcast GorDonDiablo Show.  \u201c\u00bfDe d\u00f3nde lo saca?  Tambi\u00e9n me acus\u00f3 una vez de traficar coca en la fiesta de Linda de Mol.  Si alguien toma coca\u00edna es Saskia Noort con ehhh&#8230; \u00bfC\u00f3mo se llama esa otra escritora?  (\u2026) Kluun\u201d.<\/p>\n<h2 class=\"wp-block-heading\">Diez a\u00f1os despu\u00e9s<\/h2>\n<p>No es que Jan fuera el \u00fanico que difundi\u00f3 el rumor, porque a Henk Spaan tambi\u00e9n se le ocurri\u00f3 este chisme.  \u201c\u00c9l lo niega, y Linda tambi\u00e9n lo niega, pero eso efectivamente sucedi\u00f3, lo s\u00e9 por gente que estuvo all\u00ed\u201d, grit\u00f3 con firmeza.<\/p>\n<p>Han pasado diez a\u00f1os: Linda tiene ahora sesenta a\u00f1os y eso se mencion\u00f3 anoche en <a rel=\"nofollow noopener\" href=\"https:\/\/www.kijk.nl\/programmas\/shownieuws\/guwcvbuNJ2Y\" target=\"_blank\">Mostrar noticias<\/a>.  \u201cSi te preguntas si hoy lo celebr\u00f3 a lo grande: \u00a1no!  El domingo, en un c\u00edrculo familiar privado.  Naturalmente, su hija Noa hab\u00eda regresado especialmente para esto de Alemania\u201d, dice el experto en espect\u00e1culos Bart Ettekoven.<\/p>\n<h2 class=\"wp-block-heading\">Aument\u00f3<\/h2>\n<p>Su colega Anouk Smulders se\u00f1ala: \u201c\u00bfQuiere decir &#8216;no se celebr\u00f3 a lo grande&#8217;, porque ella celebr\u00f3 sus 50 a\u00f1os a lo grande?\u201d<\/p>\n<p>Entonces Bart despierta el rumor sobre Gordon.  \u201cS\u00ed, exactamente, todo el mundo todav\u00eda recuerda aquella fiesta n\u00famero 50 en su jard\u00edn.  Todos estaban sentados en largas mesas disfrutando de una deliciosa comida, llegaron Ren\u00e9 Froger, Chantal Janzen y Gordon, de quien luego se rumoreaba que hab\u00eda sido desalojado de all\u00ed\u201d.<\/p>\n<h2 class=\"wp-block-heading\">Cobertizo de jard\u00edn<\/h2>\n<p>Al parecer, Winston Gerschtanowitz sabe m\u00e1s al respecto.  &#8220;Oh, s\u00ed, ese en ese cobertizo del jard\u00edn o algo as\u00ed&#8230;&#8221;<\/p>\n<p>\u00bfCobertizo de jard\u00edn?  Eh, eso a\u00fan no hab\u00eda salido en la prensa&#8230; Bart lo interrumpe: \u201cS\u00ed, no s\u00e9 qu\u00e9 pas\u00f3, pero no pudo soportar la luz del d\u00eda, pero de todos modos: eso nunca ha sido confirmado. por cualquiera de las partes\u201d.<\/p>\n<p>Winston: &#8220;S\u00ed, s\u00ed, s\u00ed&#8230;&#8221;<\/p>\n<h2 class=\"wp-block-heading\">Drama<\/h2>\n<p>Esta vez Linda no organiz\u00f3 una fiesta de celebridades.  \u201cTal vez Linda pens\u00f3: bueno, para evitar tal drama\u2026 No, ella tambi\u00e9n est\u00e1 en medio de la grabaci\u00f3n de Gooische Vrouwen, as\u00ed que tal vez no tuvo tiempo para ello\u201d.<\/p>\n<p>Linda fue a la oficina editorial de LINDA.  &#8220;As\u00ed que no todo pas\u00f3 en silencio&#8221;.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2024\/07\/heftig-gerucht-over-gordon-opgerakeld-op-sbs-6-nooit-bevestigd\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bart Ettekoven ha despertado un picante rumor sobre Gordon en Shownieuws. \u201c\u00a1Se rumoreaba que lo hab\u00edan cubierto de<\/p>\n","protected":false},"author":1,"featured_media":1269497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[41560,787,15093,4241,110264,78,23920,19061,131],"class_list":["post-1269496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-agita","tag-confirmado","tag-gordon","tag-intenso","tag-linda-de-mol","tag-nunca","tag-rumor","tag-sbs","tag-sobre"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1269496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1269496"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1269496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1269497"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1269496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1269496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1269496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}