{"id":1268367,"date":"2024-07-08T17:28:07","date_gmt":"2024-07-08T17:28:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-perpetrador-dijo-lo-siento-hermano-pero-deberias-morir\/"},"modified":"2024-07-08T17:28:12","modified_gmt":"2024-07-08T17:28:12","slug":"el-perpetrador-dijo-lo-siento-hermano-pero-deberias-morir","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-perpetrador-dijo-lo-siento-hermano-pero-deberias-morir\/","title":{"rendered":"El perpetrador dijo: &#8220;Lo siento, hermano, pero deber\u00edas morir&#8221;."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div style=\"min-width: 70%\">\n<p class=\"fw-bold\">\n<p>    Por Anne Losensky\n<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p class=\"fw-bold\">El asesino del coraz\u00f3n rosa en el pecho a\u00fan recuerda exactamente lo que pensaba entonces mientras esperaba de noche a orillas del Spree, en Pl\u00e4nterwald: \u201c\u00a1No importa con qui\u00e9n me cruce ahora, lo apu\u00f1alar\u00e9 en breve!\u201d. despu\u00e9s muri\u00f3 un corredor&#8230;<\/p>\n<\/div>\n<p>Tribunal regional, sala 701. La fiscal\u00eda no quiere enviar a Adel J. (35) a prisi\u00f3n, sino a un internado psiqui\u00e1trico cerrado para siempre.  Es imputado en el proceso de seguridad.  Nacido en Berl\u00edn.  Pasaporte alem\u00e1n.  Dej\u00f3 de estudiar.<\/p>\n<h2 class=\"wp-block-heading\">Un corredor fue apu\u00f1alado seis veces en el cuello<\/h2>\n<p>El 20 de noviembre de 2023 se entreg\u00f3 a la polic\u00eda por la noche.  Sobre su sudadera con capucha oscura brilla un gran coraz\u00f3n rosa: all\u00ed est\u00e1 escrito &#8220;I (Heart) Berlin&#8221;.  Acaba de clavar seis veces un cuchillo en el cuello de Finn M. (29) a orillas del Spree.  El dise\u00f1ador gr\u00e1fico corri\u00f3 all\u00ed despu\u00e9s del trabajo.<\/p>\n<figure class=\"position-relative wp-block-image\"><figcaption class=\"small fw-bold mt-1\">\n<p>         Las manos del sospechoso fueron colocadas en una bolsa para asegurar posibles pruebas.                      <span class=\"fw-normal\">Foto de : Spreepicture<\/span><br \/>\n            <\/figcaption><\/figure>\n<p>\u201cUna de las pu\u00f1aladas entr\u00f3 por delante y sali\u00f3 por detr\u00e1s\u201d, dice la autopsia.  \u201cLo bes\u00e9 en la frente mientras yac\u00eda en el suelo\u201d, recuerda el apu\u00f1alador.  &#8220;Dijo: Lo siento, hermano, pero morir\u00e1s&#8221;.<\/p>\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-b-z-die-stimme-berlins wp-block-embed-b-z-die-stimme-berlins\"\/>\n<p><strong>Anteriormente hab\u00eda estado en un club: \u201cPero las cosas no salieron seg\u00fan lo planeado\u201d, afirma.  \u201cMalos pensamientos\u201d se hab\u00edan extendido por su mente: \u201cEstaba decidido a vengarme.  Ten\u00eda una sensaci\u00f3n de ser especial, de ser mejor.  Pens\u00e9 que ten\u00eda derecho a actuar as\u00ed.  Quien lleg\u00f3 all\u00ed fue ese.  Lo siento por \u00e9l.  \u00c9l no se merec\u00eda eso.  Fui a la gasolinera y dije: mat\u00e9 a alguien, llama a la polic\u00eda\u201d. <\/strong><\/p>\n<p>El exalumno llevaba a\u00f1os recibiendo tratamiento psiqui\u00e1trico, pero no hab\u00eda tomado sus comprimidos. <\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720459687_498_El-perpetrador-dijo-Lo-siento-hermano-pero-deberias-morir.jpg\" alt=\"Rescatistas en el lugar: m\u00e9dicos de urgencias y param\u00e9dicos intentan reanimar al hombre\" loading=\"lazy\"  class=\"img-4852127 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         Rescatistas en el lugar: m\u00e9dicos de urgencias y param\u00e9dicos intentan reanimar al corredor                      <span class=\"fw-normal\">Foto de : spreepicture<\/span><br \/>\n            <\/figcaption><\/figure>\n<p><em>Un ciclista acababa de verlo gritar furiosamente: \u201c\u00a1Vais a iros todos al carajo, voy a matar a alguien!\u201d Veredicto del 17 de junio.<\/em><\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"250\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720459687_434_El-perpetrador-dijo-Lo-siento-hermano-pero-deberias-morir.jpg\" alt=\"\" loading=\"lazy\"  class=\"img-4791995 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><\/p>\n<\/figure><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/polizei\/menschen-vor-gericht\/jogger-getoetet-taeter-gesteht-prozess\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Anne Losensky El asesino del coraz\u00f3n rosa en el pecho a\u00fan recuerda exactamente lo que pensaba entonces<\/p>\n","protected":false},"author":1,"featured_media":1268368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[23075,61,3831,12695,267,12882,5826],"class_list":["post-1268367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-deberias","tag-dijo","tag-hermano","tag-morir","tag-pero","tag-perpetrador","tag-siento"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268367"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268368"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}