{"id":1268347,"date":"2024-07-08T17:14:19","date_gmt":"2024-07-08T17:14:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-luz-verde-para-que-msc-se-una-a-hhla-probablemente-solo-se-dara-despues-de-las-vacaciones-de-verano\/"},"modified":"2024-07-08T17:14:23","modified_gmt":"2024-07-08T17:14:23","slug":"la-luz-verde-para-que-msc-se-una-a-hhla-probablemente-solo-se-dara-despues-de-las-vacaciones-de-verano","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-luz-verde-para-que-msc-se-una-a-hhla-probablemente-solo-se-dara-despues-de-las-vacaciones-de-verano\/","title":{"rendered":"La luz verde para que MSC se una a HHLA probablemente solo se dar\u00e1 despu\u00e9s de las vacaciones de verano"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>HAMBURGO (dpa-AFX) &#8211; El Parlamento de Hamburgo probablemente no podr\u00e1 aprobar finalmente la entrada prevista por el Senado de la mayor compa\u00f1\u00eda naviera del mundo, MSC, en la empresa de log\u00edstica portuaria de la ciudad, HHLA, hasta despu\u00e9s de las vacaciones de verano.  La CDU y la izquierda quieren oponerse a la votaci\u00f3n prevista por el Partido Rojo-Verde sobre los planes en primera y segunda lectura en la \u00faltima reuni\u00f3n antes de las vacaciones de verano de este mi\u00e9rcoles, como se anunci\u00f3 el lunes por la tarde tras las reuniones del grupo parlamentario.  Son necesarias dos lecturas para la decisi\u00f3n final.<\/p>\n<p>Seg\u00fan el Reglamento de Ciudadan\u00eda, una quinta parte de los diputados presentes puede oponerse a una segunda lectura en la misma sesi\u00f3n.  Con un total de 25 diputados, la CDU y la izquierda tienen poco m\u00e1s de una quinta parte de los mandatos y, por tanto, podr\u00edan retrasar la decisi\u00f3n hasta la pr\u00f3xima reuni\u00f3n de los ciudadanos, prevista para el 4 de septiembre tras las vacaciones de verano.<!-- sh_cad_2 --><\/p>\n<p>El AfD tambi\u00e9n se pronunci\u00f3 en contra del acuerdo y, al igual que la izquierda, exigi\u00f3 que se permitiera a los habitantes de Hamburgo votar directamente sobre el \u201cacuerdo del siglo\u201d.  Sin embargo, no hay dudas sobre la aprobaci\u00f3n de los ciudadanos dada la mayor\u00eda rojiverde de dos tercios.<\/p>\n<p>La oposici\u00f3n quiere rechazar el consentimiento<\/p>\n<p>El acuerdo entre MSC y HHLA es malo para Hamburgo, afirm\u00f3 el lunes por la tarde el l\u00edder del grupo parlamentario de la CDU, Dennis Thering.  &#8220;No s\u00f3lo nosotros en la oposici\u00f3n lo vemos as\u00ed, sino tambi\u00e9n muchos expertos e incluso dentro de nuestras propias filas del SPD y de los Verdes hay resistencia. Los riesgos superan claramente las oportunidades y por eso rechazaremos la aprobaci\u00f3n por segunda vez leyendo el mi\u00e9rcoles.&#8221;<!-- sh_cad_4 --><\/p>\n<p>El retraso da a la coalici\u00f3n rojiverde la oportunidad de \u201creconsiderar esta decisi\u00f3n, que tiene consecuencias de gran alcance para nuestra ciudad y nuestro puerto\u201d, afirm\u00f3 Thering.  &#8220;La participaci\u00f3n de MSC podr\u00eda significar que la ciudad de Hamburgo ya no tenga control total sobre el puerto, lo que podr\u00eda tener un impacto especialmente negativo en las decisiones estrat\u00e9gicas y cada diputado deber\u00eda pens\u00e1rselo dos veces durante las vacaciones de verano&#8221;.<\/p>\n<p>Seg\u00fan los planes del Senado, MSC poseer\u00e1 el 49,9 por ciento de HHLA en el futuro<\/p>\n<p>Seg\u00fan los planes del Senado, la ciudad y la empresa MSC, que pertenece a la familia naviera italiana Aponte, gestionar\u00e1n en el futuro HHLA como una empresa conjunta en la que la ciudad posee una mayor\u00eda del 50,1 por ciento.  Anteriormente, la ciudad pose\u00eda alrededor del 70 por ciento de la HHLA que cotiza en bolsa.<!-- sh_cad_6 --><\/p>\n<p>A cambio, MSC quiere construir su sede alemana en Hamburgo, aumentar el volumen de carga a partir de 2025 y aumentarlo a un mill\u00f3n de contenedores est\u00e1ndar (TEU) por a\u00f1o para 2031.  Adem\u00e1s, MSC y la ciudad quieren aumentar el capital social de HHLA en 450 millones de euros.\/fi\/DP\/men<\/p>\n<\/div>\n<div id=\"\">\n<h2 class=\"headline headline--h4\">Productos de apalancamiento seleccionados en HHLA<\/h2>\n<p>Con los knock-outs, los inversores especulativos pueden participar desproporcionadamente en los movimientos de precios.  Simplemente seleccione la palanca que desee y le mostraremos los productos abiertos adecuados en HHLA.<\/p>\n<p class=\"font-color-red display-none\" id=\"lvgCustomHandleInfo\">El apalancamiento debe estar entre 2 y 20<\/p>\n<p><span class=\"ad-hint ad-hint--right display-block\">Publicidad<\/span><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/gruenes-licht-zum-msc-einstieg-bei-hhla-wohl-erst-nach-der-sommerpause-13654913\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HAMBURGO (dpa-AFX) &#8211; El Parlamento de Hamburgo probablemente no podr\u00e1 aprobar finalmente la entrada prevista por el Senado<\/p>\n","protected":false},"author":1,"featured_media":1230996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[3337,755,119337,246,4146,33586,18,643,2525,158,5083,3029,106],"class_list":["post-1268347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzas","tag-dara","tag-despues","tag-hhla","tag-las","tag-luz","tag-msc","tag-para","tag-probablemente","tag-solo","tag-una","tag-vacaciones","tag-verano","tag-verde"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268347"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1230996"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}