{"id":1268274,"date":"2024-07-08T15:55:35","date_gmt":"2024-07-08T15:55:35","guid":{"rendered":"https:\/\/teknomers.com\/es\/ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado\/"},"modified":"2024-07-08T15:55:40","modified_gmt":"2024-07-08T15:55:40","slug":"ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado\/","title":{"rendered":"Ciclista atropellado por una motocicleta policial en un cruce cerrado"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-4851951\">\n<figure class=\"position-relative mb-3\"><figcaption class=\"small fw-bold mt-1\">\n<p>         El ciclista (33) es atropellado por la moto policial y sale volando por los aires                      <span class=\"fw-normal\">Foto: Michael Giesecke\/Facebook<\/span><br \/>\n            <\/figcaption><\/figure>\n<div class=\"entry-content col-auto col-lg-8 mx-auto\" style=\"min-width: 70%\">\n<p class=\"fw-bold\">\n<p>    Por Maren Wittge\n<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p class=\"fw-bold\">\u00a1Choque de terror el s\u00e1bado en Berl\u00edn-Wilmersdorf!  La imprudencia de la ciclista (33) casi le cuesta la vida.  La mujer circulaba en bicicleta por un cruce cerrado por la polic\u00eda y fue atropellada por una motocicleta policial. <\/p>\n<\/div>\n<p><em>Un residente grab\u00f3 las dram\u00e1ticas escenas con su tel\u00e9fono celular el s\u00e1bado. <\/em><\/p>\n<p>El v\u00eddeo muestra c\u00f3mo una avanzada de la polic\u00eda berlinesa en motocicleta cerr\u00f3 el cruce entre Trautenaustra\u00dfe y Bundesallee el s\u00e1bado alrededor de las 12:30 horas.  Poco despu\u00e9s deb\u00eda pasar un desfile de motociclistas registrado en direcci\u00f3n norte por Bundesallee. <\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720454134_425_Ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado.jpg\" alt=\"El ciclista recorre el carril bici.  Todav\u00eda mira al polic\u00eda en motocicleta, pero ya es demasiado tarde.  Ella ya no puede frenar\" loading=\"lazy\"  class=\"img-4851963 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         El ciclista recorre el carril bici.  Todav\u00eda mira al polic\u00eda en motocicleta, pero ya es demasiado tarde.  Ella ya no puede frenar                      <span class=\"fw-normal\">Foto: Michael Giesecke\/Facebook<\/span><br \/>\n            <\/figcaption><\/figure>\n<p><strong>\u201cSeg\u00fan declaraciones de testigos, el cierre de la carretera era evidente\u201d, afirma un portavoz de la polic\u00eda. <\/strong><\/p>\n<p>De repente, el ciclista sale de Trautenaustra\u00dfe por el carril bici y quiere cruzar la Bundesallee.<\/p>\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-b-z-die-stimme-berlins wp-block-embed-b-z-die-stimme-berlins\"\/>\n<p>Antes de que el hombre de 33 a\u00f1os llegara a la isla central, un agente lleg\u00f3 en su motocicleta policial a Bundesallee, cruz\u00f3 el cruce y atrap\u00f3 a la mujer en la bicicleta.<\/p>\n<p>El ciclista vuela por el aire y choca contra el asfalto.  El polic\u00eda en motocicleta se detiene inmediatamente y otro agente corre hacia la mujer herida y la atiende.  Entonces el v\u00eddeo se detiene.<\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"558\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720454135_917_Ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado.jpg\" alt=\"La mujer herida yace sobre el asfalto.  El polic\u00eda en motocicleta se detuvo.\" loading=\"lazy\"  class=\"img-4851966 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><figcaption class=\"small fw-bold mt-1\">\n<p>         La mujer herida yace sobre el asfalto.  El polic\u00eda en motocicleta se detuvo.                      <span class=\"fw-normal\">Foto: Michael Giesecke\/Facebook<\/span><br \/>\n            <\/figcaption><\/figure>\n<p><strong>Una ambulancia de los bomberos de Berl\u00edn traslad\u00f3 al herido al hospital.  Seg\u00fan la polic\u00eda, la mujer result\u00f3 herida en la pierna y pudo abandonar la cl\u00ednica el mismo d\u00eda despu\u00e9s del tratamiento ambulatorio. <\/strong><\/p>\n<figure class=\"position-relative wp-block-image\">\n            <img decoding=\"async\" width=\"992\" height=\"250\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720454135_996_Ciclista-atropellado-por-una-motocicleta-policial-en-un-cruce-cerrado.jpg\" alt=\"\" loading=\"lazy\"  class=\"img-4791995 img-fluid w-100 size-xl d-inline-block bg-fallback\"\/><\/p>\n<\/figure><\/div>\n<section data-type=\"tag-links\" class=\"d-flex align-items-center gap-2 mt-4 mb-2\">\n            <span class=\"fw-bold text-nowrap\">Asignaturas: <\/span><br \/>\n            <span class=\"d-flex gap-2 overflow-scroll hide-scrollbar\" data-actions=\"scroll-horizontal\"><\/p>\n<p>                            Bomberos de Berl\u00edn Polic\u00eda de Berl\u00edn BILD\/BZ Accidente de tr\u00e1fico<br \/>\n                        <\/span><br \/>\n        <\/section>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/polizei\/radlerin-von-polizei-motorrad-erfasst\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ciclista (33) es atropellado por la moto policial y sale volando por los aires Foto: Michael Giesecke\/Facebook<\/p>\n","protected":false},"author":1,"featured_media":1268275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[4219,3041,6292,15702,16552,9025,231,158],"class_list":["post-1268274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-atropellado","tag-cerrado","tag-ciclista","tag-cruce","tag-motocicleta","tag-policial","tag-por","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268274"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268275"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}