{"id":1268265,"date":"2024-07-08T15:50:16","date_gmt":"2024-07-08T15:50:16","guid":{"rendered":"https:\/\/teknomers.com\/es\/azafato-borracho-recibe-una-multa-durante-un-control-de-alcohol-en-schiphol\/"},"modified":"2024-07-08T15:50:21","modified_gmt":"2024-07-08T15:50:21","slug":"azafato-borracho-recibe-una-multa-durante-un-control-de-alcohol-en-schiphol","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/azafato-borracho-recibe-una-multa-durante-un-control-de-alcohol-en-schiphol\/","title":{"rendered":"Azafato borracho recibe una multa durante un control de alcohol en Schiphol"},"content":{"rendered":"\n<div>\n<p>El control de alcoholemia fue realizado por el equipo de Vigilancia A\u00e9rea de la polic\u00eda y la Real Polic\u00eda Militar.  El azafato, que trabaja para una aerol\u00ednea extranjera, tuvo que someterse a una prueba de alcoholemia alrededor de las 7:50 de la ma\u00f1ana y result\u00f3 que hab\u00eda bebido alcohol poco antes del vuelo. <\/p>\n<h2>Pol\u00edtica de tolerancia cero en la aviaci\u00f3n<\/h2>\n<p>La prueba de alcoholemia mostr\u00f3 que el azafato hab\u00eda bebido casi tres veces m\u00e1s de lo permitido a los conductores de veh\u00edculos.  Estos requisitos son a\u00fan m\u00e1s estrictos en el \u00e1mbito de la aviaci\u00f3n.  Seg\u00fan la pol\u00edtica de tolerancia cero, la tripulaci\u00f3n de vuelo no puede consumir alcohol diez horas antes del vuelo.  Se aplica un contenido m\u00e1ximo de alcohol de 0,2. <\/p>\n<p>El azafato fue multado con 1.000 euros por el fiscal del Ministerio P\u00fablico.  Despu\u00e9s de pagar la multa, pudo irse, pero su vuelo programado despeg\u00f3 sin \u00e9l.  No est\u00e1 claro si su aerol\u00ednea ha atribuido alguna consecuencia al consumo prohibido de alcohol. <\/p>\n<h2>alcohol\u00edmetro<\/h2>\n<p>Seg\u00fan la polic\u00eda, se llevaron a cabo en total diez controles en distintos lugares de Schiphol.  El Equipo de Supervisi\u00f3n A\u00e9rea realiza peri\u00f3dicamente este tipo de controles a pilotos y tripulantes de cabina.  Esto sucede en el centro de tripulaci\u00f3n, en la puerta de embarque y en el avi\u00f3n. <\/p>\n<p>Las pruebas de alcoholemia no se anuncian y se controlan tanto a empresas nacionales como extranjeras.  Es obligatorio cooperar.  Si se niega a controlar, tambi\u00e9n se le impondr\u00e1 una multa y ya no se le permitir\u00e1 subir al avi\u00f3n. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/338121\/beschonken-steward-krijgt-boete-bij-alcoholcontrole-op-schiphol\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El control de alcoholemia fue realizado por el equipo de Vigilancia A\u00e9rea de la polic\u00eda y la Real<\/p>\n","protected":false},"author":1,"featured_media":1268266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[8381,136129,23533,2343,885,5969,3064,10510,158],"class_list":["post-1268265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-alcohol","tag-azafato","tag-borracho","tag-control","tag-durante","tag-multa","tag-recibe","tag-schiphol","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268265"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268266"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}