{"id":1268259,"date":"2024-07-08T15:48:12","date_gmt":"2024-07-08T15:48:12","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-primer-ministro-schoof-recibe-un-asentimiento-amistoso-en-bruselas-durante-su-primera-aparicion-internacional\/"},"modified":"2024-07-08T15:48:17","modified_gmt":"2024-07-08T15:48:17","slug":"el-primer-ministro-schoof-recibe-un-asentimiento-amistoso-en-bruselas-durante-su-primera-aparicion-internacional","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-primer-ministro-schoof-recibe-un-asentimiento-amistoso-en-bruselas-durante-su-primera-aparicion-internacional\/","title":{"rendered":"El Primer Ministro Schoof recibe un &#8220;asentimiento amistoso&#8221; en Bruselas durante su primera aparici\u00f3n internacional"},"content":{"rendered":"\n<div>\n<p>Lleg\u00f3 con una &#8220;actitud constructiva&#8221;, pero al mismo tiempo quer\u00eda &#8220;luchar por los intereses holandeses&#8221;.  Con estas palabras describi\u00f3 el primer ministro Dick Schoof su primera visita este lunes a Bruselas, donde mantuvo conversaciones introductorias con los presidentes de la Comisi\u00f3n Europea, el Consejo Europeo y el Parlamento Europeo.  Fue la primera aparici\u00f3n internacional de Schoof despu\u00e9s de haber prestado juramento la semana pasada.  Posteriormente, el Primer Ministro habl\u00f3 de un &#8220;muy buen ambiente&#8221; y de &#8220;conversaciones \u00fatiles&#8221;. <\/p>\n<p>Como nuevo Primer Ministro, Schoof no se enfrenta a una tarea f\u00e1cil en Bruselas: seg\u00fan el acuerdo principal, los cuatro partidos de la coalici\u00f3n quieren todo tipo de excepciones para los Pa\u00edses Bajos en la UE, tambi\u00e9n en el \u00e1mbito de las normas migratorias y agr\u00edcolas.  Schoof y sus ministros tendr\u00e1n la tarea de lograr que se cumpla ese paquete de demandas en el pr\u00f3ximo per\u00edodo. <\/p>\n<p>Eso no ser\u00e1 f\u00e1cil: detr\u00e1s de escena en Bruselas, las demandas holandesas hasta ahora han sido respondidas con sorpresa y sospecha.  Por ejemplo, el deseo de los holandeses de obtener la llamada &#8220;exclusi\u00f3n voluntaria&#8221; en materia de pol\u00edtica migratoria se considera inviable.  Y un nuevo intento de obtener una excepci\u00f3n a las normas sobre naturaleza y esti\u00e9rcol tampoco parece realista por el momento.  <\/p>\n<h2 class=\"gn4-crosshead article-heading\">intereses holandeses<\/h2>\n<p>Despu\u00e9s de sus conversaciones, Schoof subray\u00f3 que hay &#8220;algunos expedientes en los que realmente queremos consultar con la Uni\u00f3n Europea&#8221;.  Todav\u00eda es demasiado pronto para obtener resultados concretos, pero seg\u00fan el Primer Ministro hubo un &#8220;asentimiento amistoso&#8221; y &#8220;la gente entiende muy bien que los intereses holandeses son importantes para los Pa\u00edses Bajos&#8221;.  Como la migraci\u00f3n y la agricultura tambi\u00e9n son temas urgentes en Europa, seg\u00fan Schoof, &#8220;hay mucho espacio para discutir esto entre nosotros&#8221;.<\/p>\n<p>Schoof no quiso hacer ninguna declaraci\u00f3n sobre el nombramiento de un nuevo comisario europeo holand\u00e9s, excepto que ya ha discutido el tema &#8220;muy detenidamente&#8221; con la presidenta de la Comisi\u00f3n, Ursula von der Leyen.  La semana pasada, Schoof mantuvo abierta la opci\u00f3n de que el actual Comisario Europeo Wopke Hoekstra (Clima) sea redesignado.  Ahora Schoof se limita a repetir que cree que los Pa\u00edses Bajos no podr\u00e1n obtener un &#8220;puesto muy pesado&#8221; en la nueva Comisi\u00f3n, porque ya lo tuvieron en los \u00faltimos a\u00f1os con el primer vicepresidente Frans Timmermans.<\/p>\n<p>Sin embargo, Schoof destac\u00f3 que existe un &#8220;l\u00edmite inferior&#8221; para los Pa\u00edses Bajos: &#8220;As\u00ed que aqu\u00ed en Europa no hay carteras que importen menos en el orden&#8221;.  El Primer Ministro dijo que hab\u00eda notado que &#8220;los Pa\u00edses Bajos importan&#8221; como &#8220;la quinta econom\u00eda m\u00e1s grande&#8221; y &#8220;uno de los padres fundadores de la Uni\u00f3n Europea&#8221;.  <\/p>\n<p>Despu\u00e9s de su visita a Bruselas, Schoof abordar\u00e1 esta noche un avi\u00f3n con destino a Washington para la cumbre de la OTAN que comienza el martes.  All\u00ed se reunir\u00e1, entre otros, con el presidente estadounidense Joe Biden y el presidente ucraniano Volodymyr Zelensky. <\/p>\n<p><dmt-util-bar article=\"4859060\" headline=\"Premier Schoof krijgt bij zijn eerste internationale optreden een \u2018vriendelijk knikje\u2019 in Brussel\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/08\/premier-schoof-krijgt-bij-zijn-eerste-internationale-optreden-een-vriendelijk-knikje-in-brussel-a4859060\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Para compartir<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Env\u00ede un correo electr\u00f3nico al editor<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/p>\n<aside data-article-id=\"4859060\" data-js-topic-preview=\"\" data-topic-id=\"32\" data-topic-name=\"Europese Unie\"\/>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/07\/08\/premier-schoof-krijgt-bij-zijn-eerste-internationale-optreden-een-vriendelijk-knikje-in-brussel-a4859060\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lleg\u00f3 con una &#8220;actitud constructiva&#8221;, pero al mismo tiempo quer\u00eda &#8220;luchar por los intereses holandeses&#8221;. Con estas palabras<\/p>\n","protected":false},"author":1,"featured_media":1268260,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1314,1873,226983,3207,885,1715,1108,2075,366,3064,237184],"class_list":["post-1268259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-amistoso","tag-aparicion","tag-asentimiento","tag-bruselas","tag-durante","tag-internacional","tag-ministro","tag-primer","tag-primera","tag-recibe","tag-schoof"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268259"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268260"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}