{"id":1268245,"date":"2024-07-08T15:35:08","date_gmt":"2024-07-08T15:35:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/por-eso-francia-esta-en-semifinales\/"},"modified":"2024-07-08T15:35:13","modified_gmt":"2024-07-08T15:35:13","slug":"por-eso-francia-esta-en-semifinales","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/por-eso-francia-esta-en-semifinales\/","title":{"rendered":"Por eso Francia est\u00e1 en semifinales"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>La selecci\u00f3n francesa es taca\u00f1a en goles en el Campeonato de Europa de f\u00fatbol de 2024.  Despu\u00e9s de sus cinco primeros partidos, el Equipe Tricolore ha marcado tres goles: uno de penalti y dos en propia meta.  Sin embargo, los cofavoritos est\u00e1n en semifinales y podr\u00edan ganar el Campeonato de Europa con un historial halagador.<\/p>\n<p>&#8220;Queremos ganar, de eso se trata. No importa si marcas tres goles o 15&#8221;, afirm\u00f3 Aur\u00e9lien Tchouameni en respuesta a las cr\u00edticas sobre el estilo de juego del equipo franc\u00e9s.  El \u00e9xito le da la raz\u00f3n al centrocampista del Real Madrid de 24 a\u00f1os: gan\u00f3 la Liga de Campeones apenas dos semanas antes de la Eurocopa.  Tambi\u00e9n muchas veces sin brillo ni gloria.  Orientado al \u00e9xito es probablemente la mejor manera de describir a Tchouameni y sus compa\u00f1eros en la final del Campeonato de Europa. <\/p>\n<p>Mientras los medios y los expertos destrozan el gallo galo, el exitoso entrenador Didier Deschamps mantiene la calma.  E incluso est\u00e1 satisfecho con el rendimiento.  &#8220;Estoy muy orgulloso de lo que hicimos&#8221;, dijo tras la deslucida victoria por 1-0 sobre B\u00e9lgica en los octavos de final de la Eurocopa e incluso habl\u00f3 de un gran partido.<\/p>\n<h2>S\u00f3lo un gol encajado de penalti<\/h2>\n<p>De hecho, otras naciones tendr\u00edan dificultades para ser tan compactas a la defensiva.  Les Bleus encajaron un solo gol en 480 minutos de torneo.  Y esto se debi\u00f3 a un penalti de Robert Lewandowski en el empate 1-1 ante Polonia en la fase de grupos.  As\u00ed que no encajar un gol fuera del partido es un arte defensivo especial.<\/p>\n<p>Fiel al lema &#8220;La defensa gana campeonatos&#8221;, la defensa francesa en torno a Dayot Upemacano del Bayern ha construido un baluarte que apenas permite que pase nada.  44 tiros del oponente son la menor cantidad de todos los cuartofinalistas.  Y si un bal\u00f3n llegaba hacia la porter\u00eda de Mike Maignan, all\u00ed estaba: el portero del AC Milan desactiv\u00f3 casi el 94 por ciento de los tiros contrarios.  Seg\u00fan el modelo de goles esperados, Francia deber\u00eda haber encajado casi cinco goles durante el torneo.  Tambi\u00e9n intervinieron un poco de suerte y las habilidades de Maignan.<\/p>\n<h2>86 finales franceses sin gol<\/h2>\n<p>Defensivamente, el equipo de Didier Deschamps se mostr\u00f3 m\u00e1s compacto que nunca.  Pero de cara al futuro, el estilo de juego de Francia es extremadamente conservador.  Les Bleus no tienen mucha posesi\u00f3n del bal\u00f3n (poco menos del 52 por ciento) ni ponen especial \u00e9nfasis en la presi\u00f3n intensa.  Especialmente en el campo contrario: s\u00f3lo 15 balones ganados en el tercio ofensivo del campo es el menor n\u00famero de todos los equipos que alcanzaron los cuartos de final.<\/p>\n<div class=\"hs-news-image-container hs-news-image-container--orientation-center hs-news-image-container--width-max\"><a rel=\"nofollow noopener\" class=\"hs-news-image-link\" href=\"https:\/\/onelink.to\/w2n8d2\" target=\"_self\"><\/a><\/div>\n<p>Un gran misterio, sin embargo, es lo que el equipo ofensivo de Francia, formado por las superestrellas Kylian Mbapp\u00e9, perjudicado desde el primer partido de la fase de grupos por una fractura en la nariz, o Antoine Griezmann, aprovecha sus oportunidades.  Francia lleg\u00f3 a semifinales con s\u00f3lo tres goles: dos veces se benefici\u00f3 de un gol en propia puerta y una vez Mbapp\u00e9 marc\u00f3 de penalti.  As\u00ed, ning\u00fan gol marcado por un franc\u00e9s qued\u00f3 fuera del partido.  Cuesta creerlo dada la calidad de la plantilla.<\/p>\n<p>El proveedor de datos Opta registr\u00f3 86 tiros propios (excluidos los penaltis), de los cuales Francia no anot\u00f3 ni uno solo: \u00a1un r\u00e9cord negativo desde que se registraron estos datos! <\/p>\n<h2>Se avecina un halagador r\u00e9cord en la Eurocopa<\/h2>\n<p>La tasa de utilizaci\u00f3n de oportunidades de s\u00f3lo el 4,8 por ciento es la m\u00e1s d\u00e9bil de todos los participantes de los mercados emergentes.  Los goles esperados tambi\u00e9n demuestran que Francia no se comporta como un campe\u00f3n de Europa delante de la porter\u00eda: seg\u00fan estas estad\u00edsticas, los campeones de Europa de 2000 podr\u00edan haber marcado cinco goles m\u00e1s, la mayor discrepancia en el campo.  Esto tambi\u00e9n es emblem\u00e1tico de Mbapp\u00e9, a quien s\u00f3lo se le permiti\u00f3 celebrar una vez de cada 20 tiros, y eso desde el punto de penalti.<\/p>\n<p>Tampoco se espera una explosi\u00f3n de rendimiento con un f\u00fatbol espectacular en la semifinal contra Espa\u00f1a.  Al fin y al cabo, el minimalismo franc\u00e9s tiene mucho \u00e9xito y podr\u00eda figurar en los libros de r\u00e9cords.  Los campeones de Europa con menos goles marcados hasta la fecha son Alemania (1980) y Dinamarca (1992), que se alzaron con el t\u00edtulo con seis goles cada uno.  Francia, semifinalista, est\u00e1 en sus tres&#8230;     <\/p>\n<p>Lars Wiedemann<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6834974\/fussball-em-2024-deshalb-steht-frankreich-trotz-minimalismus-im-halbfinale\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n francesa es taca\u00f1a en goles en el Campeonato de Europa de f\u00fatbol de 2024. Despu\u00e9s de<\/p>\n","protected":false},"author":1,"featured_media":1268246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[203901,20364,1075,97,1714,6365,28760,231,4495],"class_list":["post-1268245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-deportes-en-general","tag-em","tag-eso","tag-esta","tag-francia","tag-futbol-americano","tag-futbol-superior","tag-por","tag-semifinales"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268245"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268246"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}