{"id":1268064,"date":"2024-07-08T12:36:12","date_gmt":"2024-07-08T12:36:12","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-derrota-de-le-pen-deja-a-meloni-solo-pero-mas-libre-para-acercarse-al-ppe\/"},"modified":"2024-07-08T12:36:16","modified_gmt":"2024-07-08T12:36:16","slug":"la-derrota-de-le-pen-deja-a-meloni-solo-pero-mas-libre-para-acercarse-al-ppe","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-derrota-de-le-pen-deja-a-meloni-solo-pero-mas-libre-para-acercarse-al-ppe\/","title":{"rendered":"La derrota de Le Pen deja a Meloni solo pero m\u00e1s libre para acercarse al PPE"},"content":{"rendered":"\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>Escuche la versi\u00f3n en audio del art\u00edculo.<\/button><\/p>\n<p class=\"atext\">Giorgia Meloni m\u00e1s aislada en Bruselas, quiz\u00e1s, pero con una soledad que puede brillar.  Porque no hay duda de que la derrota de la Asamblea Nacional de Marine Le Pen en la segunda vuelta de las elecciones legislativas francesas debilita a la derecha soberanista y sustancialmente pro-Putin, pero si hay alguien que se dispon\u00eda a brindar por la victoria de su aliado franc\u00e9s en El domingo por la noche se sinti\u00f3 decepcionado porque alguien no era Meloni, que hizo de la elecci\u00f3n atlantista y proucraniana la piedra angular de su pol\u00edtica exterior, sino el viceprimer ministro y l\u00edder de la Liga, Matteo Salvini.  Quien, en l\u00ednea con el giro ultraderechista que quiso dar a la Liga, se trasladar\u00e1 en los pr\u00f3ximos d\u00edas junto a Le Pen a la naciente <a rel=\"nofollow noopener\" target=\"\" href=\"https:\/\/24plus.ilsole24ore.com\/art\/la-destra-patrioti-l-europa-potrebbe-diventare-terzo-gruppo-parlamento-ue-chi-sono-cosa-puntano-AFbjRjdC?s=hpl\">Grupo \u201cPatriotas\u201d<\/a> del primer ministro h\u00fangaro, Victor Orban.  Quien, con igual coherencia, bautiz\u00f3 el inicio de su presidencia rotatoria de la UE con una visita (aunque a t\u00edtulo personal) al presidente ruso.<\/p>\n<p><h2 id=\"U502269597642hBB\">La salida de Vox de Ecr puede devolver la libertad a las primas<b>ejem<\/b>lejos de Orb\u00e1n<\/h2>\n<\/p>\n<p class=\"atext\">Meloni est\u00e1 m\u00e1s solo, por lo tanto, dado que los antiguos aliados del partido xen\u00f3fobo espa\u00f1ol de ultraderecha Vox han abandonado a su vez el grupo Conservadores y Reformistas (Ecr) liderado por Meloni para unirse a la Liga y la Asamblea Nacional en la nueva creaci\u00f3n orbaniana.  Una &#8220;limpieza&#8221; que s\u00f3lo puede beneficiar a la primera ministra italiana, ahora m\u00e1s libre en sus estrategias europeas, alej\u00e1ndola a ella y a su partido Fratelli d&#8217;Italia de la derecha radical y antisistema y m\u00e1s cerca del Partido Popular Europeo y, por tanto, de la mayor\u00eda. que se dispone a votar por un bis de la popular alemana Ursula von der Leyen al frente de la Comisi\u00f3n de la UE.  Bis sobre el cual Meloni se abstuvo como primer ministro hace poco menos de dos semanas en el Consejo de la UE como protesta por haber sido excluido de la definici\u00f3n de la nueva gobernanza.  Una abstenci\u00f3n que en el caso de la candidatura del socialista Antonio Costa a la presidencia del Consejo de la UE desemboc\u00f3 incluso en un voto en contra, y es la primera vez en la historia de Italia.<\/p>\n<p><h2 id=\"U502269597642mYE\">Las sirenas soberanistas de Salvini&#8230; y el inter\u00e9s de Italia<\/h2>\n<\/p>\n<p class=\"atext\">Ahora las negociaciones en Europa, tras el stand by de las elecciones legislativas francesas, cobrar\u00e1n vida en los pr\u00f3ximos d\u00edas hasta la votaci\u00f3n en el Parlamento de la UE el 18 de junio.  En este caso, ser\u00e1 la oportunidad de comprender si la derrota de la derecha soberanista en Francia contribuir\u00e1 a cambiar la actitud del Gobierno italiano y a transformar esa abstenci\u00f3n en un voto a favor, considerando tambi\u00e9n que &#8211; dado que el Parlamento Europeo necesita mayor\u00eda absoluta de los miembros de la C\u00e1mara; la abstenci\u00f3n equivaldr\u00eda de hecho a un voto en contra.  Por supuesto, en el o\u00eddo derecho del primer ministro suenan las sirenas soberanistas de Salvini.  Quien, anunciando el paso a los Patriots de Orban justo despu\u00e9s del cierre de las elecciones francesas, anticip\u00f3 &#8220;un claro no a cualquier hip\u00f3tesis de Ursula bis y a cualquier alianza con los socialistas y ecofan\u00e1ticos de todos los impuestos y desembarques&#8221;.  Pero la realpolitik deber\u00eda, por otra parte, empujar a Meloni a valorar el hecho de que &#8220;la \u00fanica derecha que logra ganar en un gran Estado europeo y liderar un gobierno que es el m\u00e1s s\u00f3lido y estable de Europa es el de los Hermanos de Italia con Meloni, l\u00edder de la coalici\u00f3n de centro-derecha&#8221;, como se apresura a decir el l\u00edder del grupo en la C\u00e1mara, Tommaso Foti.<\/p>\n<p><h2 id=\"U502269597642TkB\">A la espera de las aperturas de \u00darsula sobre el Pacto Verde y la inmigraci\u00f3n<\/h2>\n<\/p>\n<p class=\"atext\">El mismo ministro de los Fratelli d&#8217;Italia, Raffaele Fitto, en la primera posici\u00f3n para ocupar un puesto de peso como comisario, advierte que &#8220;todav\u00eda no hay una orientaci\u00f3n&#8221;, pero que es necesario &#8220;comprender la evoluci\u00f3n&#8221; y &#8220;escuchar lo que se dir\u00e1 en las conversaciones que tendr\u00e1n previamente con la presidenta Von del Leyen y sobre el fondo de su discurso program\u00e1tico&#8221;.  Traducido, el gobierno italiano espera apertura sobre el calendario del Pacto Verde y sobre la inmigraci\u00f3n.  En resumen, una prueba de madurez para Meloni, que ahora tiene la oportunidad de reforzar su posici\u00f3n media entre la derecha m\u00e1s soberanista y el PPE haciendo que el voto de los parlamentarios de la ECR pese a la hora de discutir expedientes para los que ya se esperan mayor\u00edas variables.  Una prueba interesante ser\u00e1 la misi\u00f3n de la Primera Ministra a Washington en las pr\u00f3ximas horas, donde, con motivo de la cumbre de la OTAN, se reunir\u00e1 de nuevo con numerosos l\u00edderes europeos, empezando por el Presidente franc\u00e9s Emmanuel Macron, revitalizado por el resultado de las encuestas y (probablemente ) la propia von der Leyen.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/la-sconfitta-le-pen-lascia-meloni-piu-sola-ma-piu-libera-avvicinarsi-ppe-AFkBAldC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escuche la versi\u00f3n en audio del art\u00edculo. Giorgia Meloni m\u00e1s aislada en Bruselas, quiz\u00e1s, pero con una soledad<\/p>\n","protected":false},"author":1,"featured_media":1268065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[23743,25,1716,10363,16,52237,18,19591,267,57705,2525],"class_list":["post-1268064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-acercarse","tag-deja","tag-derrota","tag-libre","tag-mas","tag-meloni","tag-para","tag-pen","tag-pero","tag-ppe","tag-solo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1268064"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1268064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1268065"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1268064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1268064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1268064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}