{"id":1261834,"date":"2024-07-03T10:41:36","date_gmt":"2024-07-03T10:41:36","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-increible-doble-vida-de-lhakpa-sherpa-rompedora-de-records-en-el-everest-y-limpiadora-de-casas-en-connecticut\/"},"modified":"2024-07-03T10:41:36","modified_gmt":"2024-07-03T10:41:36","slug":"la-increible-doble-vida-de-lhakpa-sherpa-rompedora-de-records-en-el-everest-y-limpiadora-de-casas-en-connecticut","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-increible-doble-vida-de-lhakpa-sherpa-rompedora-de-records-en-el-everest-y-limpiadora-de-casas-en-connecticut\/","title":{"rendered":"La incre\u00edble doble vida de Lhakpa Sherpa: rompedora de r\u00e9cords en el Everest y limpiadora de casas en Connecticut"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"article-body\">\n<p>Son casi las 9 de la ma\u00f1ana y las condiciones favorecen el ascenso a la cumbre. Despu\u00e9s de d\u00edas en los que una curva en la corriente en chorro ha tra\u00eddo aire fr\u00edo del \u00c1rtico, una suave brisa del sur sopla sobre el campamento base avanzado, tambi\u00e9n conocido como la estaci\u00f3n Gospel Oak en el norte de Londres. <\/p>\n<p>Es aqu\u00ed, no muy lejos del centro de la ciudad, donde me encontrar\u00e9 con uno de los alpinistas m\u00e1s destacados del mundo para ascender al techo del, digamos, centro de Londres, donde el punto m\u00e1s alto roza el cielo a 134 metros sobre el nivel del mar.<\/p>\n<p>Lhakpa Sherpa, que ha escalado el Everest diez veces, un r\u00e9cord para una mujer, llega con una taza de caf\u00e9 en la mano. Le muestro la ruta en mi tel\u00e9fono: un ascenso de 3,1 km a trav\u00e9s de los pastizales y bosques de Hampstead Heath hasta Whitestone Pond.<\/p>\n<p>\u201c\u00a1Quiz\u00e1s necesite ox\u00edgeno!\u201d, dice Lhakpa riendo mientras nos ponemos en marcha, ajustando el ritmo a medida que empezamos a escalar la cara sur de Parliament Hill. La apariencia de aventura, ya en peligro, finalmente se evapora cuando noto que el fot\u00f3grafo del FT lleva chanclas.<\/p>\n<div class=\"n-content-layout\" data-layout-name=\"auto\" data-layout-width=\"full-grid\">\n<div class=\"n-content-layout__container\">\n<div class=\"n-content-layout__slot\">\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"1393\" height=\"2090\"\/><img decoding=\"async\" src=\"https:\/\/www.ft.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e00ek4ebabms.cloudfront.net%2Fproduction%2F981e094e-4a5a-4749-9014-2be40b49f5f3.jpg?source=next-article&amp;fit=scale-down&amp;quality=highest&amp;width=700&amp;dpr=1\" alt=\"Una mujer mira el horizonte de Londres desde una colina.\" data-image-type=\"image\" width=\"1393\" height=\"2090\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Lhakpa en Hampstead Heath el mes pasado, de camino al techo del centro de Londres, a 134 metros sobre el nivel del mar. <\/span><span> <!-- -->\u00a9 Sandra Mickiewicz<\/span><\/figcaption><\/figure>\n<\/div>\n<div class=\"n-content-layout__slot\">\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"938\" height=\"1407\"\/><img decoding=\"async\" src=\"https:\/\/www.ft.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e00ek4ebabms.cloudfront.net%2Fproduction%2Feefe9926-d07b-469f-8545-4bbc61a44e5f.jpg?source=next-article&amp;fit=scale-down&amp;quality=highest&amp;width=700&amp;dpr=1\" alt=\"Una vista de los \u00e1rboles y las torres de una ciudad. \" data-image-type=\"image\" width=\"938\" height=\"1407\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Una pausa para contemplar el horizonte desde Parliament Hill <\/span><span> <!-- -->\u00a9 Sandra Mickiewicz<\/span><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>En circunstancias normales, nos habr\u00edamos reunido en una habitaci\u00f3n de hotel an\u00f3nima para hablar sobre el documental de gran presupuesto sobre Lhakpa, que tiene 50 a\u00f1os y que llegar\u00e1 a los cines y a Netflix a finales de este mes. Pero en Mountain Queen: The Summits Of Lhakpa Sherpa queda claro que quedarse quieta no es lo suyo.<\/p>\n<p>La pel\u00edcula, de la directora brit\u00e1nica nominada al Oscar Lucy Walker, es un relato inspirador del d\u00e9cimo asalto de Lhakpa al Everest en 2022. Pero es mucho m\u00e1s. Filmada a lo largo de varios a\u00f1os dentro y fuera de la monta\u00f1a, sigue su intento mucho m\u00e1s duro de recuperar su identidad y curar a su familia despu\u00e9s de una serie de reveses extraordinarios.<\/p>\n<p>Hablando en un ingl\u00e9s deficiente y lleno de energ\u00eda, Lhakpa, que vive en Estados Unidos desde hace m\u00e1s de 20 a\u00f1os, relata por primera vez el horrible abuso que sufri\u00f3 a manos de su marido, Gheorghe Dijm\u0103rescu, un conocido escalador y gu\u00eda rumano-estadounidense.<\/p>\n<div class=\"n-content-layout\" data-layout-width=\"full-grid\">\n<figure class=\"n-content-picture n-content-picture--wide n-content-layout__container\" data-component=\"image-set\"><picture><source media=\"(max-width: 490px)\"  width=\"1402\" height=\"1402\"\/><source media=\"(min-width: 980px)\"  width=\"2103\" height=\"1402\"\/><img decoding=\"async\" src=\"https:\/\/www.ft.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e00ek4ebabms.cloudfront.net%2Fproduction%2F066ce4c1-47ec-41ef-b0ee-1147096308ff.jpg?source=next-article&amp;fit=scale-down&amp;quality=highest&amp;width=700&amp;dpr=1\" alt=\"Una mujer con vestido y sombrero del Himalaya sonr\u00ede a la c\u00e1mara.\" data-image-type=\"image\" width=\"2103\" height=\"1402\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Lhakpa Sherpa habla en Nepal en &#8216;Mountain Queen&#8217;, el nuevo documental de Netflix sobre su vida<\/span><span> <!-- -->\u00a9 Cortes\u00eda de Netflix<\/span><\/figcaption><\/figure>\n<\/div>\n<p>En un momento en el que el monta\u00f1ismo se enfrenta a un debate m\u00e1s amplio sobre las din\u00e1micas de poder de g\u00e9nero y las acusaciones de acoso y agresi\u00f3n sexual, Lhakpa tambi\u00e9n se pregunta qu\u00e9 tiene que hacer una escaladora como ella para conseguir un patrocinador. Es sorprendente saber que, para viajar al Reino Unido a promocionar una pel\u00edcula sobre sus haza\u00f1as r\u00e9cord en una monta\u00f1a que cada vez est\u00e1 m\u00e1s inundada de dinero, Lhakpa tiene que tomarse un tiempo libre de su trabajo como limpiadora de casas.<\/p>\n<p>\u201cA veces, cuando pido patrocinadores, [for support] \u201cNo creen en m\u00ed\u201d, dice Lhakpa, que hasta hace poco trabajaba en Whole Foods, un supermercado cerca del apartamento que comparte con sus hijas, Sunny, de 22 a\u00f1os, y Shiny, de 17, en West Hartford, Connecticut. \u201cDicen, \u2018ah, est\u00e1 divorciada\u2019, o \u2018es madre\u2019, o \u2018lava platos en Whole Foods\u2019, \u00a1y eso me enfada much\u00edsimo! Soy fuerte, conozco muy bien esta monta\u00f1a, \u00bfpor qu\u00e9 yo no?\u201d.<\/p>\n<hr\/>\n<p><strong>Lhakpa Sherpa naci\u00f3 en 1973<\/strong> Una familia de pastores de un peque\u00f1o pueblo del Himalaya se vio abrumada por la fascinaci\u00f3n que le produc\u00edan desde el principio los imponentes picos que se ve\u00edan desde su casa. Tem\u00eda que su hija, una de once hermanos, fuera atacada por un leopardo de las nieves. Los lugare\u00f1os tambi\u00e9n ten\u00edan miedo de los \u201cyetis\u201d, el nombre que daban a los extranjeros altos y de piel p\u00e1lida que hab\u00edan empezado a llegar a la regi\u00f3n para hacer excursiones de senderismo.<\/p>\n<p>Lhakpa tuvo que superar obst\u00e1culos m\u00e1s grandes que la desaprobaci\u00f3n materna. En aquella \u00e9poca, las ni\u00f1as no iban a la escuela (Lhakpa llevaba a sus hermanos menores a clase para ahorrarles el largo camino). Ante una vida de trabajo dom\u00e9stico, se rebel\u00f3 y sigui\u00f3 mirando hacia arriba. Le ayud\u00f3 el hecho de que era inmensamente fuerte, lo que era motivo de orgullo para su padre. \u201cLos hombres nepal\u00edes dicen que las mujeres deben quedarse en casa, pero \u00e9l le dijo a mi madre: \u2018\u00a1D\u00e9jala ir, es fuerte!\u2019\u201d, recuerda. \u201c\u2018\u00a1T\u00fa eres mi hijo fuerte!\u2019, me dijo\u201d.<\/p>\n<div class=\"n-content-layout\" data-layout-name=\"auto\" data-layout-width=\"full-grid\">\n<div class=\"n-content-layout__container\">\n<div class=\"n-content-layout__slot\">\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"1439\" height=\"2159\"\/><img decoding=\"async\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/La-increible-doble-vida-de-Lhakpa-Sherpa-rompedora-de-records.jpg\" alt=\"Una mujer camina por una pasarela de madera sobre un arroyo en un terreno monta\u00f1oso. \" data-image-type=\"image\" width=\"1439\" height=\"2159\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Trekking de Lhakpa al campamento base del Everest en Nepal.<\/span><span> <!-- -->\u00a9 Matthew Irving\/Netflix<\/span><\/figcaption><\/figure>\n<\/div>\n<div class=\"n-content-layout__slot\">\n<figure class=\"n-content-image n-content-image--full\" data-component=\"image-set\"><picture><source media=\"(min-width: 700px)\"  width=\"934\" height=\"1402\"\/><img decoding=\"async\" src=\"https:\/\/www.ft.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e00ek4ebabms.cloudfront.net%2Fproduction%2Fa0e86117-c85c-4a52-bfdc-da81da597b27.jpg?source=next-article&amp;fit=scale-down&amp;quality=highest&amp;width=700&amp;dpr=1\" alt=\"Dos monta\u00f1eros con pesadas capas de ropa invernal suben una empinada subida helada con cuerdas\" data-image-type=\"image\" width=\"934\" height=\"1402\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>&#8230; y en camino a la cumbre en 2022 <\/span><span> <!-- -->\u00a9 Netflix<\/span><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Con el pelo corto, Lhakpa encontr\u00f3 trabajo como porteadora y \u201cchica de cocina\u201d en expediciones de trekking. En 1993, deposit\u00f3 una flor durante el funeral de Pasang Lhamu Sherpa, que muri\u00f3 en el descenso despu\u00e9s de convertirse en la primera mujer nepal\u00ed en alcanzar la cima del Everest. Lhakpa dice que sinti\u00f3 que la energ\u00eda de su compa\u00f1era sherpa le pasaba a ella.<\/p>\n<p>En 2000, Lhakpa ya se ganaba la vida en Katmand\u00fa entre expediciones y tuvo un hijo, Nima, tras una breve relaci\u00f3n. Despu\u00e9s de escribir una carta al gobierno, acab\u00f3 liderando un equipo de mujeres nepalesas en la ascensi\u00f3n al Everest y se convirti\u00f3 en la \u00fanica en llegar a la cima. \u201cMe sent\u00ed muy poderosa\u201d, me cuenta. \u201cNo ten\u00eda preocupaciones, me sent\u00eda como si todav\u00eda fuera una adolescente\u201d.<\/p>\n<p>Poco despu\u00e9s, Lhakpa conoci\u00f3 a Dijm\u0103rescu en un bar de Katmand\u00fa. Alto, apuesto y carism\u00e1tico, acababa de alcanzar la cima del Everest por segunda vez. La pareja se enamor\u00f3 y llegaron juntos a la cumbre en 2001. Lhakpa y Nima se mudaron a Connecticut con Dijm\u0103rescu, que ten\u00eda una empresa de techado (Lhakpa recuerda haber hecho la mayor parte del trabajo pesado). Volv\u00edan al Everest con clientes cada primavera.<\/p>\n<p>Despu\u00e9s de que Sunny llegara en 2002, Lhakpa dice que Dijm\u0103rescu se volvi\u00f3 agresivo y dominante. Durante una discusi\u00f3n en el Everest en 2004, le dio un pu\u00f1etazo en la cabeza a Lhakpa frente a unos clientes y sac\u00f3 su cuerpo inerte de la tienda, describi\u00e9ndola como &#8220;basura&#8221;. Lhakpa tem\u00eda que muriera y dice que solo pensar en Sunny la mantuvo en pie.<\/p>\n<p>Durante a\u00f1os estuvo atrapada en una relaci\u00f3n abusiva con un hombre controlador que aplast\u00f3 su confianza y amenaz\u00f3 la vida que hab\u00eda construido. \u201c\u00c9l es mi monstruo, es mi yeti\u201d, dice en la pel\u00edcula.<\/p>\n<p>Poco despu\u00e9s de detenernos en un mirador para contemplar el horizonte de Londres, le pregunto a Lhakpa si ha seguido las noticias recientes sobre otro alpinista nepal\u00ed. Un par de semanas antes de nuestra caminata, el New York Times public\u00f3 un art\u00edculo sobre los peligros que enfrentan las mujeres en las grandes monta\u00f1as. Dos mujeres afirmaron que Nirmal \u201cNims\u201d Purja, el alpinista brit\u00e1nico-nepal\u00ed elogiado cuyas haza\u00f1as en picos de 8.000 metros le han valido fama y fortuna, las acos\u00f3 sexualmente, una de ellas mientras estaba en una expedici\u00f3n al K2 como cliente de Elite Exped, la compa\u00f1\u00eda de gu\u00edas de Purja.<\/p>\n<div class=\"n-content-layout\" data-layout-width=\"full-grid\">\n<figure class=\"n-content-picture n-content-picture--wide n-content-layout__container\" data-component=\"image-set\"><picture><source media=\"(max-width: 490px)\"  width=\"1402\" height=\"1402\"\/><source media=\"(min-width: 980px)\"  width=\"2103\" height=\"1402\"\/><img decoding=\"async\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2024\/07\/1720003296_780_La-increible-doble-vida-de-Lhakpa-Sherpa-rompedora-de-records.jpg\" alt=\"Una mujer con gorra se encuentra en la esquina de una calle en los suburbios de los Estados Unidos. \" data-image-type=\"image\" width=\"2103\" height=\"1402\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>Lhakpa en West Hartford, Connecticut, donde vive en un apartamento con sus hijas, Sunny, de 22 a\u00f1os, y Shiny, de 17. <\/span><span> <!-- -->\u00a9 Netflix<\/span><\/figcaption><\/figure>\n<\/div>\n<p>A trav\u00e9s de su abogado, que no respondi\u00f3 a mis correos electr\u00f3nicos, Purja le dijo al New York Times que \u201cniega rotundamente las acusaciones de irregularidades. Estas acusaciones son falsas y difamatorias\u201d. Mi propio correo electr\u00f3nico a Elite Exped tampoco recibi\u00f3 respuesta, pero un portavoz de Nimsdai, la propia empresa de Purja, repite la negaci\u00f3n y dice que Purja est\u00e1 \u201cevaluando actualmente sus opciones legales\u201d. <\/p>\n<p>Lhakpa me dice que no ha seguido las noticias y que queda claro que quiere centrarse en su propia historia. Pero me parece que una pel\u00edcula sobre una mujer frenada por la desigualdad extrema (en su educaci\u00f3n, en su matrimonio, en las monta\u00f1as y en la inseguridad econ\u00f3mica con la que todav\u00eda lidia) resulta oportuna. &#8220;Me sorprende que esta conversaci\u00f3n no haya sucedido antes&#8221;, dice Lucy Walker sobre el debate m\u00e1s amplio que ha suscitado la historia de Purja.<\/p>\n<hr\/>\n<p><strong>La propia lucha de Lhakpa estaba lejos de terminar.<\/strong> Incapaz de dejar a Dijm\u0103rescu, quien m\u00e1s tarde amenaz\u00f3 con matar a la familia si lo intentaba, sigui\u00f3 escalando con \u00e9l y en 2006 alcanz\u00f3 su sexta cumbre del Everest, estando embarazada de Sunny. Ser\u00eda la \u00faltima en una d\u00e9cada; a medida que el comportamiento de Dijm\u0103rescu empeoraba y las finanzas de la familia se resintieron, Lhakpa se vio obligada a convertirse en la ama de casa sumisa que nunca hab\u00eda querido ser.<\/p>\n<p>\u201cCuando la vida no es f\u00e1cil para m\u00ed, pienso en mi monta\u00f1a, la monta\u00f1a es mi amiga de la infancia\u201d, dice en la pel\u00edcula sobre esta triste pausa. \u201cCuando estoy con Gheorghe estoy sola, nadie me ve, me trata como si no fuera nadie\u201d.<\/p>\n<blockquote class=\"n-content-pullquote n-content-pullquote--no-image\" aria-hidden=\"true\">\n<div class=\"n-content-pullquote__content\">\n<p>Su d\u00e9cima cumbre le vali\u00f3 elogios, pero siempre iba a tener que volver a limpiar casas elegantes, cuyos due\u00f1os no ten\u00edan idea de qui\u00e9n era ella.<\/p>\n<\/div>\n<\/blockquote>\n<p>En 2012, tras un devastador ataque del que fueron testigos Sunny y Shiny, Lhakpa huy\u00f3 con ellas a un refugio para mujeres y, finalmente, escap\u00f3 de su matrimonio, consiguiendo m\u00e1s tarde la custodia exclusiva de sus hijas. Dijm\u0103rescu, que recibi\u00f3 una sentencia de prisi\u00f3n en suspenso, le rog\u00f3 que regresara. En cambio, ella plane\u00f3 regresar al Everest. <\/p>\n<p>El hermano menor de Lhakpa, Mingma Gelu Sherpa, que hab\u00eda empezado a trabajar en la monta\u00f1a al mismo tiempo que ella, hab\u00eda conseguido crear una empresa de gu\u00edas y en 2016 Lhakpa se uni\u00f3 a una expedici\u00f3n con \u00e9l. Tom\u00e1ndose un descanso de su trabajo en un 7-Eleven, consigui\u00f3 llegar a la cima por s\u00e9ptima vez y comenz\u00f3 su rehabilitaci\u00f3n. \u201cEl Everest es mi m\u00e9dico, me cur\u00f3 el alma\u201d, dijo.<\/p>\n<p>Poco despu\u00e9s, Walker se puso en contacto con Lhakpa. Decidida a darle la pel\u00edcula de monta\u00f1ismo que se merec\u00eda, contrat\u00f3 a un director de fotograf\u00eda de gran altitud para capturar la hist\u00f3rica d\u00e9cima cumbre en 2022. Pero, sin duda, las escenas en Connecticut y en el campamento base del Everest son las m\u00e1s cautivadoras.<\/p>\n<p>Observamos c\u00f3mo una madre inmigrante y sus hijas estadounidenses intentan superar una grieta que las separa de la comprensi\u00f3n mientras enfrentan sus vidas tan diferentes y sus traumas comunes. Es un proceso que, sin embargo, resulta muy gratificante y que, sin embargo, a Lhakpa le ha resultado muy dif\u00edcil. \u201cMi cultura es ocultar este tipo de problemas\u201d, me dice cuando nos acercamos al final de nuestra caminata. \u201cPero ahora no tengo otra opci\u00f3n, ya no puedo ocultarme m\u00e1s\u201d.<\/p>\n<div class=\"n-content-layout\" data-layout-width=\"full-grid\">\n<figure class=\"n-content-picture n-content-picture--wide n-content-layout__container\" data-component=\"image-set\"><picture><source media=\"(max-width: 490px)\"  width=\"1402\" height=\"1402\"\/><source media=\"(min-width: 980px)\"  width=\"2103\" height=\"1402\"\/><img decoding=\"async\" src=\"https:\/\/www.ft.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e00ek4ebabms.cloudfront.net%2Fproduction%2Fabf36310-8a33-4149-b6dd-36a6ef4fd83a.jpg?source=next-article&amp;fit=scale-down&amp;quality=highest&amp;width=700&amp;dpr=1\" alt=\"Una mujer con ropa de monta\u00f1a resistente se encuentra en la cima de una monta\u00f1a con nubes muy abajo, sosteniendo una foto de dos ni\u00f1as. \" data-image-type=\"image\" width=\"2103\" height=\"1402\" loading=\"lazy\"\/><\/picture><figcaption class=\"n-content-picture__caption\"><span>En la cima del Everest, sosteniendo las fotos de sus dos hijas  <\/span><span> <!-- -->\u00a9 Netflix<\/span><\/figcaption><\/figure>\n<\/div>\n<p>Su d\u00e9cima cumbre triunfal tambi\u00e9n fue reveladora. En 2000, Lhakpa hab\u00eda sido una de las 145 personas que hab\u00edan llegado a la cumbre. Esta vez fue una de las casi 700. Se podr\u00eda decir que hoy en d\u00eda el Everest se define en la conciencia popular por las fotos de las colas para el d\u00eda de la cumbre. \u201cOjal\u00e1 hubiera un peque\u00f1o l\u00edmite\u201d, dice Lhakpa. \u201cEl Everest merece respeto\u201d.<\/p>\n<p>Pero ella, m\u00e1s que nadie, reconoce la paradoja que se esconde en el coraz\u00f3n de la industria: las compa\u00f1\u00edas de gu\u00edas dirigidas por sherpas, como la de su hermano, est\u00e1n impulsando el estatus y la prosperidad de personas tradicionalmente explotadas. Los escaladores m\u00e1s ricos emplean ahora a tres o incluso cuatro sherpas personales. \u201cParece m\u00e1s como un trabajo de ni\u00f1era, pero los sherpas tambi\u00e9n necesitan el trabajo\u201d, afirma.<\/p>\n<p>Ahora Lhakpa necesita un trabajo. Su d\u00e9cima cumbre le vali\u00f3 elogios y una peque\u00f1a cantidad de patrocinio para escalar el K2, el segundo pico m\u00e1s alto del mundo, en 2023. Pero siempre iba a tener que volver a limpiar casas elegantes, cuyos due\u00f1os no tienen idea de qui\u00e9n es ella. Espera que el tratamiento de Netflix le traiga nuevas oportunidades.<\/p>\n<p>Quiere escalar con sus hijas el punto m\u00e1s alto de cada uno de los 50 estados de Estados Unidos para que los j\u00f3venes que han tenido vidas dif\u00edciles conozcan la monta\u00f1a. Y quiere mejorar el entrenamiento de los j\u00f3venes sherpas que lo arriesgan todo por los ricos que llegan a la cima. \u201cQuiero cambiar la vida de los j\u00f3venes\u201d, dice Lhakpa, que ahora tiene su propia empresa de gu\u00edas, Cloudscape Climbing. <\/p>\n<p>Tras un peque\u00f1o desv\u00edo por un antiguo bosque de robles, nos dirigimos hacia el sur hasta Whitestone Pond, donde un m\u00e1stil de bandera marca nuestra cumbre. Chocamos los cinco con iron\u00eda. Lhakpa dice que est\u00e1 nerviosa por el estreno de una pel\u00edcula tan personal, pero que, sobre todo, espera que sirva de inspiraci\u00f3n a otras personas. \u201cSoy una se\u00f1ora mayor, pero tengo much\u00edsima energ\u00eda\u201d, dice mientras iniciamos el descenso. \u201cQuiero que la gente vea que me pasan cosas muy malas, pero nunca me doy por vencida\u201d.<\/p>\n<p><em>&#8216;Mountain Queen&#8217; se estrena en un n\u00famero limitado de cines a partir del 26 de julio y est\u00e1 disponible en Netflix a partir del 31 de julio<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/d592212a-4bf9-450d-bc90-0271e9d95a6d\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son casi las 9 de la ma\u00f1ana y las condiciones favorecen el ascenso a la cumbre. Despu\u00e9s de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1242,76913,2604,45751,6851,240523,32645,12944,240524,108734,148],"class_list":["post-1261834","post","type-post","status-publish","format-standard","hentry","category-general","tag-casas","tag-connecticut","tag-doble","tag-everest","tag-increible","tag-lhakpa","tag-limpiadora","tag-records","tag-rompedora","tag-sherpa","tag-vida"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1261834"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261834\/revisions"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1261834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1261834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1261834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}