{"id":1261825,"date":"2024-07-03T10:32:19","date_gmt":"2024-07-03T10:32:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/mbappe-o-ronaldo-quien-sale-volando\/"},"modified":"2024-07-03T10:32:23","modified_gmt":"2024-07-03T10:32:23","slug":"mbappe-o-ronaldo-quien-sale-volando","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/mbappe-o-ronaldo-quien-sale-volando\/","title":{"rendered":"\u00bfMbapp\u00e9 o Ronaldo?  \u00bfQui\u00e9n sale volando?"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Kylian Mbapp\u00e9 est\u00e1 tumbado en la cama de su casa, vestido con unos vaqueros azules y un jersey verde.  El ni\u00f1o apoya la cabeza entre las manos y mira a su alrededor so\u00f1adoramente, con admiraci\u00f3n, casi con amor.  A su alrededor: carteles de Cristiano Ronaldo por todas partes.  Su gran \u00eddolo.<\/p>\n<p>Ronaldo fue una \u201cinspiraci\u00f3n\u201d para \u00e9l, dijo una vez Mbapp\u00e9.  El chico que una vez idolatraba la m\u00e1quina goleadora de Portugal en el problem\u00e1tico suburbio parisino de Bondy hace tiempo que se ha convertido en una superestrella, la esperanza de Francia.  Ahora, m\u00e1s de diez a\u00f1os despu\u00e9s de que se tomaran las fotograf\u00edas en la habitaci\u00f3n de la infancia de Mbapp\u00e9, hay un duelo entre generaciones en el escenario de la Eurocopa.<\/p>\n<p>Cuartos de final, Francia contra Portugal (viernes, 21 h\/ZDF \u200b\u200by MagentaTV), Mbapp\u00e9 contra Ronaldo: para uno de los dos grandes, el sue\u00f1o del t\u00edtulo termina en Hamburgo.<\/p>\n<h2>Ronaldo antes del final, Mbapp\u00e9 como heredero al trono<\/h2>\n<p>Y ahora se ha invertido el reparto de roles entre Mbapp\u00e9 y Ronaldo.  El portugu\u00e9s, de casi 40 a\u00f1os y que ahora trabaja en el Al-Nassr de Arabia Saudita, hace tiempo que se declar\u00f3 fan\u00e1tico de Mbapp\u00e9.  \u201c\u00c9l es el presente y el futuro del f\u00fatbol mundial\u201d, afirm\u00f3 Ronaldo, que fue el primer profesional en participar en seis Eurocopas y ahora encabeza la clasificaci\u00f3n con 29 apariciones y 14 goles: \u201cEs un jugador fant\u00e1stico, muy r\u00e1pido y pertenece a los pr\u00f3ximos a\u00f1os\u201d.<\/p>\n<div class=\"hs-news-image-container hs-news-image-container--orientation-center hs-news-image-container--width-max\"><a rel=\"nofollow noopener\" class=\"hs-news-image-link\" href=\"https:\/\/onelink.to\/w2n8d2\" target=\"_self\"><\/a><\/div>\n<p>Eso s\u00ed, cuando Mbapp\u00e9 tiene el bal\u00f3n, la afici\u00f3n francesa contiene la respiraci\u00f3n.  Siempre puede pasar algo espectacular.  Pero hasta el momento no es la Eurocopa para el atacante, que tras el torneo se marcha al Real Madrid.  Nariz rota, s\u00f3lo un golpe.  Mbapp\u00e9 no ha llevado al equipo como se esperaba hasta ahora, lo m\u00e1s destacado del subcampe\u00f3n del mundo es su fuerte defensa.  &#8220;Estamos haciendo todo lo posible para no encajar ning\u00fan gol&#8221;, afirm\u00f3 el t\u00e9cnico Didier Deschamps.<\/p>\n<p>Para Ronaldo, que ya no siembra tanto miedo y terror en las defensas rivales como antes, esta no es una buena noticia antes de la nueva edici\u00f3n de la final de la Eurocopa 2016.  Pero al igual que su mayor t\u00edtulo, el Campeonato de Europa de hace ocho a\u00f1os, Ronaldo est\u00e1 impulsado por una voluntad absoluta, esta aparentemente interminable avidez por el \u00e9xito.  &#8220;Son uno de los favoritos al t\u00edtulo&#8221;, dijo sobre Francia: &#8220;Pero vamos a la guerra&#8221;.<\/p>\n<p>Podr\u00eda ser la \u00faltima batalla europea de Ronaldo.  &#8220;Es sin duda mi \u00faltima Eurocopa&#8221;, afirm\u00f3 tras alcanzar los cuartos de final. Ronaldo se est\u00e1 volviendo cada vez m\u00e1s aficionado, sobre todo de su &#8220;sucesor&#8221; Mbapp\u00e9.  Despu\u00e9s de su paso a la Realeza, public\u00f3 en las redes sociales fotos de \u00e9l mismo cuando era peque\u00f1o con un traje del Real, y tambi\u00e9n hubo una instant\u00e1nea de \u00e9l con Ronaldo.  &#8220;Ahora es mi turno de verte. Estoy deseando verte iluminar el Bernab\u00e9u&#8221;, escribi\u00f3 Ronaldo en los comentarios.  Pero primero a\u00fan queda el duelo por la Eurocopa.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne6818528\/em-2024---mbappe-gegen-idol-ronaldo-ein-superstar-faehrt-nach-hause\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kylian Mbapp\u00e9 est\u00e1 tumbado en la cama de su casa, vestido con unos vaqueros azules y un jersey<\/p>\n","protected":false},"author":1,"featured_media":1261826,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[484,203901,20364,1714,6365,28760,7260,5153,4118,1232,487,1425,5770],"class_list":["post-1261825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-cristiano-ronaldo","tag-deportes-en-general","tag-em","tag-francia","tag-futbol-americano","tag-futbol-superior","tag-kylian-mbappe","tag-mbappe","tag-portugal","tag-quien","tag-ronaldo","tag-sale","tag-volando"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1261825"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1261826"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1261825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1261825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1261825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}