{"id":1261656,"date":"2024-07-03T07:30:12","date_gmt":"2024-07-03T07:30:12","guid":{"rendered":"https:\/\/teknomers.com\/es\/scudetto-en-la-familia-khephren-y-marcus-la-saga-de-los-hermanos-thuram-en-la-juve-inter\/"},"modified":"2024-07-03T07:30:16","modified_gmt":"2024-07-03T07:30:16","slug":"scudetto-en-la-familia-khephren-y-marcus-la-saga-de-los-hermanos-thuram-en-la-juve-inter","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/scudetto-en-la-familia-khephren-y-marcus-la-saga-de-los-hermanos-thuram-en-la-juve-inter\/","title":{"rendered":"Scudetto en la familia: Khephren y Marcus, la saga de los hermanos Thuram en la Juve-Inter"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><h2 class=\"is-subtitle\">Los hijos de Lilian nacieron en Emilia y han seguido el mismo camino: ahora competir\u00e1n en la rivalidad m\u00e1s sentida<\/h2>\n<\/p>\n<div class=\"bck-author-signature gz-hide-in-editor\">\n<div class=\"author-signature__content\">\n<div class=\"author-block\">\n<p>\n                                                    <span class=\"author-name\">por nuestro corresponsal Sebastiano Vernazza<\/span>\n                            <\/p>\n<p>\n                <time class=\"article-date xlk\" content=\"2024-07-03T09:16:57+02:00\" data-time=\"2024-07-03\"><\/p>\n<p>                    3 de julio &#8211; 9:16 a.m.  <span class=\"from-location\">&#8211; DUSSELDORF (ALEMANIA)<\/span><br \/>\n                <\/time>\n            <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"content \" id=\"m38902-38901-38903\">\n<p class=\"paragraph\" spellcheck=\"true\">Hermanos, pero no cuchillos.  Hijos del arte, con el padre Lilian, ex defensa del Parma y la Juve, siempre presente en las gradas y entrenamientos.  Marcus y Khephren Thuram se volver\u00e1n a encontrar en la Serie A. Marcus, delantero del Inter, campe\u00f3n italiano;  Centrocampista de Khephren en la ambiciosa nueva Juve de Thiago Motta.  No ha habido muchos hermanos rivales en equipos de alto nivel en nuestro campeonato: los Baresi, Franco y Beppe, repartidos entre Mil\u00e1n e Inter;  los Inzaghis, Filippo y Simone, el primero en la Juve y el Mil\u00e1n y el segundo en la Lazio, ahora entrenador del Inter.  La selecci\u00f3n francesa se convertir\u00e1 en una &#8220;f\u00e1brica hermana&#8221;: un d\u00eda los Thuram se unir\u00e1n a Hern\u00e1ndez, Theo y Lucas, fuera de la Eurocopa por lesi\u00f3n.  Juntos, Marcus y Khephren compartieron una convocatoria con la selecci\u00f3n de \u00e9lite de Francia en marzo de 2023 para el partido contra Holanda (4-0), v\u00e1lido para la clasificaci\u00f3n para la Eurocopa.  Marcus permaneci\u00f3 en el banquillo.  Khephren debut\u00f3 unos momentos m\u00e1s tarde en el partido.  El d\u00eda anterior hab\u00edan aparecido juntos en una rueda de prensa.  &#8220;Khephren es una persona seria &#8211; dijo Marcus -, sabe lo que quiere y estoy impresionado por su progreso. Es decidido. Veo todos los partidos del Niza y veo que Khephren crece cada vez&#8221;.  Y Khephren, a cambio: &#8220;Marcus es jovial y responsable al mismo tiempo. No fue dif\u00edcil ser hermano de Marcus e hijo de Lilian. No me siento a la sombra de nadie, soy yo mismo&#8221;.  Didier Deschamps, compa\u00f1ero de Thuram padre en Francia, campeona del mundo y de Europa entre 1998 y 2000, no les ha dejado jugar juntos todav\u00eda, pero suceder\u00e1, es inevitable.  Llegar\u00e1 el d\u00eda en que Khephren le d\u00e9 una asistencia a Marcus.  Mientras tanto, deber\u00eda registrarse la convocatoria de Khephren para la selecci\u00f3n de Francia que participar\u00e1 en los Juegos de Par\u00eds.  El seleccionador del Olimpica franc\u00e9s es Thierry Henry, exdelantero, que estuvo unos meses en la Juve en 1999, y compa\u00f1ero de padre Thuram en el Barcelona.  Hay fotos de Khephren de ni\u00f1o con Henry en el campo de entrenamiento del Bar\u00e7a.  Era el Barcelona 2007-08: Xavi e Iniesta, Messi y Ronaldinho.  Los hermanos Thuram observaron y aprendieron. <\/p>\n<\/div>\n<div class=\"content content-paragraph \" id=\"m38928-38927-38929\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38974-38973-38975\">diferencias<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Marcus y Khephren son tipos diferentes, en t\u00e9rminos de personajes y estilos de juego.  Ambos nacieron en Emilia, con cuatro a\u00f1os de diferencia, cuando su padre jugaba en el Parma, pero entre los dos el &#8220;italiano&#8221; es Marcus: \u00abMe encanta la alegr\u00eda de vivir y la cocina de los italianos, cuando era ni\u00f1o S\u00f3lo com\u00eda pasta\u201d, dijo en una entrevista.  Khephren mira m\u00e1s a Estados Unidos, porque estudi\u00f3 en una escuela estadounidense.  El ingl\u00e9s es su idioma de referencia y es un apasionado del baloncesto de la NBA.  Thuram padre vigilaba, no quer\u00eda que perdieran el sentido de la proporci\u00f3n.  Cuando Khephren firm\u00f3 su primer gran contrato en el Niza, su padre le impidi\u00f3 comprar un coche de futbolista y el ni\u00f1o se present\u00f3 a entrenar en un coche peque\u00f1o.  Marcus es m\u00e1s extrovertido y tuvo y tiene una relaci\u00f3n de falso conflicto con su padre.  Los dos discuten por todo y siempre llegan a un acuerdo.  Khephren es m\u00e1s tranquilo e introspectivo, pero no en el campo: all\u00ed sabe imponer respeto e imponer sus visiones esenciales.  Quiz\u00e1s Thiago Motta lo quiera porque ve algo de s\u00ed mismo en Kephren, de Motta como un centrocampista racional.  Marcus, el mayor, se muestra protector con Khephren, a quien reconoce una cierta superioridad futbol\u00edstica: &#8220;Es m\u00e1s fuerte que yo&#8221;, afirm\u00f3.  Y es posible que tenga raz\u00f3n, si sopesamos la t\u00e9cnica pura.<\/p>\n<\/div>\n<p><!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic END--><\/p>\n<div class=\"content content-paragraph \" id=\"m38938-38937-38939\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m38980-38979-38981\">en Par\u00eds<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\"> Los hermanos Thuram crecieron en el Athletic Club Boulogne-Billancourt, un club con sede y campos cerca del Parque de los Pr\u00edncipes de Par\u00eds y con tradici\u00f3n de f\u00fatbol juvenil.  Marcus entren\u00f3 aqu\u00ed entre 2010 y 2012, Khephren entre 2013 y 2016. Pap\u00e1 Lilian siempre estuvo al margen de los entrenamientos y partidos, con afabilidad y sin hacerse engorrosos.  Sin temor a presionar a sus hijos, a diferencia de Michel Platini, que muchos a\u00f1os antes hab\u00eda decidido que su hijo Laurent se inscribiera en el Boulogne-Billancourt con el apellido de su madre.  Los entrenadores de la \u00e9poca cre\u00edan que Marcus era explosivo y estaba por encima del promedio en t\u00e9rminos de f\u00edsico y carrera y dentro de lo normal en t\u00e9rminos de caminar.  Allan Saint-Maximin, ex extremo del Newcastle lleno de t\u00e9cnica y velocidad, tambi\u00e9n &#8220;criado&#8221; por Boulogne-Billancourt, contempor\u00e1neo de Marcus y ahora &#8220;desaparecido&#8221; en Arabia, era considerado m\u00e1s h\u00e1bil.  Khephren corri\u00f3 menos que su hermano porque no lo necesitaba, siempre hizo lo correcto en cuanto a pases y opciones de juego, cualidades que perfeccion\u00f3.  En Boulogne-Billancourt estaban convencidos de que Kefr\u00e9n llegar\u00eda m\u00e1s alto que Marco.  Estaban bien.  En sus respectivas diferencias, los &#8220;hermanos Thuram&#8221; han llegado a lo m\u00e1s alto del f\u00fatbol y pronto disputar\u00e1n el partido m\u00e1s conflictivo de nuestro campeonato, el Inter-Juve, el derbi italiano de los hermanos franceses.<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js fxr-left-center\">\n<div class=\"bck-copyright\">\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/div><\/div>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ESI generic START--><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&device=desktop&cmsType=xalok&type=article&EXT_COMMENTS=xalok&path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic END--><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Calciomercato\/Juventus\/03-07-2024\/thuram-fratelli-contro-khephren-contro-marcus-nella-sfida-juve-inter.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hijos de Lilian nacieron en Emilia y han seguido el mismo camino: ahora competir\u00e1n en la rivalidad<\/p>\n","protected":false},"author":1,"featured_media":1261657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[126,2296,32040,238513,36,18620,21322,1139,30],"class_list":["post-1261656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-familia","tag-hermanos","tag-juveinter","tag-khephren","tag-los","tag-marcus","tag-saga","tag-scudetto","tag-thuram"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1261656"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1261656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1261657"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1261656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1261656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1261656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}