{"id":1254804,"date":"2024-06-27T19:50:17","date_gmt":"2024-06-27T19:50:17","guid":{"rendered":"https:\/\/teknomers.com\/es\/nos-trabajara-mucho-menos-con-autonomos-debido-a-una-legislacion-mas-estricta-y-a-su-aplicacion-por-parte-de-las-autoridades-fiscales\/"},"modified":"2024-06-27T19:50:21","modified_gmt":"2024-06-27T19:50:21","slug":"nos-trabajara-mucho-menos-con-autonomos-debido-a-una-legislacion-mas-estricta-y-a-su-aplicacion-por-parte-de-las-autoridades-fiscales","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/nos-trabajara-mucho-menos-con-autonomos-debido-a-una-legislacion-mas-estricta-y-a-su-aplicacion-por-parte-de-las-autoridades-fiscales\/","title":{"rendered":"NOS trabajar\u00e1 mucho menos con aut\u00f3nomos debido a una legislaci\u00f3n m\u00e1s estricta y a su aplicaci\u00f3n por parte de las autoridades fiscales"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>A partir del 1 de julio de 2025, NOS trabajar\u00e1 con muchos menos aut\u00f3nomos que ahora.  La emisora \u200b\u200blo anunci\u00f3 en un correo electr\u00f3nico interno el jueves. <em>NRC<\/em>, informe a su personal.  A partir del 1 de enero de 2025, las autoridades fiscales controlar\u00e1n mucho m\u00e1s estrictamente los falsos aut\u00f3nomos y un a\u00f1o despu\u00e9s probablemente entre en vigor una ley que har\u00e1 que la definici\u00f3n de aut\u00f3nomo sea a\u00fan m\u00e1s estricta.  Actualmente trabajan para el NOS unos doscientos aut\u00f3nomos, la mayor\u00eda de los cuales son empleados disfrazados seg\u00fan esa definici\u00f3n restringida.<\/p>\n<p>La nueva ley se introduce para proteger a los trabajadores aut\u00f3nomos.  Algunos aut\u00f3nomos en los Pa\u00edses Bajos tienen ingresos bajos e inseguros y poco margen para negociar con sus clientes.  A menudo tampoco est\u00e1n protegidos contra riesgos como el desempleo y la enfermedad, y rara vez acumulan una pensi\u00f3n.  Aunque esto no se aplica necesariamente a los aut\u00f3nomos que trabajan para el NOS, por ejemplo, la ley est\u00e1 dirigida a todos los aut\u00f3nomos.<\/p>\n<p>Uno de los aspectos de la nueva ley: los trabajadores aut\u00f3nomos ya no podr\u00e1n realizar las actividades principales de una organizaci\u00f3n.  Son actividades que tambi\u00e9n realizan los empleados asalariados.  Un gran n\u00famero de los aproximadamente doscientos trabajadores aut\u00f3nomos de NOS realizan (en gran medida) el mismo trabajo que sus compa\u00f1eros por cuenta ajena.  Esto tambi\u00e9n se aplica a los trabajadores aut\u00f3nomos de muchos otros medios de comunicaci\u00f3n de los Pa\u00edses Bajos.  La NOS escribe en el correo electr\u00f3nico interno que ha informado a sus trabajadores independientes &#8220;antes que la mayor\u00eda de las otras organizaciones, al parecer&#8221;.<\/p>\n<p>A\u00fan no est\u00e1 claro cu\u00e1les ser\u00e1n las consecuencias para los aut\u00f3nomos de NOS.  Lo cierto es que les resultar\u00e1 dif\u00edcil seguir trabajando para la emisora \u200b\u200bdespu\u00e9s de la introducci\u00f3n de la nueva ley.  Internamente, la direcci\u00f3n de NOS habr\u00eda aconsejado a los aut\u00f3nomos que reflexionaran sobre su carrera profesional.  A\u00fan no est\u00e1 claro si el NOS puede ofrecer a los trabajadores aut\u00f3nomos un contrato colectivo de trabajo y, en caso afirmativo, qu\u00e9 parte.  El correo electr\u00f3nico dice sobre los contratos: &#8220;A\u00fan no sabemos c\u00f3mo y de qu\u00e9 forma deber\u00edan implementarse&#8221;.<\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<div class=\"dmt-article-suggestion__text\">\n<p>\t\t\t\tLea tambi\u00e9n\n\t\t\t<\/p>\n<p><span>Seg\u00fan estos criterios, pronto ser\u00e1s trabajador por cuenta ajena o por cuenta propia<\/span>\n<\/div>\n<p><dmt-util-bar article=\"4858000\" headline=\"NOS gaat veel minder met freelancers werken door strengere wet en handhaving Belastingdienst\" url=\"https:\/\/www.nrc.nl\/nieuws\/2024\/06\/27\/nos-gaat-veel-minder-met-freelancers-werken-door-strengere-wet-en-handhaving-belastingdienst-a4858000\"><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"share\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Para compartir<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-share-web\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<button class=\"dmt-util-bar__button\" slot=\"contact\"><br \/>\n<span class=\"dmt-util-bar__button-container\"><br \/>\n<span class=\"dmt-util-bar__button-title\">Env\u00ede un correo electr\u00f3nico al editor<\/span><br \/>\n<dmt-icon aria-hidden=\"true\" class=\"dmt-util-bar__button-icon\" name=\"ic-email\"\/><br \/>\n<\/span><br \/>\n<\/button><br \/>\n<\/dmt-util-bar> <\/p>\n<aside data-article-id=\"4858000\" data-js-topic-preview=\"\" data-topic-id=\"57\" data-topic-name=\"Arbeidsmarkt\"\/>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2024\/06\/27\/nos-gaat-veel-minder-met-freelancers-werken-door-strengere-wet-en-handhaving-belastingdienst-a4858000\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 1 de julio de 2025, NOS trabajar\u00e1 con muchos menos aut\u00f3nomos que ahora. La emisora<\/p>\n","protected":false},"author":1,"featured_media":1254805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[450,8102,2856,99,351,26762,3021,246,11083,16,1995,2796,2300,1854,231,32390,158],"class_list":["post-1254804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-aplicacion","tag-autonomos","tag-autoridades","tag-con","tag-debido","tag-estricta","tag-fiscales","tag-las","tag-legislacion","tag-mas","tag-menos","tag-mucho","tag-nos","tag-parte","tag-por","tag-trabajara","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1254804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1254804"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1254804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1254805"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1254804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1254804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1254804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}