{"id":1246504,"date":"2024-06-21T08:31:49","date_gmt":"2024-06-21T08:31:49","guid":{"rendered":"https:\/\/teknomers.com\/es\/todo-el-sistema-de-pasillo-bajo-el-estudio-de-television-rechazado-por-eva-jinek\/"},"modified":"2024-06-21T08:31:53","modified_gmt":"2024-06-21T08:31:53","slug":"todo-el-sistema-de-pasillo-bajo-el-estudio-de-television-rechazado-por-eva-jinek","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/todo-el-sistema-de-pasillo-bajo-el-estudio-de-television-rechazado-por-eva-jinek\/","title":{"rendered":"&#8216;Todo el sistema de pasillo bajo el estudio de televisi\u00f3n rechazado por Eva Jinek&#8217;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>La AD ha iniciado una especie de guerra contra Eva Jinek porque va a retransmitir desde \u00c1msterdam y ahora incluso han incitado a Pieter Omtzigt contra ella.  \u00bfPero no tiene raz\u00f3n?<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 ONG<\/span> <\/div>\n<p>Eva Jinek ha renunciado a un mill\u00f3n de euros de sueldo porque prefiere hacer su programa de entrevistas en la televisi\u00f3n p\u00fablica.  La NPO tiene muchas esperanzas de poder finalmente entregar al so\u00f1ado sucesor de De Wereld Draait Door.  Su cabeza est\u00e1 en el tajo, por lo que es l\u00f3gico que la presentadora tenga algo que exigir.<\/p>\n<h2 class=\"wp-block-heading\">Inc\u00f3modo<\/h2>\n<p>El nuevo programa de entrevistas de Eva ya tiene un contrato firmado por cuatro a\u00f1os, por lo que todas las inversiones en su programa son en cualquier caso a largo plazo.  El presentador quiere crear algo duradero, algo cautivador.  Y tambi\u00e9n quiere ofrecer a sus invitados una buena experiencia.  \u00bfPodr\u00e1 darlo en el l\u00fagubre Media Park?  No, piensa ella misma.  Ella elige la capital.<\/p>\n<p>Aunque la televisi\u00f3n nacional suele estar muy orientada al capital, es innegable que el nuevo lugar de transmisi\u00f3n de Eva, De Hallen en Amsterdam, es mucho mejor que el terrible Studio 3 en Hilversum.  Sin embargo, la AD est\u00e1 furiosa y ha calculado en un posavasos que su nueva ubicaci\u00f3n costar\u00eda 2 millones de euros m\u00e1s.<\/p>\n<h2 class=\"wp-block-heading\">Preguntas parlamentarias<\/h2>\n<p>Seg\u00fan NPO, este c\u00e1lculo es incorrecto, pero la campa\u00f1a contra Eva ya ha comenzado: el peri\u00f3dico ha conseguido incluso enojar al partido de Pieter Omtzigt.  Va <a rel=\"nofollow noopener\" href=\"https:\/\/www.ad.nl\/show\/nsc-wil-tekst-en-uitleg-van-staatssecretaris-na-commotie-rond-nieuwe-talkshow-eva-jinek~a4e1f492\/\" target=\"_blank\">Preguntas parlamentarias<\/a> Pregunta por el estudio de Eva.  Cualquier cosa con tal de recuperarla en el Mediapark, en el mismo terrible estudio que el de Sophie &#038; Jeroen, y hasta hace poco el de Op1.<\/p>\n<p>El creador de opini\u00f3n Johan Fretz considera que esto es muy exagerado.  \u00c9l escribe sarc\u00e1sticamente <a rel=\"nofollow\" href=\"https:\/\/x.com\/johanfretz\/status\/1803891032305635387?s=12&amp;t=zYLafuzcWwKyKdpespCyKg\">X<\/a>: \u201cPieter Omtzigt quiere realizar una investigaci\u00f3n parlamentaria sobre la elecci\u00f3n de Jinek de realizar su programa de entrevistas desde Amsterdam.  Todo para garantizar que la base constitucional permanezca intacta; de lo contrario, no quedar\u00e1 nada que destruir\u201d.<\/p>\n<h2 class=\"wp-block-heading\">&#8216;\u00a1\u00bfRealmente tan malo?!&#8217;<\/h2>\n<p>La gran pregunta es: \u00bfes realmente tan malo el estudio en Hilversum que Eva rechaz\u00f3?  Seg\u00fan \u00c1ngela de Jong, es realmente deprimente y los ba\u00f1os son horribles.  \u00bfQu\u00e9 piensa Tina Nijkamp?  La autoridad de televisi\u00f3n dice en ella. <a rel=\"nofollow noopener\" href=\"https:\/\/open.spotify.com\/episode\/6ruQjO0L8ewOxrtTKiEjB0?si=f30d77ded729465b\" target=\"_blank\">podcast<\/a>: \u201cEntonces, cuando llegas al Media Park, hay un edificio de estudios a la derecha\u201d.<\/p>\n<p>Hay una puerta en ese edificio.  \u201cY cuando entras all\u00ed, bajas un tramo de escaleras\u201d.<\/p>\n<p>Espantoso.  \u201cPor supuesto que eso no se siente muy bien, porque parece como si estuvieras entrando en un s\u00f3tano sin ventanas y eso es cierto.  No puedes ver ninguna luz exterior despu\u00e9s de bajar las escaleras\u201d.<\/p>\n<h2 class=\"wp-block-heading\">Sistema de corredores<\/h2>\n<p>\u00bfY qu\u00e9 una vez que te han atra\u00eddo?  \u201cLuego llegamos a una sala muy grande, casi una especie de sistema de pasillos.  Un sistema de t\u00faneles subterr\u00e1neos.  As\u00ed se siente un poco.  Amplios pasillos.  Y luego a la izquierda est\u00e1 la sala de recepci\u00f3n.  Bueno, en realidad se ve muy bien.  Es muy grande y eso lo hace muy inc\u00f3modo\u201d.<\/p>\n<p>En esa enorme y loca sala hay seis mesas redondas muy grandes con sillas verdes.  \u201cEsas sillas muy verdes que se ven mucho ahora.  Hay bancos verdes y una foto de pared muy bien iluminada de un puente, un puente holand\u00e9s y algunas otras fotos hermosas en la pared.  Se ve muy bien, pero es demasiado grande\u201d.<\/p>\n<h2 class=\"wp-block-heading\">Perdido<\/h2>\n<p>El enorme tama\u00f1o de esa sala la hace un poco extra\u00f1a, dice Tina.  \u201cCuando te sientas ah\u00ed, realmente te sientes perdido, porque est\u00e1s en una especie de edificio escolar que es muy grande.  Eso es lo que se siente.  Al lado est\u00e1 la sala de maquillaje, la sala de maquillaje.  Eso es hermoso.  Hay todo tipo de cuadros colgados en la pared, esos cuadros del Rijksmuseum\u201d.<\/p>\n<p>As\u00ed que no est\u00e1 tan mal en maquillaje, pero luego\u2026 \u201cCuando caminas hacia el estudio, tienes que pasar por ese sistema de pasillos nuevamente\u201d.<\/p>\n<p>Horrible.  \u00bfY si tienes que ir al ba\u00f1o?  &#8220;Son muy peque\u00f1os y no huelen muy bien, pero tengo que decir: hay muchos&#8221;.<\/p>\n<h2 class=\"wp-block-heading\">Socialidad<\/h2>\n<p>Tina entiende perfectamente a Eva, aunque le parece muy alto el supuesto precio de 2 millones de euros.  \u201cEntiendo muy bien que Eva quiera vivir en \u00c1msterdam, porque es mucho m\u00e1s agradable y tienes luz del d\u00eda, pero es mucho m\u00e1s impr\u00e1ctico.  Lo mantengo\u201d.<\/p>\n<p>\u201cA Eva tambi\u00e9n le vendr\u00eda bien trabajar durante el d\u00eda en un ambiente agradable.  El Media Park en s\u00ed tambi\u00e9n es muy triste.  Tambi\u00e9n trabaj\u00e9 all\u00ed durante a\u00f1os y debo decir honestamente: me sent\u00ed muy feliz cuando pude trabajar en SBS en \u00c1msterdam en un ambiente de vida\u201d.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2024\/06\/heel-gangenstelsel-onder-door-eva-jinek-geweigerde-tv-studio\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La AD ha iniciado una especie de guerra contra Eva Jinek porque va a retransmitir desde \u00c1msterdam y<\/p>\n","protected":false},"author":1,"featured_media":1246505,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[5200,774,14868,148670,14869,49156,231,13485,5321,2198,212975,339],"class_list":["post-1246504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-bajo","tag-estudio","tag-eva","tag-eva-jinek","tag-jinek","tag-pasillo","tag-por","tag-rechazado","tag-sistema","tag-television","tag-tina-nijkamp","tag-todo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1246504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1246504"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1246504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1246505"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1246504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1246504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1246504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}