{"id":1235240,"date":"2024-06-13T00:30:50","date_gmt":"2024-06-13T00:30:50","guid":{"rendered":"https:\/\/teknomers.com\/es\/jan-ullrich-celebra-su-regreso-a-la-television-alemana-en-el-tour-de-francia\/"},"modified":"2024-06-13T00:30:54","modified_gmt":"2024-06-13T00:30:54","slug":"jan-ullrich-celebra-su-regreso-a-la-television-alemana-en-el-tour-de-francia","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jan-ullrich-celebra-su-regreso-a-la-television-alemana-en-el-tour-de-francia\/","title":{"rendered":"Jan Ullrich celebra su regreso a la televisi\u00f3n alemana: en el Tour de Francia"},"content":{"rendered":"\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"font-bold text-18 Articleleading-17\">En los a\u00f1os 90, Jan Ullrich era uno de los mejores ciclistas del mundo.  Ahora el exdeportista quiere transmitir sus experiencias y conocimientos en la televisi\u00f3n.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 Articleleading-17\">Jan Ullrich ser\u00e1 invitado al estudio del canal de televisi\u00f3n Eurosport durante dos etapas del Tour de Francia.  El ganador del Tour de 1997 aparecer\u00e1 en el programa \u201cVelo Club\u201d en los estudios de M\u00fanich los d\u00edas 2 y 3 de julio, que se retransmitir\u00e1 inmediatamente despu\u00e9s del final de la etapa.  Eurosport lo anunci\u00f3 el mi\u00e9rcoles.  El Tour de Francia comienza el 29 de junio en Florencia y finaliza el 21 de julio en Niza.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 Articleleading-17\">&#8220;El Tour de Francia ha moldeado y dominado mi vida &#8211; con todos sus altibajos &#8211; y me acompa\u00f1ar\u00e1 durante toda mi vida. El ciclismo sigue siendo mi gran amor. Aqu\u00ed estoy en mi profesi\u00f3n. Me gustar\u00eda dar algo a cambio y a mi transmitir experiencias&#8221;, afirm\u00f3 Ullrich.  Espera contribuir con sus d\u00e9cadas de experiencia.<\/p>\n<\/div>\n<div data-testid=\"StageLayout.StreamItem\">\n<p class=\"text-18 Articleleading-17\">La etapa del 2 de julio discurre de Pinerolo a Valloire.  Se trata de cruzar el Col du Galibier, de 2.642 metros de altura, donde Ullrich sufri\u00f3 un colapso en 1998 y finalmente perdi\u00f3 el recorrido ante Marco Pantani.  Un d\u00eda despu\u00e9s, la etapa discurre desde Saint-Jean-de-Maurienne hasta Saint-Vulbas, donde se espera una llegada al sprint.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/mehr-sport\/radsport\/tour-de-france\/id_100425708\/jan-ullrich-feiert-comeback-im-deutschen-tv-bei-der-tour-de-france.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los a\u00f1os 90, Jan Ullrich era uno de los mejores ciclistas del mundo. Ahora el exdeportista quiere<\/p>\n","protected":false},"author":1,"featured_media":1235241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[2884,35,63340,1714,789,82513,8046,604,2198,185,29940,39921],"class_list":["post-1235240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-alemana","tag-celebra","tag-eurosport","tag-francia","tag-jan","tag-jan-ullrich","tag-regresar","tag-regreso","tag-television","tag-tour","tag-tour-de-francia","tag-ullrich"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1235240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1235240"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1235240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1235241"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1235240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1235240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1235240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}