{"id":1222019,"date":"2024-03-08T03:14:31","date_gmt":"2024-03-08T03:14:31","guid":{"rendered":"https:\/\/teknomers.com\/es\/belgica-es-en-gran-medida-independiente-gracias-a-rusia-posiblemente-no-sea-una-coincidencia-que-putin-apunte-ahora-a-nuestro-pais\/"},"modified":"2024-03-08T03:14:35","modified_gmt":"2024-03-08T03:14:35","slug":"belgica-es-en-gran-medida-independiente-gracias-a-rusia-posiblemente-no-sea-una-coincidencia-que-putin-apunte-ahora-a-nuestro-pais","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/belgica-es-en-gran-medida-independiente-gracias-a-rusia-posiblemente-no-sea-una-coincidencia-que-putin-apunte-ahora-a-nuestro-pais\/","title":{"rendered":"&#8220;B\u00e9lgica es en gran medida independiente gracias a Rusia&#8221;: posiblemente no sea una coincidencia que Putin apunte ahora a nuestro pa\u00eds"},"content":{"rendered":"\n<div>\n<aside data-test-id=\"temptation-ARTICLE_INLINE_MIDDLE\" data-temptation-position=\"ARTICLE_INLINE_MIDDLE\" class=\"gi55p43 gi55p42\"\/>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\"><span class=\"_1s2xivw0\">t<\/span>A una pregunta de un joven belga en el Festival Mundial de la Juventud celebrado en la ciudad de Sochi, en el sur de Rusia, Putin respondi\u00f3 con relativa naturalidad que &#8220;B\u00e9lgica, por cierto, probablemente lo sepas, apareci\u00f3 en el mapa mundial, sobre todo gracias a Rusia y su posici\u00f3n&#8221;. como estado independiente\u201d.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Sin embargo, con su declaraci\u00f3n Putin da un gran giro a la historia a favor de Rusia.  Porque es todo lo contrario.  Fue el zar ruso Nicol\u00e1s I \u2013apodado \u201cel gendarme de Europa\u201d\u2013 quien se puso del lado del Reino Unido de los Pa\u00edses Bajos cuando estall\u00f3 la revoluci\u00f3n belga en 1830, contra el intento belga de secesionarse.  Rusia incluso quiso enviar tropas para reprimir el levantamiento.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Ese paso estaba en consonancia con el objetivo de Nicol\u00e1s de apoyar a las monarqu\u00edas gobernantes en Europa tanto como fuera posible, contra los intentos revolucionarios que tambi\u00e9n podr\u00edan afianzarse en el Imperio ruso.  Los lazos familiares tambi\u00e9n influyeron: la hermana de Nicol\u00e1s, Anna Paulowna, estaba casada con el pr\u00edncipe heredero holand\u00e9s Guillermo II, hijo del rey Guillermo I. <\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Por lo tanto, Nicol\u00e1s hizo planes para enviar tropas rusas a nuestra regi\u00f3n para ayudar a Guillermo I a sofocar el levantamiento.  Al mismo tiempo, si fuera posible, tambi\u00e9n podr\u00eda intervenir contra la Revoluci\u00f3n Francesa de Julio de 1830, en la que fue depuesto el monarca absoluto Carlos X.<\/p>\n<h2 class=\"_3fx0xw0 _1bm64ig0\">Polonia<\/h2>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Sin embargo, los planes del zar se vieron frustrados por el levantamiento polaco de noviembre de 1830 contra el dominio ruso, que tuvo lugar aproximadamente simult\u00e1neamente con la revoluci\u00f3n belga.  Los regimientos rusos que ya estaban estacionados en Polonia para avanzar hacia B\u00e9lgica de pronto se vieron m\u00e1s que ocupados.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Al final, Rusia reconoci\u00f3 la independencia belga en la Conferencia de Londres a finales de 1830, ya que estaba sola frente a las otras cuatro grandes potencias europeas: Francia, el Reino Unido, Prusia y Austria.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">La figura del rey Leopoldo I tambi\u00e9n fue importante, afirma el historiador Herman Van Goethem (Universidad de Amberes).  \u201cPersonaliz\u00f3 la neutralidad belga y el equilibrio de poder europeo desde 1815: era un pr\u00edncipe alem\u00e1n, viudo de una princesa heredera brit\u00e1nica y su cu\u00f1ado era hermano del zar ruso.  Putin puede estar refiri\u00e9ndose a este v\u00ednculo familiar con Rusia para explicar la buena voluntad de Rusia hacia la independencia belga.  Sin embargo, la historia es mucho m\u00e1s compleja\u201d.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">No fue hasta 1839 que los propios Pa\u00edses Bajos aceptaron la independencia belga.  Aunque esa independencia se la debemos m\u00e1s a los polacos que a los rusos.<\/p>\n<h2 class=\"_3fx0xw0 _1bm64ig0\">Euroclaro<\/h2>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Puede que no sea una coincidencia que la declaraci\u00f3n de Putin se centre ahora en B\u00e9lgica.  Desde hace alg\u00fan tiempo, Occidente debate c\u00f3mo utilizar 270.000 millones de euros en activos rusos congelados para beneficiar a Ucrania.  Una gran parte de ese dinero se encuentra en Bruselas, en la c\u00e1mara de compensaci\u00f3n Euroclear.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">El a\u00f1o pasado, B\u00e9lgica pudo reservar 625 millones de euros para Ucrania gracias a los ingresos fiscales procedentes de los intereses de los activos congelados que se invierten.  Junto con el hecho de que B\u00e9lgica alberga la sede de la Uni\u00f3n Europea y la OTAN, esto convierte a nuestro pa\u00eds en un objetivo ideal para Rusia.<\/p>\n<p class=\"wfc0ho5 wfc0ho0 _18x8la40\">Tampoco es la primera vez que Putin toma un rumbo bastante libre con la historia.  La invasi\u00f3n de Ucrania tambi\u00e9n se justifica con afirmaciones muy cuestionables sobre c\u00f3mo ese pa\u00eds en realidad no tiene derecho a existir e hist\u00f3ricamente es s\u00f3lo parte de Rusia.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.demorgen.be\/oorlog-in-oekraine\/belgie-grotendeels-dankzij-rusland-onafhankelijk-het-is-mogelijk-geen-toeval-dat-poetin-net-nu-ons-land-in-het-vizier-neemt~b57851f6\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-31<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>tA una pregunta de un joven belga en el Festival Mundial de la Juventud celebrado en la ciudad<\/p>\n","protected":false},"author":1,"featured_media":1222020,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[191,134531,203,16841,1962,92,7277,5944,1655,1392,1872,1177,457,15,158],"class_list":["post-1222019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-ahora","tag-apunte","tag-belgica","tag-coincidencia","tag-gracias","tag-gran","tag-independiente","tag-medida","tag-nuestro","tag-pais","tag-posiblemente","tag-putin","tag-rusia","tag-sea","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1222019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1222019"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1222019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1222020"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1222019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1222019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1222019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}