{"id":1216374,"date":"2024-03-04T21:43:28","date_gmt":"2024-03-04T21:43:28","guid":{"rendered":"https:\/\/teknomers.com\/es\/joven-reservista-se-declara-culpable-de-filtrar-datos-del-pentagono-y-acepta-16-anos-de-prision\/"},"modified":"2024-03-04T21:43:33","modified_gmt":"2024-03-04T21:43:33","slug":"joven-reservista-se-declara-culpable-de-filtrar-datos-del-pentagono-y-acepta-16-anos-de-prision","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/joven-reservista-se-declara-culpable-de-filtrar-datos-del-pentagono-y-acepta-16-anos-de-prision\/","title":{"rendered":"Joven reservista se declara culpable de filtrar datos del Pent\u00e1gono y acepta 16 a\u00f1os de prisi\u00f3n"},"content":{"rendered":"\n<p>El soldado estadounidense Jack Teixeira (22) acept\u00f3 una sentencia de diecis\u00e9is a\u00f1os de prisi\u00f3n por filtrar documentos militares estadounidenses secretos a trav\u00e9s de una plataforma de redes sociales.  ABC News informa esto.  Si no hubiera aceptado la oferta de declaraci\u00f3n de los fiscales, el juez podr\u00eda haberlo condenado a hasta treinta a\u00f1os de prisi\u00f3n.<br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.ad.nl\/buitenland\/jonge-reservist-pleit-schuldig-aan-lekken-pentagon-gegevens-en-aanvaardt-16-jaar-cel~a6cfc794\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-43<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El soldado estadounidense Jack Teixeira (22) acept\u00f3 una sentencia de diecis\u00e9is a\u00f1os de prisi\u00f3n por filtrar documentos militares<\/p>\n","protected":false},"author":1,"featured_media":1216375,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2193,205,14764,1755,6754,38,22339,4158,14403,206,2685],"class_list":["post-1216374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-acepta","tag-anos","tag-culpable","tag-datos","tag-declara","tag-del","tag-filtrar","tag-joven","tag-pentagono","tag-prision","tag-reservista"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1216374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1216374"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1216374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1216375"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1216374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1216374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1216374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}