{"id":1211570,"date":"2024-03-01T20:55:27","date_gmt":"2024-03-01T20:55:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/un-coche-se-incendia-poco-despues-del-mantenimiento-en-el-garaje-el-vehiculo-se-quema-por-completo\/"},"modified":"2024-03-01T20:55:32","modified_gmt":"2024-03-01T20:55:32","slug":"un-coche-se-incendia-poco-despues-del-mantenimiento-en-el-garaje-el-vehiculo-se-quema-por-completo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/un-coche-se-incendia-poco-despues-del-mantenimiento-en-el-garaje-el-vehiculo-se-quema-por-completo\/","title":{"rendered":"Un coche se incendia poco despu\u00e9s del mantenimiento en el garaje: el veh\u00edculo se quema por completo"},"content":{"rendered":"\n<p>Un Mercedes estall\u00f3 completamente en llamas el viernes por la noche en la Europalaan de Zele despu\u00e9s de que el veh\u00edculo se incendiara mientras estaba en movimiento.  El propietario acababa de recoger su coche del garaje despu\u00e9s de que se averiara y fuera necesario sustituir una pieza.  Del veh\u00edculo no queda casi nada.<br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.hln.be\/zele\/auto-vat-vuur-vlak-na-onderhoud-bij-garage-voertuig-volledig-uitgebrand~a30ce9ed\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-3<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Mercedes estall\u00f3 completamente en llamas el viernes por la noche en la Europalaan de Zele despu\u00e9s de<\/p>\n","protected":false},"author":1,"featured_media":1211571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2553,1793,38,755,23074,26014,1520,555,231,8478,15399],"class_list":["post-1211570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-coche","tag-completo","tag-del","tag-despues","tag-garaje","tag-incendia","tag-mantenimiento","tag-poco","tag-por","tag-quema","tag-vehiculo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1211570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1211570"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1211570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1211571"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1211570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1211570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1211570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}