{"id":1166186,"date":"2024-02-03T06:02:38","date_gmt":"2024-02-03T06:02:38","guid":{"rendered":"https:\/\/teknomers.com\/es\/hui-ka-yan-el-magnate-de-evergrande-afronta-su-perdicion\/"},"modified":"2024-02-03T06:02:42","modified_gmt":"2024-02-03T06:02:42","slug":"hui-ka-yan-el-magnate-de-evergrande-afronta-su-perdicion","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/hui-ka-yan-el-magnate-de-evergrande-afronta-su-perdicion\/","title":{"rendered":"Hui Ka Yan: el magnate de Evergrande afronta su perdici\u00f3n"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desbloquea el Editor&#8217;s Digest gratis<\/p>\n<p class=\"article__content-sign-up-topic-description\"><span>Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/span><\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=2be0ccdc-b607-4822-bcca-8344384cc7a1\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>La p\u00e1gina de inicio de Evergrande est\u00e1 congelada en el tiempo hace poco m\u00e1s de un a\u00f1o.  En aquel entonces, su fundador, Hui Ka Yan, todav\u00eda parec\u00eda tener la esperanza de poder salvar al desarrollador m\u00e1s endeudado del mundo.  \u201cTodos los empleados de Evergrande deben.  .  .  Nunca te rindas\u201d, dice el carism\u00e1tico magnate a los ejecutivos en un video, exhort\u00e1ndolos a terminar miles de apartamentos que quedaron incompletos despu\u00e9s de que la compa\u00f1\u00eda incumpliera oficialmente su deuda de 300 mil millones de d\u00f3lares en 2021.<\/p>\n<p>Pero las valientes palabras no pudieron evitar el desastre.  Esta semana un juez de Hong Kong declar\u00f3 \u201cya es suficiente\u201d.  Evergrande, cuyo colapso ayud\u00f3 a desencadenar una crisis inmobiliaria que ha provocado una desaceleraci\u00f3n en la segunda econom\u00eda m\u00e1s grande del mundo, deber\u00eda ser liquidada.  Hui no pudo reaccionar.  El empresario, llamado Xu Jiayin en mandar\u00edn, desapareci\u00f3 en septiembre y se encuentra detenido en alg\u00fan lugar de China bajo sospecha de participaci\u00f3n en \u201cdelitos ilegales\u201d.<\/p>\n<p>Pero el fallo y su detenci\u00f3n son un final ignominioso para el ascenso de un ex trabajador sider\u00fargico que se convirti\u00f3 en uno de los m\u00e1s ricos de China durante los a\u00f1os de auge.  En menos de tres d\u00e9cadas, Hui cre\u00f3 una de las empresas inmobiliarias m\u00e1s grandes del pa\u00eds mientras incursionaba en el f\u00fatbol, \u200b\u200blos veh\u00edculos el\u00e9ctricos y los parques tem\u00e1ticos.  Us\u00f3 su fabulosa riqueza para congraciarse con las \u00e9lites, desde la \u201caristocracia roja\u201d de Beijing hasta la familia real brit\u00e1nica.<\/p>\n<p>&#8220;De todos los desarrolladores, debo decir que fue uno de los m\u00e1s agresivos&#8221;, dice Desmond Shum, autor de <em>Ruleta Roja<\/em>, un libro sobre la pol\u00edtica y los negocios de la \u00e9lite china, que conoci\u00f3 a Hui en su apogeo.  &#8220;As\u00ed que cuando el mercado cambia, no es sorprendente que estas personas sean las primeras en ser cortadas&#8221;.<\/p>\n<p>Como muchos de su generaci\u00f3n, la vida personal de Hui reflej\u00f3 los r\u00e1pidos cambios de China despu\u00e9s de la apertura de su econom\u00eda a finales de los a\u00f1os 1970.  Nacido en la pobreza en la provincia de Henan, fue criado por su abuela.  Despu\u00e9s de trabajar en la industria del acero en la d\u00e9cada de 1980, lanz\u00f3 Evergrande en 1996 justo a tiempo para captar un auge inmobiliario impulsado por la nueva clase media de China.<\/p>\n<p>Despu\u00e9s de expandirse a 280 ciudades, seg\u00fan el sitio web de Evergrande, Hui invirti\u00f3 en parques tem\u00e1ticos y destin\u00f3 fondos a un programa gubernamental de reurbanizaci\u00f3n de \u201cbarrios marginales\u201d.  Esto lo dej\u00f3 muy expuesto a las ciudades m\u00e1s peque\u00f1as de China, donde los expertos advirtieron que el mercado se dirig\u00eda hacia un exceso de oferta. <\/p>\n<p>\u00c9l y otros promotores a menudo vend\u00edan casas antes de la construcci\u00f3n, utilizando los fondos para adquirir terrenos mientras los bancos ofrec\u00edan hipotecas sobre las propiedades no construidas.  Los promotores y los gobiernos locales se volvieron adictos al modelo impulsado por la deuda.  \u201cEse es el problema de una burbuja.  Una vez que est\u00e1s dentro, est\u00e1s dentro; es casi imposible salir\u201d, dijo Zhu Ning, profesor del Instituto Avanzado de Finanzas de Shanghai y autor de <em>La burbuja garantizada de China<\/em>.<\/p>\n<p>Hui lleg\u00f3 a encarnar una nueva y atrevida generaci\u00f3n de magnates chinos, luciendo una hebilla de cintur\u00f3n dorada de Herm\u00e8s, comprando mansiones en Sydney, Hong Kong y Londres, y volando en jets privados.  En 2015, compr\u00f3 un megayate de 60 metros y celebr\u00f3 la victoria de su equipo de f\u00fatbol, \u200b\u200bGuangzhou Evergrande, en la Liga de Campeones de Asia, con el copropietario del multimillonario de Internet Jack Ma y el pr\u00edncipe Andr\u00e9s de Gran Breta\u00f1a.  En 2017, encabez\u00f3 la lista de ricos de Forbes China, con un patrimonio neto total de casi 43.000 millones de d\u00f3lares.<\/p>\n<p>Quienes lo conocieron dicen que ten\u00eda una personalidad brillante y tranquila, perfecta para establecer contactos de alto nivel.  Seg\u00fan un banquero: \u201cHui es una persona con un alto coeficiente intelectual.  .  .[otherwise]\u00bfC\u00f3mo pudo persuadir a algunos grandes financieros de Hong Kong para que invirtieran en \u00e9l y en Evergrande? <\/p>\n<p>La ca\u00edda de Hui comenz\u00f3 en 2020, cuando el gobierno del presidente Xi Jinping introdujo una nueva pol\u00edtica que limitaba el apalancamiento en su intento de corregir los desequilibrios econ\u00f3micos.  El modelo agresivo de Evergrande signific\u00f3 que esto se tradujera r\u00e1pidamente en una crisis de liquidez.  Su reestructuraci\u00f3n de bonos extraterritoriales fue de hecho bloqueada el a\u00f1o pasado despu\u00e9s de que las autoridades encontraron irregularidades en su brazo continental, lo que llev\u00f3 a la liquidaci\u00f3n.<\/p>\n<p>Sin embargo, pocos esperan que la orden de liquidaci\u00f3n se extienda al continente.  Beijing no ceder\u00e1 el control del proceso potencialmente explosivo desde el punto de vista pol\u00edtico para resolver las deudas de Evergrande y otros promotores y terminar su gran n\u00famero de apartamentos incompletos, dijeron los analistas. <\/p>\n<p>Hui no estuvo disponible para hacer comentarios y Evergrande no respondi\u00f3 de inmediato. <\/p>\n<p>Muchos ahora creen que Hui podr\u00eda seguir a otros magnates que han ca\u00eddo en desgracia con Beijing, como Xiao Jianhua, un financiero con conexiones pol\u00edticas que fue secuestrado del Four Seasons en Hong Kong por agentes chinos en 2017 y sentenciado a 13 a\u00f1os de prisi\u00f3n.  \u201cIncluso si alguien quisiera contactarlo [Hui]es posible que no puedan hacerlo\u201d, dijo a los periodistas en noviembre el magnate de Hong Kong Joseph Lau, que sol\u00eda jugar a las cartas con \u00e9l.<\/p>\n<p>Su ca\u00edda marca el \u201cfin de una era\u201d, dice Shum.  \u201cMuchos empresarios chinos durante las \u00faltimas d\u00e9cadas asumieron riesgos m\u00e1ximos porque la econom\u00eda estaba en una tendencia ascendente en un solo sentido.  .  .  Entonces, cuando llega la recesi\u00f3n durante la era Xi, la gente no est\u00e1 en absoluto preparada para ello\u201d.<\/p>\n<p>El legado de Hui promete ser, en el mejor de los casos, mixto.  En las afueras de Beijing, Central Mansion es un antiguo proyecto de viviendas de Evergrande \u201crescatado\u201d por la empresa estatal China Railway Construction.  Despu\u00e9s de un largo per\u00edodo de inactividad, seis de sus 15 edificios fueron terminados este mes, dijo un agente, mientras que el resto est\u00e1 previsto para finales de 2024. <\/p>\n<p>Un cliente le dice al Financial Times que est\u00e1 preocupada por su inversi\u00f3n despu\u00e9s de la liquidaci\u00f3n: el complejo seguir\u00e1 siendo administrado por una filial de Evergrande Property Services.  Pero el agente inmobiliario asegura al Financial Times que \u201cno hay nada de qu\u00e9 preocuparse\u201d: Evergrande ya no tiene ninguna influencia real.  &#8220;Despu\u00e9s de todo, el jefe Xu todav\u00eda est\u00e1 tras las rejas&#8221;, dice.<\/p>\n<p><em>Con informaci\u00f3n adicional de Cheng Leng en Hong Kong, Ryan McMorrow en Beijing y Sun Yu en Nueva York<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/2be0ccdc-b607-4822-bcca-8344384cc7a1\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desbloquea el Editor&#8217;s Digest gratis Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/p>\n","protected":false},"author":1,"featured_media":1166187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[23474,23854,52674,13975,56014,54902],"class_list":["post-1166186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-afronta","tag-evergrande","tag-hui","tag-magnate","tag-perdicion","tag-yan"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1166186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1166186"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1166186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1166187"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1166186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1166186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1166186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}