{"id":1163452,"date":"2024-02-01T16:43:56","date_gmt":"2024-02-01T16:43:56","guid":{"rendered":"https:\/\/teknomers.com\/es\/he-desgastado-a-muchos-peluqueros-como-una-mariposa-pero-ahora-ya-esta-he-encontrado-al-indicado\/"},"modified":"2024-02-01T16:44:00","modified_gmt":"2024-02-01T16:44:00","slug":"he-desgastado-a-muchos-peluqueros-como-una-mariposa-pero-ahora-ya-esta-he-encontrado-al-indicado","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/he-desgastado-a-muchos-peluqueros-como-una-mariposa-pero-ahora-ya-esta-he-encontrado-al-indicado\/","title":{"rendered":"He desgastado a muchos peluqueros, como una mariposa, pero ahora ya est\u00e1, he encontrado al indicado."},"content":{"rendered":"\n<div id=\"\">\n<section class=\"artstyle__production artstyle__production--type-plus fu--type-plus artstyle__production--hide-author fu--hide-author artstyle__production--hide-time fu--hide-time artstyle__production--margin-bottom-s-s fu--margin-bottom-s-s artstyle__production--with-authors\" data-element-id=\"article-element-authors\"><span class=\"artstyle__production__authors\">Peter Buwalda<\/span><time class=\"artstyle__production__datetime\" datetime=\"1 februari 2024\"><span class=\"artstyle__production__date\">1 de febrero de 2024<\/span><span class=\"artstyle__production__time\">16:20<\/span><\/time><span class=\"artstyle__production-decoration\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"184\" height=\"11\" viewbox=\"0 0 184 11\" fill=\"none\"><mask id=\"path-1-inside-1\" fill=\"white\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M86.9133 5.08154L81.8318 0L76.7745 5.05725H0V5.65725H76.7288L81.8318 10.7603L86.9133 5.67871L91.9949 10.7603L96.9948 5.76038L101.995 10.7603L107.098 5.65725H184V5.05725H107.052L101.995 0L96.9948 4.99988L91.9949 0L86.9133 5.08154Z\"\/><\/mask><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M86.9133 5.08154L81.8318 0L76.7745 5.05725H0V5.65725H76.7288L81.8318 10.7603L86.9133 5.67871L91.9949 10.7603L96.9948 5.76038L101.995 10.7603L107.098 5.65725H184V5.05725H107.052L101.995 0L96.9948 4.99988L91.9949 0L86.9133 5.08154Z\" fill=\"white\"\/><path d=\"M81.8318 0L82.2122 -0.380432L81.8318 -0.760863L81.4514 -0.380432L81.8318 0ZM86.9133 5.08154L86.5329 5.46197L86.9133 5.84241L87.2938 5.46197L86.9133 5.08154ZM76.7745 5.05725V5.59526H76.9974L77.155 5.43768L76.7745 5.05725ZM0 5.05725V4.51924H-0.538012V5.05725H0ZM0 5.65725H-0.538012V6.19526H0V5.65725ZM76.7288 5.65725L77.1092 5.27682L76.9516 5.11924H76.7288V5.65725ZM81.8318 10.7603L81.4514 11.1407L81.8318 11.5211L82.2122 11.1407L81.8318 10.7603ZM86.9133 5.67871L87.2938 5.29828L86.9133 4.91785L86.5329 5.29828L86.9133 5.67871ZM91.9949 10.7603L91.6144 11.1407L91.9949 11.5211L92.3753 11.1407L91.9949 10.7603ZM96.9948 5.76038L97.3752 5.37995L96.9948 4.99951L96.6143 5.37995L96.9948 5.76038ZM101.995 10.7603L101.614 11.1407L101.995 11.5211L102.375 11.1407L101.995 10.7603ZM107.098 5.65725V5.11924H106.875L106.717 5.27682L107.098 5.65725ZM184 5.65725V6.19526H184.538V5.65725H184ZM184 5.05725H184.538V4.51924H184V5.05725ZM107.052 5.05725L106.671 5.43768L106.829 5.59526H107.052V5.05725ZM101.995 0L102.375 -0.380432L101.995 -0.760863L101.614 -0.380432L101.995 0ZM96.9948 4.99988L96.6143 5.38031L96.9948 5.76074L97.3752 5.38031L96.9948 4.99988ZM91.9949 0L92.3753 -0.380432L91.9949 -0.760863L91.6144 -0.380432L91.9949 0ZM81.4514 0.380432L86.5329 5.46197L87.2938 4.70111L82.2122 -0.380432L81.4514 0.380432ZM77.155 5.43768L82.2122 0.380432L81.4514 -0.380432L76.3941 4.67682L77.155 5.43768ZM76.7745 4.51924H0V5.59526H76.7745V4.51924ZM-0.538012 5.05725V5.65725H0.538012V5.05725H-0.538012ZM0 6.19526H76.7288V5.11924H0V6.19526ZM82.2122 10.3798L77.1092 5.27682L76.3484 6.03768L81.4514 11.1407L82.2122 10.3798ZM86.5329 5.29828L81.4514 10.3798L82.2122 11.1407L87.2938 6.05914L86.5329 5.29828ZM92.3753 10.3798L87.2938 5.29828L86.5329 6.05914L91.6144 11.1407L92.3753 10.3798ZM96.6143 5.37995L91.6144 10.3798L92.3753 11.1407L97.3752 6.14081L96.6143 5.37995ZM102.375 10.3798L97.3752 5.37995L96.6143 6.14081L101.614 11.1407L102.375 10.3798ZM106.717 5.27682L101.614 10.3798L102.375 11.1407L107.478 6.03768L106.717 5.27682ZM107.098 6.19526H184V5.11924H107.098V6.19526ZM184.538 5.65725V5.05725H183.462V5.65725H184.538ZM184 4.51924H107.052V5.59526H184V4.51924ZM101.614 0.380432L106.671 5.43768L107.432 4.67682L102.375 -0.380432L101.614 0.380432ZM97.3752 5.38031L102.375 0.380432L101.614 -0.380432L96.6143 4.61945L97.3752 5.38031ZM91.6144 0.380432L96.6143 5.38031L97.3752 4.61945L92.3753 -0.380432L91.6144 0.380432ZM87.2938 5.46197L92.3753 0.380432L91.6144 -0.380432L86.5329 4.70111L87.2938 5.46197Z\" fill=\"black\" mask=\"url(#path-1-inside-1)\"\/><\/svg><\/span><\/section>\n<p class=\"artstyle__paragraph artstyle__paragraph--drop-cap fu--drop-cap artstyle__paragraph--drop-cap-z fu--drop-cap-z\" data-element-id=\"e864-b829-039d-9de5-46e2-55fe-7a23-2d24\">\n<p>      Entonces, hoy vamos por el mosaico, con algo de periodismo de investigaci\u00f3n en el campo.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"daf6-3e0b-71c5-ddc5-0a08-82df-3e19-d852\">\n<p>      &#8216;\u00bfQuieres m\u00e1s caf\u00e9?&#8217;\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"d1f4-bb7a-fe12-b774-eae3-8383-3f68-df9d\">\n<p>      Mis manos forman una se\u00f1al, no molestes.  &#8216;Ocupado.  Pero todav\u00eda me gustar\u00eda una gota, s\u00ed.  Bonito en realidad.  As\u00ed que por favor.  Vi\u00e9rtalo.  Yol\u00f3.  Por cierto, tengo que irme pronto.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"0dd1-ac95-a690-d32e-fa97-8754-64a1-a3bc\">\n<p>      &#8216;\u00bfLejos?  \u00bfEl d\u00eda de la columna?  \u00bfQu\u00e9 vamos a experimentar ahora?&#8217;\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"43d7-d5e4-f9fc-bf48-2a69-079c-2965-8323\">\n<p>      Lo s\u00e9, nunca me he levantado los jueves en los \u00faltimos diez a\u00f1os, de mi silla quiero decir, fuera de la cama, fuera de la cama, maldita sea, v\u00e1monos de nuevo, pero salir ciertamente no era una opci\u00f3n, m\u00e1s importante, las compras. , peque\u00f1os y grandes, simplemente los dejo resonar sobre el parquet.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"2092-7495-76aa-b992-b5fe-c7fb-a7e7-3813\">\n<p>      &#8220;Tengo que ir a Majd, consulta de barba&#8221;.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"6fad-1a40-3fe2-e8c9-329a-f1d0-42b5-9fec\">\n<p>      \u201cMazzzzzjhd.\u201d  Mi amigo Jet, que tiene la pronunciaci\u00f3n correcta.  Cuando nos conocimos me present\u00e9 como &#8220;Petor Boewalduh&#8221;.  &#8216;S\u00ed&#8217;, dijo, &#8216;s\u00ed, entiendo a qui\u00e9n te refieres, pero dices: &#8216;Pee-t\u00e8r Buu-wal-d\u00e1&#8217;.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"e30d-d190-d424-89fe-0c33-574c-a3bd-70f8\">\n<p>      Es una broma.  Pero se acab\u00f3 <i>el mundo sigue<\/i> por cierto, no es broma.  Entonces las cosas podr\u00edan haber sido muy diferentes, Matthijs podr\u00eda haberme arrastrado al suelo por el cuello, con las rodillas en la clav\u00edcula, qu\u00e9 dijiste, c\u00f3mo crees que te llamas, y luego Flats, el pelusa de buen humor.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"86ba-fe71-a6ff-a52a-ecb3-6e6d-b805-f66b\">\n<p>      Majd es mi nuevo peluquero.  Me aconsej\u00f3 que me dejara barba y segu\u00ed ciegamente su consejo, creo que porque huy\u00f3 de Siria y ahora, a sus 29 a\u00f1os, dirige una elegante peluquer\u00eda.  He desgastado a muchos peluqueros, como una mariposa, pero ahora ya est\u00e1, he conocido al verdadero, Majd.  Una tarde entr\u00e9 sin saber por qu\u00e9 con \u00e9l, ten\u00eda que ser as\u00ed.  Me estrecharon la mano, &#8220;bienvenido&#8221;, dijo Majd.  Es un chico fresco, radiante, de ojos azules y buen pelo, requisito para los peluqueros.  (Y cantantes, comparen a Elvis con Phil Collins.) (Con un dentista funciona al rev\u00e9s, nunca tome uno con &#8216;cero caries&#8217;, un &#8216;cementerio quemado&#8217; (Vestdijk, <i>guardias de marfil<\/i>) es preferible, el dentista debe haber sufrido, de lo contrario no &#8220;sabe&#8221;.  Los buenos dentistas son propensos a las amalgamas y luego retroceden cuando accidentalmente se ven en un espejo).\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"d820-e38d-9d6c-9469-b7ec-0e40-be52-a29d\">\n<p>      Majd tiene un bonito caj\u00f3n de pipas, con sillones de barbero que dan un suspiro cuando te sientas en ellos.  Despu\u00e9s de mi primer corte de pelo, dijo: &#8220;Ahora has encontrado a tu peluquero para siempre&#8221;.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"afd7-4cba-36cb-8677-a99a-d023-6a3a-e822\">\n<p>      &#8220;S\u00ed, Majd&#8221;, dije conmovido.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"5dd4-f1eb-ec2c-9803-625f-df4e-f32e-a6fb\">\n<p>      Cinco cosas elevan a Majd por encima de los peluqueros comunes y corrientes.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"474d-9c41-5cc2-477c-7db1-96a6-3f6b-0ccf\">\n<p>      1. La mano.  Nunca antes un peluquero me hab\u00eda sacudido.  Una vez m\u00e1s, para mi consulta gratuita sobre barba, obtengo una.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"8020-6478-032b-c14c-4138-188f-cb34-18a2\">\n<p>      2. Majd es sencillo.  Mir\u00f3 mi cabello, que mi novia Jet le hab\u00eda retocado desde el tratamiento corona.  &#8220;Hermoso&#8221;, dijo, &#8220;pero es un gran caos&#8221;.  &#8220;No tiene pelo&#8221;, le dije, tratando de evitarlo, &#8220;tiene el mismo largo que otro&#8221;.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"e2bf-ba78-2c93-fb22-94c4-4927-052e-7d22\">\n<p>      &#8220;Es realmente cierto&#8221;, dijo Majd.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"cee1-06dc-938c-9974-9aa2-e902-e431-8f9b\">\n<p>      3. Su poderosa visi\u00f3n de ella.  Majd inmediatamente hizo un plan, basado en toda mi mente.  Esto inclu\u00eda una barba de prueba.  &#8220;Te ver\u00e9 la barba dentro de dos semanas&#8221;, dice Majd, y te enteras de que no es holand\u00e9s de origen.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"a5d0-1181-791d-e078-185a-55af-839a-8409\">\n<p>      4. Que Majd s\u00f3lo vive en Holanda desde hace nueve a\u00f1os, la mitad de los cuales en un centro para solicitantes de asilo, y ya tiene su propia peluquer\u00eda.  Hab\u00eda huido de Siria, me dijo cuando le pregunt\u00e9.  En el centro de asilo, un holand\u00e9s daba clases de conversaci\u00f3n y un d\u00eda Majd le hizo algunos trabajos de jardiner\u00eda.  El hombre result\u00f3 ser peluquero y contrat\u00f3 a Majd.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"a247-5218-6156-9298-a1c3-0862-d11d-0caa\">\n<p>      5. Que Majd llam\u00f3 a este hombre y a su esposa su padre y su madre holandeses, en una cl\u00e1usula subordinada, para explicarme que \u00e9l tambi\u00e9n tiene padres que viven en Damasco.  &#8220;S\u00ed&#8221;, dice, &#8220;tengo cuatro padres y madres, he notado que los que hacen el bien, los conocen bien, es muy lindo darse cuenta&#8221;.\n    <\/p>\n<p><iframe id=\"sim_4021489366_1\" width=\"100%\" frameborder=\"0\" src=\"https:\/\/ims.volkskrant.nl\/optiext\/optiextension.dll?ID=MofMcIOTGz4_eO12zRZyy3_k1B2_oXSIXiWIOsaTs8K2w3C2xx7aMAL2GEFRfcLU_jR7lp0eNt4zq8CfIX&amp;guid=FE12945E-3D8B-4BB1-BC6D-DBEE9E057152&amp;frameid=sim_4021489366_1&amp;reference=\" loading=\"lazy\"><\/iframe> <\/p>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lea tambi\u00e9n<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.volkskrant.nl\/columns-van-de-dag\/vele-kappers-heb-ik-versleten-als-een-vlindertje-maar-nu-is-het-klaar-ik-heb-de-ware-ontmoet~b6bc96ea\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-23<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peter Buwalda1 de febrero de 202416:20 Entonces, hoy vamos por el mosaico, con algo de periodismo de investigaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1163453,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[191,440,72433,1567,97,45361,59455,5433,80770,267,158],"class_list":["post-1163452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-ahora","tag-como","tag-desgastado","tag-encontrado","tag-esta","tag-indicado","tag-mariposa","tag-muchos","tag-peluqueros","tag-pero","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1163452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1163452"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1163452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1163453"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1163452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1163452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1163452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}