{"id":1157649,"date":"2024-01-29T07:36:22","date_gmt":"2024-01-29T07:36:22","guid":{"rendered":"https:\/\/teknomers.com\/es\/un-escalador-britanico-sufre-multiples-lesiones-tras-caer-mas-de-30-pies-desde-el-borde-de-un-acantilado-en-espana\/"},"modified":"2024-01-29T07:36:26","modified_gmt":"2024-01-29T07:36:26","slug":"un-escalador-britanico-sufre-multiples-lesiones-tras-caer-mas-de-30-pies-desde-el-borde-de-un-acantilado-en-espana","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/un-escalador-britanico-sufre-multiples-lesiones-tras-caer-mas-de-30-pies-desde-el-borde-de-un-acantilado-en-espana\/","title":{"rendered":"Un escalador brit\u00e1nico sufre m\u00faltiples lesiones tras caer m\u00e1s de 30 pies desde el borde de un acantilado en Espa\u00f1a"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Un escalador BRIT\u00c1NICO fue trasladado en avi\u00f3n al hospital despu\u00e9s de caer m\u00e1s de 30 pies desde el borde de un acantilado en Espa\u00f1a. <\/p>\n<p>Se dice que el hombre de 80 a\u00f1os sufri\u00f3 m\u00faltiples heridas, incluidas lesiones en la cabeza, despu\u00e9s de caer cerca de la ciudad de Moraira, en la Costa Blanca.<\/p>\n<figure class=\"article__media\">\n<div class=\"article__media-img-container open-gallery\" data-index=\"47802\"><a rel=\"nofollow\" href=\"#\"><\/a><\/p>\n<p><span class=\"article__gallery-count-value\">1<\/span><\/p>\n<\/div><figcaption class=\"article__media-caption\"><span class=\"article__media-span\">Bomberos y param\u00e9dicos acudieron al lugar para ayudar al brit\u00e1nico de 80 a\u00f1os.<\/span><span class=\"article__credit\">Cr\u00e9dito: Consorcio Provincial de Bomberos de Alicante<\/span><\/figcaption><\/figure>\n<p>Una ambulancia a\u00e9rea lo traslad\u00f3 al Hospital Doctor Balmis de Alicante tras ser estabilizado en el lugar.<\/p>\n<p>La alarma se dio ayer poco antes de las 2 de la tarde en el pueblo de Murla, a 30 minutos en coche hacia el interior desde Moraira. <\/p>\n<p>Se llam\u00f3 a bomberos, param\u00e9dicos y ambulancia a\u00e9rea para ayudar en la respuesta de emergencia. <\/p>\n<p>Las im\u00e1genes mostraban a los rescatistas rodeando al pensionista herido en la ladera de un acantilado. <\/p>\n<p>No qued\u00f3 claro de inmediato si el herido hab\u00eda estado con alguien m\u00e1s en ese momento.<\/p>\n<p>Y no se sabe cu\u00e1l es su condici\u00f3n actual.<\/p>\n<p>Un portavoz de los bomberos de Alicante dijo: \u201cNuestro equipo de rescate ha ayudado en el rescate de un escalador brit\u00e1nico de 80 a\u00f1os en Murla.<\/p>\n<p>\u201cSufri\u00f3 m\u00faltiples lesiones tras una ca\u00edda de 32 pies.<\/p>\n<p>&#8220;Lo llevaron a un parque de bomberos de D\u00e9nia donde lo esperaba una ambulancia para trasladarlo al hospital&#8221;.<\/p>\n<p>Se produce despu\u00e9s de que un escalador brit\u00e1nico cayera m\u00e1s de 300 pies hasta su muerte en las monta\u00f1as de Austria.<\/p>\n<p>Malcolm McDonald, de 42 a\u00f1os, fue encontrado muerto despu\u00e9s de caer de la famosa &#8220;escalera al cielo&#8221; en las monta\u00f1as de Dachstein en septiembre.<\/p>\n<p>El gerente del comercio hab\u00eda viajado hasta el campo cerca de Salzburgo para emprender la ruta de la v\u00eda ferrata Donnerkogel.<\/p>\n<p>La v\u00eda ferrata, que significa &#8220;v\u00eda de hierro&#8221;, consta de una enorme escalera de metal colgada entre dos picos de monta\u00f1a.<\/p>\n<p>Compuesta por un tramo vertiginosamente largo de 130 pies de pelda\u00f1os, la escalera se encuentra a casi 300 pies sobre el suelo.<\/p>\n<p>Malcolm, de Irlanda del Norte, estaba escalando solo cuando ocurri\u00f3 el desastre el 12 de septiembre.<\/p>\n<p>Los servicios de emergencia acudieron al lugar, incluidos dos tripulantes de helic\u00f3pteros, pero no pudieron salvarlo.<\/p>\n<p>Su cuerpo fue recuperado del profundo barranco debajo de la escalera despu\u00e9s de la horrorosa ca\u00edda.<\/p>\n<p>La desconsolada familia de Malcom lo describi\u00f3 como &#8220;amable y cari\u00f1oso&#8221; en un emotivo homenaje.<a rel=\"nofollow noopener\" href=\"https:\/\/www.thesun.co.uk\/news\/24042232\/brit-death-ladder-austrian-mountain-tributes-paid\/#\" target=\"_blank\"><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thesun.co.uk\/news\/25565710\/brit-climber-injured-plunging-cliff-edge-spain\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-58<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un escalador BRIT\u00c1NICO fue trasladado en avi\u00f3n al hospital despu\u00e9s de caer m\u00e1s de 30 pies desde el<\/p>\n","protected":false},"author":1,"featured_media":1157650,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[46854,10212,850,6731,2479,66059,1076,5822,16,7608,11509,212951,13712,720],"class_list":["post-1157649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-acantilado","tag-borde","tag-britanico","tag-caer","tag-desde","tag-escalador","tag-espana","tag-lesiones","tag-mas","tag-multiples","tag-pies","tag-seccion-noticiasnoticias-del-mundo","tag-sufre","tag-tras"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1157649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1157649"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1157649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1157650"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1157649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1157649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1157649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}