{"id":1152325,"date":"2024-01-25T16:32:24","date_gmt":"2024-01-25T16:32:24","guid":{"rendered":"https:\/\/teknomers.com\/es\/roundup-acciones-de-nueva-york-beneficios-sin-nuevos-records\/"},"modified":"2024-01-25T16:32:28","modified_gmt":"2024-01-25T16:32:28","slug":"roundup-acciones-de-nueva-york-beneficios-sin-nuevos-records","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/roundup-acciones-de-nueva-york-beneficios-sin-nuevos-records\/","title":{"rendered":"ROUNDUP\/Acciones de Nueva York: Beneficios sin nuevos r\u00e9cords"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>NUEVA YORK (dpa-AFX) &#8211; Los mercados burs\u00e1tiles estadounidenses obtuvieron ganancias el jueves a pesar de las noticias corporativas y econ\u00f3micas mixtas.  Sin embargo, el \u00edndice l\u00edder Dow Jones Industrial (Dow Jones 30 Industrial), que se hab\u00eda debilitado la v\u00edspera, volvi\u00f3 a quedar por detr\u00e1s de los dem\u00e1s \u00edndices con un aumento del 0,12 por ciento, hasta 37.852,61 puntos.  Las cifras positivas de IBM y Dow Inc (Dow) se vieron compensadas por nuevos titulares negativos de Boeing.<\/p>\n<p>El S&#038;P 500 de todo el mercado avanz\u00f3 otro 0,35 por ciento hasta 4.885,78 puntos.  En el \u00edndice de selecci\u00f3n tecnol\u00f3gica NASDAQ 100, a pesar de las decepcionantes cifras de Tesla, el precio subi\u00f3 un 0,46 por ciento hasta los 17.580,31 puntos.  Sin embargo, los dos \u00edndices que alcanzaron m\u00e1ximos hist\u00f3ricos el martes no pudieron establecer nuevos r\u00e9cords.<!-- sh_cad_2 --><\/p>\n<p>La econom\u00eda estadounidense creci\u00f3 m\u00e1s de lo esperado en el \u00faltimo trimestre de 2023.  Pero las ventas de viviendas nuevas no alcanzaron las previsiones en diciembre a pesar de un aumento significativo, mientras que los pedidos de bienes duraderos se estancaron sorprendentemente (los analistas hab\u00edan esperado un aumento).  Adem\u00e1s, el n\u00famero de solicitudes iniciales semanales de asistencia por desempleo aument\u00f3 m\u00e1s de lo esperado, pero se mantiene en un nivel bastante bajo.<\/p>\n<p>Tambi\u00e9n hubo luces y sombras por parte de las empresas.  Las acciones de Tesla terminaron su reciente consolidaci\u00f3n y cayeron un 10,9 por ciento como las de peor desempe\u00f1o en el Nasdaq 100.  Estaban en su nivel m\u00e1s bajo desde mayo del a\u00f1o pasado.  El fabricante de coches el\u00e9ctricos decepcion\u00f3 tanto con sus cifras trimestrales, que mostraron una desaceleraci\u00f3n del crecimiento, como con unas perspectivas de negocio sombr\u00edas.<!-- sh_cad_4 --><\/p>\n<p>Las acciones de Boeing fueron las que m\u00e1s perdieron en el Dow Jones, con un -7 por ciento.  Las turbulencias que rodean al modelo de avi\u00f3n 737-9 Max volvieron a pesar sobre los \u00e1nimos: tras un peligroso incidente, los aviones de este tipo, que desde entonces han sido parados, pronto podr\u00e1n volver a volar.  Sin embargo, la autoridad aeron\u00e1utica estadounidense FAA no quiere aprobar por el momento ninguna ampliaci\u00f3n adicional de la producci\u00f3n de todos los modelos del 737 Max.  En respuesta, Bank of America baj\u00f3 su calificaci\u00f3n de compra de Boeing.<\/p>\n<p>En la aseguradora de salud Humana, unas p\u00e9rdidas trimestrales que aumentaron dr\u00e1sticamente a\u00f1o tras a\u00f1o y unas perspectivas de beneficios decepcionantes provocaron que los precios de las acciones cayeran m\u00e1s de un 14 por ciento hasta su nivel m\u00e1s bajo desde la primavera de 2020.<!-- sh_cad_6 --><\/p>\n<p>Por el contrario, las acciones de la empresa inform\u00e1tica IBM subieron un 12,5 por ciento tras unas perspectivas de crecimiento sorprendentemente s\u00f3lidas y el anuncio de recortes de empleos.  Esto signific\u00f3 que ocuparon el primer lugar en el \u00edndice principal de Estados Unidos y fueron m\u00e1s caros de lo que hab\u00edan sido en m\u00e1s de diez a\u00f1os.  Detr\u00e1s de ellos, las acciones de la empresa qu\u00edmica Dow ganaron un 2,1 por ciento a pesar de cifras y objetivos moderados.<!-- sh_cad_7 --><\/p>\n<p>Unas ventas anuales r\u00e9cord, un fuerte aumento de los beneficios y unas perspectivas optimistas llevaron a la aerol\u00ednea American Airlines a aumentar el precio de sus acciones un 7,2 por ciento.\/gl\/he<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.finanzen.net\/nachricht\/aktien\/roundup-aktien-new-york-gewinne-ohne-neue-rekorde-13202819\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-28<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK (dpa-AFX) &#8211; Los mercados burs\u00e1tiles estadounidenses obtuvieron ganancias el jueves a pesar de las noticias corporativas<\/p>\n","protected":false},"author":1,"featured_media":1014915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[4090,212,2431,12944,93549,1030,5147],"class_list":["post-1152325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzas","tag-beneficios","tag-nueva","tag-nuevos","tag-records","tag-roundupacciones","tag-sin","tag-york"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1152325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1152325"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1152325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1014915"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1152325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1152325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1152325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}