{"id":1145539,"date":"2024-01-21T12:51:24","date_gmt":"2024-01-21T12:51:24","guid":{"rendered":"https:\/\/teknomers.com\/es\/guidesi-lombardia-es-un-modelo-verde-para-las-regiones-quimicas-de-la-ue\/"},"modified":"2024-01-21T12:51:28","modified_gmt":"2024-01-21T12:51:28","slug":"guidesi-lombardia-es-un-modelo-verde-para-las-regiones-quimicas-de-la-ue","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/guidesi-lombardia-es-un-modelo-verde-para-las-regiones-quimicas-de-la-ue\/","title":{"rendered":"Guidesi: \u00abLombard\u00eda es un modelo verde para las regiones qu\u00edmicas de la UE\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><button class=\"aembed-audio \" type=\"button\"><span class=\"icon icon-listen-small icon--status\"\/>Escuche la versi\u00f3n en audio del art\u00edculo.<\/button><\/p>\n<p class=\"atext\">Contin\u00faa la actividad de &#8220;lobby europeo&#8221; que lleva a cabo la Regi\u00f3n de Lombard\u00eda.  Y ahora hay un nuevo grupo de inter\u00e9s que explotar: regiones con muchas empresas involucradas en el sector qu\u00edmico.  El consejero de desarrollo econ\u00f3mico de Lombard\u00eda, Guido Guidesi, acaba de asumir la presidencia.<\/p>\n<p class=\"atext\"><b>Concejal, no s\u00f3lo de automoci\u00f3n o temas relacionados con la sostenibilidad.  Ahora Lombard\u00eda tambi\u00e9n representa los intereses de las regiones con una presencia masiva de empresas qu\u00edmicas.  \u00bfPor qu\u00e9 aceptaste esta nueva batalla?<\/b><\/p>\n<p class=\"atext\">Fui elegido por esta asociaci\u00f3n que existe desde hace 20 a\u00f1os.  Me postul\u00e9, obviamente representando a mi regi\u00f3n, con un programa que evidentemente logr\u00f3 generar confianza.  Quienes votaron por m\u00ed fueron regiones &#8220;hist\u00f3ricas&#8221; de Europa, como Sajonia, pero tambi\u00e9n regiones que han entrado m\u00e1s recientemente en Europa, como algunas regiones polacas y parte de la Rep\u00fablica Checa. Somos 14 en total, en Italia hay son Lombard\u00eda y Emilia Romagna.<\/p>\n<p class=\"atext\"><b>\u00bfY cu\u00e1l es el programa que uni\u00f3 todos estos territorios diferentes?<\/b><\/p>\n<div class=\"acor acor--mkt\">\n<div class=\"row row--dotted\">\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/lab24.ilsole24ore.com\/campi-flegrei-vulcano\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><\/figure>\n<p><\/a><\/div>\n<div class=\"col-md-6\"><a rel=\"nofollow noopener\" class=\"aprev aprev--acor aprev--acor-small aprev--shline\" href=\"https:\/\/tariffe.ilsole24ore.com\/\" target=\"_blank\"><\/p>\n<figure class=\"aprev-img\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/10\/Salario-minimo-primer-documento-tecnico-de-CNEL-aprobado.png\" alt=\"Saber m\u00e1s\"\/><\/figure>\n<p><\/a><\/div>\n<\/div>\n<\/div>\n<p class=\"atext\">B\u00e1sicamente, el hecho compartido de que en los \u00faltimos a\u00f1os se ha prestado poca atenci\u00f3n a la qu\u00edmica.  Todav\u00eda se suele asociar con algo peligroso o insostenible, existen prejuicios.  Pero ante todo la qu\u00edmica se basa ahora en proyectos &#8220;verdes&#8221;, prestando gran atenci\u00f3n a la transici\u00f3n energ\u00e9tica.  La qu\u00edmica es la protagonista de la transici\u00f3n medioambiental, como lo demuestra el trabajo que est\u00e1 realizando Eni, o como explican los datos de Farmindustria.  Adem\u00e1s, es la base de muchos sectores que ni siquiera podemos imaginar, desde la construcci\u00f3n, pasando por los productos farmac\u00e9uticos, pasando por los textiles, hasta la recuperaci\u00f3n de pl\u00e1stico.  Y renunciar a \u00e9l significa depender cada vez m\u00e1s del exterior, y por extranjero me refiero a pa\u00edses fuera de Europa, de los que la pandemia ha demostrado que debemos liberarnos en la medida de lo posible.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ilsole24ore.com\/art\/guidesi-la-lombardia-modello-green-le-regioni-ue-chimica-AFYGEnOC\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-11<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escuche la versi\u00f3n en audio del art\u00edculo. Contin\u00faa la actividad de &#8220;lobby europeo&#8221; que lleva a cabo la<\/p>\n","protected":false},"author":1,"featured_media":1145540,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[215091,246,1181,2832,18,22951,1814,106],"class_list":["post-1145539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-guidesi","tag-las","tag-lombardia","tag-modelo","tag-para","tag-quimicas","tag-regiones","tag-verde"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1145539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1145539"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1145539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1145540"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1145539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1145539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1145539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}