{"id":1145317,"date":"2024-01-21T09:32:37","date_gmt":"2024-01-21T09:32:37","guid":{"rendered":"https:\/\/teknomers.com\/es\/campeonato-de-europa-de-balonmano-el-entrenador-del-dhb-gislason-se-divierte-esto-es-peculiar\/"},"modified":"2024-01-21T09:32:43","modified_gmt":"2024-01-21T09:32:43","slug":"campeonato-de-europa-de-balonmano-el-entrenador-del-dhb-gislason-se-divierte-esto-es-peculiar","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/campeonato-de-europa-de-balonmano-el-entrenador-del-dhb-gislason-se-divierte-esto-es-peculiar\/","title":{"rendered":"Campeonato de Europa de balonmano |  El entrenador del DHB, G\u00edslason, se divierte: &quot;\u00a1Esto es peculiar!&quot;"},"content":{"rendered":"\n<div data-testid=\"StreamLayout.Stream\">\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-170a2tk\">Despu\u00e9s del empate contra Austria en la ronda principal del Campeonato de Europa, el \u00e1nimo en el campo alem\u00e1n estaba algo deprimido.  Pero el seleccionador nacional Alfred G\u00edslason todav\u00eda provoc\u00f3 risas.<\/p>\n<\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">La selecci\u00f3n alemana de balonmano no imagin\u00f3 que ser\u00eda as\u00ed.  Debido al empate 22:22 contra Austria en el segundo partido de la ronda principal, el equipo DHB ya no tiene en sus manos las semifinales del Campeonato de Europa local.<\/p>\n<\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">Sobre todo, una d\u00e9bil ofensiva impidi\u00f3 la victoria contra el equipo sorpresa de la Rep\u00fablica Alpina.  Los jugadores y el seleccionador nacional, Alfred G\u00edslason, se mostraron igualmente descontentos tras el partido.<\/p>\n<\/div>\n<p><h3 class=\"css-m8kmtl\" id=\"gislason-und-die-frage-nach-dem-risiko\">G\u00edslason y la cuesti\u00f3n del riesgo<\/h3>\n<\/p>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">Al final de la rueda de prensa posterior al partido, G\u00edslason provoc\u00f3 una carcajada.  El t\u00e9cnico dio descanso al mediapunta Juri Knorr en el primer cuarto de hora ante Austria y convoc\u00f3 a Philipp Weber.  Cuando se le pregunt\u00f3 si quer\u00eda volver a minimizar este \u201criesgo\u201d en los pr\u00f3ximos partidos, reaccion\u00f3 con sorpresa.<\/p>\n<\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p><span class=\"css-1llyqnr\" aria-label=\"Bezeichnung mit Videotitel\">Video<\/span><span>  | <!-- -->El partido de DHB contra Austria fue muy emocionante<\/span><\/p>\n<figure class=\"css-s38f4x\"\/><small class=\"css-odmyy6\">Fuente: ARD\/ZDF<\/small><\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">&#8220;Eso es un poco extra\u00f1o&#8221;, dijo G\u00edslason.  &#8220;Si no cambio, surgir\u00e1 la pregunta de por qu\u00e9 no comenc\u00e9 con fulano de tal y por qu\u00e9 s\u00f3lo juega Knorr. Entonces le dar\u00e9 a Knorr un poco m\u00e1s de tiempo porque ya ten\u00eda mucho fr\u00edo y entonces hay riesgo.&#8221;<\/p>\n<\/div>\n<p><h3 class=\"css-m8kmtl\" id=\"kritik-an-zu-wenig-rotation-gegen-frankreich\">Cr\u00edticas a Francia por una rotaci\u00f3n demasiado escasa<\/h3>\n<\/p>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">G\u00edslason se refer\u00eda a las preguntas sobre la derrota en la ronda preliminar ante Francia.  All\u00ed apenas dio descanso al primer guardia, por lo que los jugadores parecieron cansados \u200b\u200ben la fase final.  Posteriormente hubo algunas cr\u00edticas a sus acciones.  Contra Islandia y Austria cambi\u00f3 a\u00fan m\u00e1s y ahora tuvo que afrontar la cuesti\u00f3n del riesgo.<\/p>\n<\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">\u201c\u00a1Por \u200b\u200bsupuesto que existe un riesgo!\u201d, afirm\u00f3 G\u00edslason en la rueda de prensa.  &#8220;Pero no hay riesgo si quien viene por \u00e9l juega bien&#8221;, afirm\u00f3 el seleccionador nacional.  Dirigi\u00e9ndose a los periodistas, simplemente dijo con una sonrisa: &#8220;Tienen que escribir algo. Lo hago seg\u00fan mi cabeza y mis sentimientos. Quiz\u00e1s me equivoque, pero a veces tengo raz\u00f3n&#8221;.<\/p>\n<\/div>\n<div class=\"css-wl96nl\" data-testid=\"StageLayout.StreamItem\">\n<p class=\"css-wzramg\">As\u00ed que despu\u00e9s de un partido frustrante y una pregunta cuyo contenido obviamente no le gust\u00f3, G\u00edslason todav\u00eda provoc\u00f3 risas en la sala de prensa.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.t-online.de\/sport\/mehr-sport\/handball\/handball-em\/id_100325880\/handball-em-dhb-coach-gislason-amuesiert-das-ist-eigenartig-.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-10<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s del empate contra Austria en la ronda principal del Campeonato de Europa, el \u00e1nimo en el campo<\/p>\n","protected":false},"author":1,"featured_media":1145318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[211590,626,1226,1914,38,16091,57923,752,348,1714,32274,226613,3155,18800,138189],"class_list":["post-1145317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-alfredo-gislason","tag-austria","tag-balonmano","tag-campeonato","tag-del","tag-dhb","tag-divierte","tag-entrenador","tag-europa","tag-francia","tag-gislason","tag-peculiarquot","tag-quotesto","tag-seleccionador-nacional","tag-yuri-knorr"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1145317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1145317"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1145317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1145318"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1145317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1145317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1145317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}