{"id":1144532,"date":"2024-01-20T18:32:38","date_gmt":"2024-01-20T18:32:38","guid":{"rendered":"https:\/\/teknomers.com\/es\/una-pancarta-de-stuttgart-casi-fue-demolida-en-bochum\/"},"modified":"2024-01-20T18:32:43","modified_gmt":"2024-01-20T18:32:43","slug":"una-pancarta-de-stuttgart-casi-fue-demolida-en-bochum","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/una-pancarta-de-stuttgart-casi-fue-demolida-en-bochum\/","title":{"rendered":"Una pancarta de Stuttgart casi fue demolida en Bochum"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 20 de enero de 2024 19:30<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong><strong>El partido de la Bundesliga entre el VfL Bochum y el VfB Stuttgart del s\u00e1bado (20 de enero de 2024) comenz\u00f3 de nuevo con casi una hora de retraso, a las 17:20, con el marcador 0-0 al descanso.  El <\/strong><strong>El VfL gan\u00f3 el partido 1-0<\/strong><strong>.<\/strong><\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Los aficionados del VfB colgaron dos grandes pancartas en la valla del barrio de Stuttgart que, seg\u00fan las autoridades reguladoras, bloqueaban las v\u00edas de escape y de rescate.  El \u00e1rbitro Bastian Dankert inicialmente no pit\u00f3 durante la segunda mitad del partido.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Los directivos del Stuttgart intentaron influir en los aficionados del VfB en la valla.  Al principio colgaron una pancarta de protesta contra la decisi\u00f3n de los inversores del DFL.<\/p>\n<h2 id=\"Feuerwehr-und-Ordnungsamt-beteiligt\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Intervienen los bomberos y la oficina de orden p\u00fablico<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Sin embargo, seg\u00fan los medios de comunicaci\u00f3n, los aficionados visitantes se negaron a quitar la pancarta que colgaba debajo con la leyenda &#8220;Ultras Cannstatter Wasen&#8221;, que, seg\u00fan las autoridades, bloqueaba una puerta de escape hacia el c\u00e9sped.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Junto con los bomberos y la oficina de orden p\u00fablico se busc\u00f3 una salida hasta que finalmente se colg\u00f3 la pancarta para que se pudiera abrir el port\u00f3n.  Dankert volvi\u00f3 a pitar el partido. <\/p>\n<h2 id=\"Undav-verteidigt-Stuttgart-Fans\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Undav defiende a los aficionados del Stuttgart<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El delantero del VfB Deniz Undav no considera que los aficionados del Stuttgart sean los culpables de la larga interrupci\u00f3n. <cite>&#8220;No entiendo por qu\u00e9 la gente lo convierte en un problema. Nadie lo entendi\u00f3 tampoco&#8221;<\/cite>dice Undav: <cite>&#8220;Por supuesto, todos estaban un poco enojados. Se pod\u00eda abrir la puerta, yo estaba all\u00ed. No hay culpa para los fans&#8221;.<\/cite> Undav contin\u00faa: <cite>&#8220;Obviamente es una l\u00e1stima que hayamos tenido que esperar tanto tiempo afuera, con tanto fr\u00edo&#8221;.<\/cite> <\/p>\n<div class=\"copytext__audio columns twelve m-ten  m-offset-one l-eight  l-offset-two\">\n<div class=\"copytext__audio__info\">\n<p>Espect\u00e1culo deportivo, 20 de enero de 2024 18:00 horas<\/p>\n<\/p><\/div>\n<\/div>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El director deportivo del Bochum, Marc Lettau, afirm\u00f3 que los aficionados del Stuttgart fueron informados de los problemas. <cite>&#8220;Siempre indicamos por escrito que los bomberos tienen las mismas expectativas cuando se trata de colgar pancartas&#8221;.<\/cite>dijo el hombre de 37 a\u00f1os. <cite>&#8220;Al final hay que ce\u00f1irse a ello. Eso es obviamente molesto&#8221;.<\/cite><\/p>\n<div class=\"copytext__audio columns twelve m-ten  m-offset-one l-eight  l-offset-two\">\n<div class=\"copytext__audio__info\">\n<p>Espect\u00e1culo deportivo, 20 de enero de 2024 18:00 horas<\/p>\n<\/p><\/div>\n<\/div>\n<h2 id=\"Aehnlicher-Vorfall-schon-in-Moenchengladbach\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Incidente similar ya en <span class=\"hyphenate\">M\u00f6nchengladbach<\/span><\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\"><a rel=\"nofollow noopener\" href=\"https:\/\/www.reviersport.de\/fussball\/1bundesliga\/a601038---bundesliga-banner-stuttgart-fans-verzoegert-zweite-halbzeit-bochum.html\" title=\"Laut &amp;quot;Revier-Sport&amp;quot;\" class=\"textlink--extern\" target=\"_blank\">Seg\u00fan \u201cRevier-Sport\u201d<\/a> Un problema similar se produjo a finales de septiembre, cuando el Borussia M\u00f6nchengladbach visit\u00f3 Bochum.  En ese momento, los Gladbacher simplemente quitaron las banderas de la valla despu\u00e9s de diez minutos de discusi\u00f3n.<\/p>\n<div class=\"columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"backlink\">\n                                        <a rel=\"nofollow noopener\" class=\"backlink__link\" href=\"https:\/\/www1.wdr.de\/sport\/fussball\/erste-bundesliga\/banner-sorgt-in-bochum-fuer-verzoegerung-100.html\" target=\"_blank\"><\/p>\n<div class=\"backlink__img-wrapper\"><\/div>\n<p>                                        <\/a>\n                                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/regional\/wdr\/wdr-stuttgarter-banner-sorgte-fuer-beinahe-abbruch-in-bochum-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 20 de enero de 2024 19:30 El partido de la Bundesliga entre el VfL Bochum<\/p>\n","protected":false},"author":1,"featured_media":1144533,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1119,2432,42437,244,20812,3723,158,76613],"class_list":["post-1144532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-bochum","tag-casi","tag-demolida","tag-fue","tag-pancarta","tag-stuttgart","tag-una","tag-wdr"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1144532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1144532"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1144532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1144533"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1144532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1144532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1144532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}