{"id":1132716,"date":"2024-01-13T07:44:35","date_gmt":"2024-01-13T07:44:35","guid":{"rendered":"https:\/\/teknomers.com\/es\/palabras-de-icardi-de-ilkin-aydin-esa-fotografia\/"},"modified":"2024-01-13T07:44:39","modified_gmt":"2024-01-13T07:44:39","slug":"palabras-de-icardi-de-ilkin-aydin-esa-fotografia","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/palabras-de-icardi-de-ilkin-aydin-esa-fotografia\/","title":{"rendered":"\u00a1Palabras de Icardi de \u0130lkin Ayd\u0131n!  Esa fotograf\u00eda&#8230;"},"content":{"rendered":"\n<div id=\"\">&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>\u0130lkin Ayd\u0131n, el exitoso jugador de voleibol de la Selecci\u00f3n Nacional y del Galatasaray, habl\u00f3 sobre la famosa pose que hizo con Icardi.  Ayd\u0131n, que concedi\u00f3 una entrevista a H\u00fcrriyet, dijo:<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8211; Hiciste muy feliz a toda Turqu\u00eda el verano pasado.  \u00bfEst\u00e1s emocionado por los Juegos Ol\u00edmpicos?<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Estoy muy emocionado.  Estoy ilusionado desde que acab\u00f3 la temporada de la selecci\u00f3n el a\u00f1o pasado.  Probablemente estar\u00e9 muy emocionado hasta el comienzo de los Juegos Ol\u00edmpicos.  Somos conscientes de que hay expectaci\u00f3n.  Espero que haya una temporada saludable con la selecci\u00f3n nacional y sin lesiones.  La idea de por qu\u00e9 no deber\u00edamos ser campeones en ambos torneos es sorprendente.  Nuestros objetivos van en esa direcci\u00f3n, veamos.  El campeonato ol\u00edmpico es el sue\u00f1o de todos los deportistas.  No es algo que no pueda suceder.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8211; Recientemente asististe a una ceremonia de premiaci\u00f3n.  Su discurso fue muy apreciado.  Pero se habl\u00f3 m\u00e1s de la pose que tom\u00f3 con Mauro Icardi luego de la ceremonia.  \u00bfC\u00f3mo se desarroll\u00f3?  \u00bfPodemos saber de usted?<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Ahora que fui all\u00ed con esa pajarita, c\u00f3mo se habl\u00f3 m\u00e1s de nuestra foto con Icardi, me sent\u00ed un poco ofendido.  Bromas aparte, fue una noche muy agradable para m\u00ed.  Est\u00e1bamos sentados espalda con espalda con Icardi.  De repente, empezaron a llegar muchas notificaciones a mi tel\u00e9fono.  Lo abr\u00ed y la gente escrib\u00eda sobre la foto de Icardi-\u0130lkin.  Entonces dije que no ofender\u00eda a nadie.  Cuando me lo encontr\u00e9 en el escenario, inmediatamente le dije que estaba jugando en el Galatasaray.  Y \u00e9l dijo: &#8216;Lo s\u00e9&#8217;.  Al principio esto me sorprendi\u00f3.  \u00c9l pos\u00f3 normalmente mientras se tomaba la foto, yo dije: &#8216;No, todos est\u00e1n esperando que posemos para la celebraci\u00f3n del gol&#8217;.  As\u00ed fue como se desarroll\u00f3. <\/p>\n<p>&#13;<br \/>\n&#13;\n                <\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/galatasaray\/2024\/01\/13\/ilkin-aydindan-icardi-sozleri-o-fotograf\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; &#13; &#13; \u0130lkin Ayd\u0131n, el exitoso jugador de voleibol de la Selecci\u00f3n Nacional y del Galatasaray, habl\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1132717,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[34899,4337,31583,2005,38092,222795,14616,201159,3131,16090,5854],"class_list":["post-1132716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-aydin","tag-esa","tag-fotografia","tag-galatasaray","tag-icardi","tag-ilkin","tag-ilkin-aydin","tag-mauroicardi","tag-palabras","tag-seleccion-nacional","tag-turquia"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1132716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1132716"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1132716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1132717"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1132716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1132716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1132716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}