{"id":1104279,"date":"2023-12-23T05:27:21","date_gmt":"2023-12-23T05:27:21","guid":{"rendered":"https:\/\/teknomers.com\/es\/riza-calimbay-que-se-separo-del-besiktas-hizo-declaraciones\/"},"modified":"2023-12-23T05:27:25","modified_gmt":"2023-12-23T05:27:25","slug":"riza-calimbay-que-se-separo-del-besiktas-hizo-declaraciones","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/riza-calimbay-que-se-separo-del-besiktas-hizo-declaraciones\/","title":{"rendered":"\u00a1R\u0131za \u00c7al\u0131mbay, que se separ\u00f3 del Be\u015fikta\u015f, hizo declaraciones!"},"content":{"rendered":"\n<div id=\"\">&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n<p>En la semana 17 de la Superliga Trendyol, el Be\u015fikta\u015f fue derrotado por el Corendon Alanyaspor por 3-1.  Despu\u00e9s de esta pelea, los blanquinegros se separaron del entrenador R\u0131za \u00c7al\u0131mbay.  El experimentado t\u00e9cnico hizo declaraciones en la rueda de prensa tras este acontecimiento.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong><span style=\"background-color:#FFFF00\">LO M\u00c1S DESTACADO DE LAS PALABRAS DE RIZA \u00c7ALIMBAY SON LOS SIGUIENTES:<\/span><\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Somos de Be\u015fikta\u015f.  No fui a ning\u00fan otro club, s\u00f3lo vest\u00ed la camiseta del Be\u015fikta\u015f.  Entrenamos por un corto tiempo.  Sucedieron cosas memorables.  Dar\u00e9 respuestas breves.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Ahmet Nur \u00c7ebi dijo: &#8220;El Be\u015fikta\u015f lo necesita, ven&#8221;.  Hablamos durante 3 semanas hasta el congreso.  No hablamos de dinero.  Lo que \u00e9l quer\u00eda eran 3 partidos de todos modos, esos 3 partidos los pasamos de la mejor manera posible.  Me reun\u00ed con Samet Aybaba y Mehmet \u00d6zdilek.  Di informaci\u00f3n sobre el equipo.  Hasan Arat y Serdal Adal\u0131 dijeron: &#8220;Continuaremos con R\u0131za Hoca&#8221;.  Luego continuamos la misi\u00f3n.  Hubo un proceso, lo supe m\u00e1s tarde.  El contrato que nos hizo Ahmet Nur \u00c7ebi era hasta junio de 2024.  Hab\u00eda una cl\u00e1usula que dec\u00eda &#8220;la nueva administraci\u00f3n podr\u00e1 ponerle fin en un plazo de 15 d\u00edas&#8221;.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NUNCA CONOCEMOS A HASAN ARAT&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Nos alegramos cuando vinieron el hermano Samet y Feyyaz.  Jugamos juntos.  Luego se dijo que el contrato terminar\u00eda el d\u00eda 27.  Una de las cosas que me entristece es que est\u00e1n saliendo tantas cosas;  &#8216;R\u0131za \u00c7al\u0131mbay es nuestro entrenador.  No exist\u00eda tal cosa como &#8220;llegaremos hasta el final&#8221;.  Tevfik Yamant\u00fcrk dijo a la junta directiva: &#8220;Deber\u00eda quedarse un a\u00f1o y medio&#8221;, pero Hasan Arat no respondi\u00f3 nada.  Otra cosa que me entristece es que nunca hablamos ni nos reunimos con Hasan Arat.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO SOY ENTRENADOR PARA 2 PARTIDOS&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Quer\u00edan ampliar mi contrato por 2 partidos m\u00e1s.  No soy un entrenador de 2 partidos, soy un muy buen entrenador y alguien que tiene \u00e9xito.  No vengo all\u00ed durante 2 d\u00edas o 1 mes.  Asum\u00ed la responsabilidad s\u00f3lo porque el Be\u015fikta\u015f la necesitaba.  El equipo que compramos fue eliminado de la liga y eliminado de Europa&#8230; Lo solucionamos.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;LE ENVIARON PAPEL A MI ABOGADO&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El hermano Samet y Feyyaz quer\u00edan que continuara durante 2 partidos.  Luego dijeron que nos presentar\u00edamos para el contrato.  Confi\u00e9 en ellos y fich\u00e9 por 2 partidos.  Mientras iba al partido de Lugano, le enviaron un papel a mi abogado diciendo: &#8216;Si no firmas, rescindiremos el contrato&#8217;.  No le dije esto a nadie.  Estoy realmente triste.  No vine por dinero.  Ahmet Nur \u00c7ebi ya les ha allanado el camino en el contrato.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO HICE LO QUE DIJERON&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Anoche llegu\u00e9 a las instalaciones despu\u00e9s del partido.  Dijeron que vendr\u00e1n Feyyaz, el hermano Samet y otro gerente.  El hermano Feyyaz y Samet no vinieron.  Vinieron 3 gerentes.  Lo que quer\u00edan era separarse por la noche.  &#8216;Es la 1 de la madrugada, no lo har\u00e9.  Le dije: &#8216;Ma\u00f1ana dar\u00e9 una conferencia de prensa y renunciar\u00e9&#8217;.  Insistieron, no acept\u00e9.  Anunciaron que rompimos inmediatamente.  Entonces no hice lo que me dijeron, lo hice a mi manera.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;SE EST\u00c1N TOMANDO DECISIONES SIN OBTENER MI OPINI\u00d3N&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El hermano de Samet dijo: &#8220;Excluimos a cinco jugadores del equipo&#8221;.  \u00c9l dice &#8220;nosotros&#8221;, entonces yo no existo.  Le dije: &#8216;Buena suerte&#8217;.  Entonces el incidente ha terminado.  Esta decisi\u00f3n se toma sin mi opini\u00f3n.  Anoche se lo dije a los administradores y dijeron: &#8216;Samet Hodjas tom\u00f3 esa decisi\u00f3n&#8217;.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>Si 5 jugadores fueron excluidos de la plantilla sin tu conocimiento, \u00bfpor qu\u00e9 no dimitiste de tu puesto?<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Entre los 5 excluidos de la plantilla, hab\u00eda nombres que pens\u00e9 que tambi\u00e9n quedar\u00edan fuera de la plantilla.  Hubo jugadores con los que tuvimos problemas.  Nunca me han excluido de ning\u00fan club.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;GEDSON, MIS PALABRAS FUERON MAL ENTENDIDAS&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Antes del partido, el m\u00e9dico dijo: &#8220;Gedson puede jugar&#8221;.  Entonces llam\u00e9 a Gedson y le pregunt\u00e9 sobre su situaci\u00f3n.  &#8216;Jugu\u00e9 lesionado 3 veces antes de esto y volvi\u00f3 a aparecer.  &#8220;No jugar\u00e9 esta vez&#8221;, dijo.  Luego le expliqu\u00e9 la situaci\u00f3n al hermano Samet y le dije: &#8216;Puedes hablar si quieres&#8217;.  \u00c9l le dijo lo mismo a ella.  Ten\u00eda miedo de volver a lastimarse.  Mis palabras fueron mal entendidas.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NUNCA ME ARREPIENTO, NO ME ARREPENT\u00cd&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Soy de Be\u015fikta\u015f.  No fui a otros equipos y volv\u00ed como los dem\u00e1s.  No tengo ning\u00fan resentimiento hacia la comunidad.  Yo tambi\u00e9n tengo experiencia, puedo ignorar algunas cosas.  La pasi\u00f3n del Be\u015fikta\u015f es genial para nosotros.  Be\u015fikta\u015f tiene una postura, esa es mi postura.  \u00a1Pero algunos no se detuvieron!  Nunca me arrepiento.  Ahora, si quisieran, volver\u00eda a ir, pero si se comportan as\u00ed, no ir\u00e9.  Se supon\u00eda que algunas cosas no deb\u00edan suceder.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO PODEMOS ENCONTRAR UN TAP\u00d3N&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>&#8220;\u00bfPor qu\u00e9 no me llamaste antes?&#8221;, a Ahmet Nur \u00c7ebi.  Yo dije.  E Si hubiera venido al principio de la temporada, Be\u015fikta\u015f habr\u00eda sido muy diferente.  Lo m\u00e1s importante es el per\u00edodo de preparaci\u00f3n.  Hay al menos 10 heridos.  \u015eenol Hodja tiene experiencia y no imparte una formaci\u00f3n incorrecta.  No pudimos presionar a los jugadores, simplemente hablamos y tratamos de motivarlos.  Hab\u00eda gente herida al menor incidente.  No quer\u00eda jugar el partido del Club Brugge en absoluto, no hab\u00eda jugadores.  No pudimos encontrar ni un solo defensor.  Jugamos con Onur como defensor.  Jugamos a Muleka abiertamente porque no hay jugadores.  No pude obtener ning\u00fan resultado de Ante Rebic.  Mantuvimos la disciplina, las amistades eran buenas.  Los partidos del Club Brujas y del Fenerbah\u00e7e no fueron buenos para nosotros.  No me importa el partido de Brujas, pero el partido del Fenerbah\u00e7e fue similar al de ayer.  Recibimos goles por errores individuales.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO DEJO HABLAR A MIS FUTBOLISTAS&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El otro d\u00eda entrenamos por primera vez con Milot Rashica.  Tuvimos muy poco tiempo.  Quer\u00edan que hiciera mucho en este corto tiempo.  Si tienes los materiales, puedes hacerlo.  Si tuvi\u00e9ramos el 40 por ciento del material, a\u00fan podr\u00edamos hacer lo que quisi\u00e9ramos.  No dejo hablar a mis amigos del f\u00fatbol.  Trabajamos con ellos en tiempos dif\u00edciles.  Estoy muy contento con todos ellos, les agradec\u00ed a todos.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>\u00bfC\u00f3mo saldr\u00e1 el Be\u015fikta\u015f de la situaci\u00f3n actual?<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Ya no tengo derecho a decir nada sobre Be\u015fikta\u015f.  Encuentran la salida.  Lo \u00fanico que falta en el ratio es que no hubo un buen traspaso.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO ME INTERESAN LAS REDES SOCIALES&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>No me interesan las redes sociales.  Ni siquiera s\u00e9 c\u00f3mo salir de all\u00ed.  Tenemos un amigo que est\u00e1 interesado en ese negocio.  \u00c9l debe haberlo hecho, yo lo resolver\u00e9.  Mir\u00e9 las redes sociales una o dos veces.  En mi vida futbol\u00edstica, nunca he estado tanto en la agenda como en las redes sociales.  Exageran.  Nada de campamento&#8230; Nunca romp\u00ed mi disciplina.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;NO ME LLAMARON&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Lo que m\u00e1s lamento es que Samet Aybaba y Feyyaz U\u00e7ar vinieran a hablar conmigo en lugar de con los directivos.  No vinieron, no me llamaron.  Lo quer\u00edan, lo firm\u00e9.  Lo hice por el Be\u015fikta\u015f.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>S\u00f3lo nos reunimos con el presidente Hasan Arat en la reuni\u00f3n con los jugadores y esa reuni\u00f3n se celebr\u00f3 como &#8220;Hola&#8221;.  Si yo fuera el presidente, me reunir\u00eda en privado para hablar de la situaci\u00f3n del equipo.  No s\u00e9 por qu\u00e9 no se reuni\u00f3.  Si no est\u00e1s detr\u00e1s del entrenador, el jugador pensar\u00e1 &#8216;Ir\u00e1 de todos modos&#8217;.  \u00c9l me respetar\u00e1 tal como yo respetaba a Hasan Arat.  Todos conocer\u00e1n su trabajo.  No quer\u00eda nada econ\u00f3micamente aqu\u00ed.  No soy alguien que diga que tiene que ser Be\u015fikta\u015f.  Ni siquiera escrib\u00ed una cl\u00e1usula en el contrato.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;ME DEJARON SOLA&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Mi consejo: si contratas a un entrenador, ap\u00f3yalo.  Si contamos con su apoyo, las cosas ser\u00e1n diferentes.  Vienes a entrenar con Samet Aybaba y Feyyaz U\u00e7ar.  Me qued\u00e9 solo.  Definitivamente.  Una vez Feyyaz U\u00e7ar dijo: &#8220;Continuamos con R\u0131za \u00c7al\u0131mbay&#8221;.  Eso es todo.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Los gerentes me dijeron: &#8220;Estamos haciendo una declaraci\u00f3n de separaci\u00f3n&#8221;.  Y yo dije: &#8216;Hazlo&#8217;.  Cuando llegamos, el equipo estaba disperso, sus rostros mostraban descontento.  Estaban desconectados, intentamos entrelazarlos.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p><strong>&#8220;\u00cdBAMOS A RENOVAR EL CONTRATO&#8221;<\/strong><\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>El hermano Samet y Feyyaz dijeron: &#8220;El presidente vendr\u00e1 a renovar el contrato y nosotros renovaremos su contrato&#8221; cuando acordaron dos partidos.  El hermano Samet me lo dijo antes de ir a Belgrado.  Lo sigui\u00f3 un defensor.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Cuando el entrenador est\u00e1 de turno no hablo con nadie.  Burak Y\u0131lmaz es mi alumno.  Se lo propuse al Trabzonspor.  No discuto con nadie, no digo nada malo.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>No acept\u00e9 el contrato de 2 partidos.  Primero enviaron documentos, luego vinieron el hermano Samet y Feyyaz y hablamos.  Se dijo que el contrato se ampliar\u00eda.  \u00bfA qu\u00e9 te dedicas?  Tienes dos compa\u00f1eros de equipo.  Le dije: &#8216;Conf\u00edo en ti, firmar\u00e9&#8217;.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Si le dan tiempo al nuevo entrenador, ver\u00e1 las carencias.  Si me hubiera quedado, te habr\u00eda dicho los requisitos para el traslado.  La mayor amenaza para el Be\u015fikta\u015f es la Copa Africana.  Ir\u00e1n 6-7 amigos.  Si el nuevo entrenador me pide informaci\u00f3n se la doy.  Soy de Be\u015fikta\u015f.  No puedo traicionar al Be\u015fikta\u015f, no puedo pensar de otra manera.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Hasan Arat dice que los aficionados del Be\u015fikta\u015f gestionar\u00e1n el Be\u015fikta\u015f.  Est\u00e1 bien, gestiona, somos de Be\u015fikta\u015f.  \u00bfHas visto a un entrenador irse para 4-5 partidos?<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n                            &#13;<br \/>\n&#13;\n                <\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.fotomac.com.tr\/besiktas\/2023\/12\/22\/besiktasta-yollarin-ayrildigi-riza-calimbay-aciklamalarda-bulundu\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-7<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#13; &#13; &#13; En la semana 17 de la Superliga Trendyol, el Be\u015fikta\u015f fue derrotado por el Corendon<\/p>\n","protected":false},"author":1,"featured_media":1104280,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[14301,3402,39121,100284,4634,38,1489,39119,39120,751],"class_list":["post-1104279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-aspora","tag-besiktas","tag-calimbay","tag-corendon-alanyaspor","tag-declaraciones","tag-del","tag-hizo","tag-riza-calimbay","tag-riza","tag-separo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1104279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1104279"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1104279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1104280"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1104279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1104279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1104279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}