{"id":1104270,"date":"2023-12-23T05:13:18","date_gmt":"2023-12-23T05:13:18","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-cuestion-migratoria-hace-que-toda-europa-gire-hacia-la-derecha\/"},"modified":"2023-12-23T05:13:22","modified_gmt":"2023-12-23T05:13:22","slug":"la-cuestion-migratoria-hace-que-toda-europa-gire-hacia-la-derecha","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-cuestion-migratoria-hace-que-toda-europa-gire-hacia-la-derecha\/","title":{"rendered":"La cuesti\u00f3n migratoria hace que toda Europa gire hacia la derecha"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"artstyle__figure  artstyle__figure-landscape\" data-element-id=\"90ed3b8d-df52-40c6-8e5c-284f6bc51032\">\n<picture data-element-id=\"90ed3b8d-df52-40c6-8e5c-284f6bc51032\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"><\/source><\/source><\/picture>\n<p><figcaption class=\"artstyle__figcaption\"><cite class=\"artstyle__figcaption__caption\">Solicitantes de asilo en el centro de registro de Ter Apel.<\/cite><span class=\"artstyle__figcaption__credit\">Imagen Harry Cock \/ de Volkskrant<\/span><\/figcaption><\/p>\n<\/figure>\n<p class=\"artstyle__paragraph \" data-element-id=\"5cc1-8552-3fbd-24eb-9ba4-9a76-007e-3170\">\n<p>      Si Europa no puede detener los barcos en el Mediterr\u00e1neo, la derecha radical puede ganar las elecciones europeas de 2024, dijo esta semana a los periodistas en Bruselas Manfred Weber, l\u00edder de los dem\u00f3cratas cristianos en el Parlamento Europeo.  &#8216;Necesitamos una soluci\u00f3n.  &#8220;Si fracasamos, corremos el riesgo de poner a toda Europa en una situaci\u00f3n dif\u00edcil&#8221;, afirm\u00f3.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"c889-d301-b603-4d45-a609-77ae-3d5c-e0f8\">\n<p>      En la \u00faltima encuesta, los dos grupos de derecha radical en el Parlamento Europeo pasaron de 138 a 167 esca\u00f1os, en un parlamento de 705 esca\u00f1os.  Una victoria limitada, pero la victoria de Geert Wilders caus\u00f3 una gran impresi\u00f3n en Europa.  Las cosas pueden avanzar r\u00e1pidamente para los populistas.  A nivel nacional, los pol\u00edticos tambi\u00e9n sienten en sus nucas el c\u00e1lido aliento de la derecha radical.  En Francia, el partido de Marine Le Pen encabeza las encuestas, en Austria el FP\u00d6, en Alemania el AfD obtiene mejores resultados que nunca.\n    <\/p>\n<div class=\"artstyle__container\" data-element-id=\"cbfb012a-380d-4e86-89b6-24d6f9d82ea3\">\n<div class=\"artstyle__container__body\">\n<p class=\"artstyle__container__text\" data-element-id=\"73ae-20c8-10d6-42c1-14ca-02d8-6024-81ae\">\n      <b>Sobre el Autor<\/b><b><br \/><\/b>Peter Giesen prescribe <i>de Volkskrant <\/i>sobre la Uni\u00f3n Europea y la cooperaci\u00f3n internacional.  Anteriormente fue corresponsal en Francia.  El es el autor de varios libros.\n    <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"artstyle__paragraph \" data-element-id=\"20ee-3b18-d874-356d-0a57-12ba-d988-c2df\">\n<p>      La cuesti\u00f3n de la inmigraci\u00f3n est\u00e1 empujando a todo un continente hacia la derecha.  Los partidos intermedios est\u00e1n tratando diligentemente de recuperar el control con medidas duras.  Esta semana se aprob\u00f3 en Francia una estricta ley de inmigraci\u00f3n y Alemania ha reintroducido controles fronterizos con Polonia.  El pacto migratorio se present\u00f3 finalmente en Bruselas, ocho a\u00f1os despu\u00e9s de la gran crisis de refugiados de 2015.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"d0d6-2daa-0ddd-4f33-7d25-6f70-00a3-f2e1\">\n<p>      Numerosas preguntas pr\u00e1cticas<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"7ab5-7343-fe3d-7071-d5a0-a803-ab30-3ebc\">\n<p>      Sobre el papel parece claro.  Los solicitantes de asilo est\u00e1n siendo separados en las fronteras exteriores europeas.  Los que apenas tienen posibilidades son detenidos y, tras un r\u00e1pido procedimiento, devueltos a su pa\u00eds de origen.  S\u00f3lo a los solicitantes de asilo prometedores se les permite continuar, en espera de una decisi\u00f3n.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"97fc-6df1-30bf-76bc-e9f8-0561-549c-d614\">\n<p>      Sin embargo, el plan plante\u00f3 numerosas cuestiones pr\u00e1cticas.  \u00bfQu\u00e9 se hace con los solicitantes de asilo que todav\u00eda viajan al norte de Europa?  \u00bfSer\u00e1n enviados de regreso a campos en Italia o Grecia?  \u00bfNo se violan los derechos de los solicitantes de asilo en un procedimiento demasiado apresurado?  Y la pregunta m\u00e1s importante de todas: \u00bfes posible devolver a sus pa\u00edses de origen a los solicitantes de asilo rechazados?  Sin esta opci\u00f3n, en Italia y Grecia corren el riesgo de desarrollarse campos de detenci\u00f3n gigantescos y superpoblados.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"26c5-d615-f51e-d53e-90f1-bebd-ed4a-b076\">\n<p>      Adem\u00e1s, los partidos de centro derecha en particular est\u00e1n luchando con un problema pol\u00edtico importante.  Sus votantes esperan medidas duras contra la inmigraci\u00f3n.  Pero ese enfoque puede volverse contra el centroderecha, como lo demostraron las elecciones holandesas.  La l\u00edder del VVD, Yesilg\u00f6z, hizo de la migraci\u00f3n la punta de lanza de su campa\u00f1a y abri\u00f3 la puerta al PVV.  Esto hizo que el VVD fuera vulnerable a la competencia de Geert Wilders, quien ha hecho de la inmigraci\u00f3n un tema central durante dos d\u00e9cadas.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"3f34-2a03-003c-3b37-3788-f559-e415-bdca\">\n<p>      Los votantes prefieren el original a la copia, en palabras cl\u00e1sicas del populista franc\u00e9s Jean-Marie Le Pen.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"4ec9-c27c-5c79-169c-e08e-1441-5bc0-19b5\">\n<p>      No s\u00f3lo consecuencias para la migraci\u00f3n<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"cc1e-3db4-c228-c4fe-7829-007e-cd24-8822\">\n<p>      La posici\u00f3n del centroderecha normaliza las ideas de la derecha radical.  Esta semana en Francia, se aprob\u00f3 una ley de inmigraci\u00f3n que el parlamento acerc\u00f3 tanto a la derecha que Marine Le Pen la vio como una &#8220;victoria ideol\u00f3gica&#8221; para su partido.  El presidente franc\u00e9s Macron &#8220;que ha sido elegido dos veces para frenar a la extrema derecha, ha transmitido las ideas de la extrema derecha&#8221;, escribi\u00f3 <i>El mundo<\/i> en un comentario.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"2061-a20c-f66f-c78f-ee93-fcdd-9fa5-2860\">\n<p>      El centroderecha est\u00e1 en crisis en todo el mundo, escribi\u00f3 el polit\u00f3logo alem\u00e1n Thomas Biebricher en su libro publicado el a\u00f1o pasado<i> Mitte\/Derecha<\/i>.  Esto tiene graves consecuencias, afirma.  Los partidos conservadores tradicionales eran moderados, ten\u00edan temperamento administrativo y un gran sentido de responsabilidad.  Despu\u00e9s de 1945, los dem\u00f3cratas cristianos fueron la fuerza impulsora de la cooperaci\u00f3n europea.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"f73e-d436-fe65-b6d7-b04c-b849-8b44-b85a\">\n<p>      Si el centroderecha se ve eclipsado por la derecha radical, esto no s\u00f3lo tendr\u00e1 consecuencias para la pol\u00edtica de inmigraci\u00f3n.  La cooperaci\u00f3n europea es cada vez m\u00e1s dif\u00edcil y las pol\u00edticas medioambientales y clim\u00e1ticas se ven sometidas a graves presiones.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"dfbf-20ad-cca7-c323-59ec-1d56-26e0-4146\">\n<p>      Problema complejo<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"8d30-5dfd-b56e-b773-7783-9936-e99b-9557\">\n<p>      Ir\u00f3nicamente, una vez que los populistas llegan al poder, se dan cuenta de lo dif\u00edcil que es reducir las cifras de inmigraci\u00f3n.  El fin de semana pasado, la primera ministra italiana, Giorgia Meloni, y el primer ministro brit\u00e1nico, Rishi Sunak, aparecieron en el festival de derecha radical Atreju en Roma.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"b8f0-8ea2-9fae-f0e7-74aa-4e3b-f90e-30e8\">\n<p>      Rishi Sunak dijo que Europa corre el peligro de verse &#8220;abrumada&#8221; por la inmigraci\u00f3n.  Despu\u00e9s del Brexit \u2013 con el lema <i>recuperar el control<\/i> \u2013 la inmigraci\u00f3n al Reino Unido no ha hecho m\u00e1s que aumentar.  Ahora Sunak y Meloni quieren reescribir los tratados internacionales que, en su opini\u00f3n, obstaculizan una pol\u00edtica migratoria estricta.  Sin duda, escucharemos esto con m\u00e1s frecuencia en los pr\u00f3ximos a\u00f1os: es necesario revisar los tratados internacionales.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"3f1e-862e-d19e-9bd4-0e68-8fcd-f874-8cea\">\n<p>      Meloni prometi\u00f3 frenar la inmigraci\u00f3n con un &#8220;bloqueo naval&#8221;.  Pero este a\u00f1o, llegaron a Italia un 55 por ciento m\u00e1s de inmigrantes que en 2022. Adem\u00e1s, Meloni se vio obligada a admitir a 425.000 trabajadores inmigrantes legales para mantener en funcionamiento la econom\u00eda de una Italia que envejece r\u00e1pidamente.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"77ab-8c2a-6d1f-ca58-41dc-4ba8-01a9-9380\">\n<p>      Realidad rebelde<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"c1bd-2f8f-e131-481f-e30f-08bd-ea8e-ae07\">\n<p>      Meloni calific\u00f3 la migraci\u00f3n como \u201cel fen\u00f3meno m\u00e1s complejo con el que me he enfrentado jam\u00e1s\u201d.  Reconoci\u00f3 que los resultados no estuvieron a la altura de las expectativas, pero dijo que no est\u00e1 interesada en medidas r\u00e1pidas que no resuelvan fundamentalmente el problema.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"ebfd-8f1c-7d04-af5f-20b2-7701-6d08-dcb2\">\n<p>      Mientras el centro-derecha sigue tomando medidas duras contra la inmigraci\u00f3n, la &#8220;posfascista&#8221; Meloni de repente son\u00f3 como una vieja pol\u00edtica que cuenta la &#8220;historia honesta&#8221;, porque sus promesas electorales chocan con una realidad ingobernable.\n    <\/p>\n<p><iframe id=\"sim_5272912154_1\" width=\"100%\" frameborder=\"0\" src=\"https:\/\/ims.volkskrant.nl\/optiext\/optiextension.dll?ID=MofMcIOTGz4_eO12zRZyy3_k1B2_oXSIXiWIOsaTs8K2w3C2xx7aMAL2GEFRfcLU_jR7lp0eNt4zq8CfIX&amp;guid=5455F0A2-6D8D-4270-B063-E32B1C27B6F2&amp;frameid=sim_5272912154_1&amp;reference=\" loading=\"lazy\"><\/iframe><\/p>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lea tambi\u00e9n<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.volkskrant.nl\/nieuws-achtergrond\/het-migratievraagstuk-trekt-heel-europa-naar-rechts~bfa7113b\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-23<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solicitantes de asilo en el centro de registro de Ter Apel.Imagen Harry Cock \/ de Volkskrant Si Europa<\/p>\n","protected":false},"author":1,"featured_media":1104271,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[8492,11514,348,77064,1740,2668,55821,530],"class_list":["post-1104270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cuestion","tag-derecha","tag-europa","tag-gire","tag-hace","tag-hacia","tag-migratoria","tag-toda"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1104270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1104270"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1104270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1104271"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1104270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1104270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1104270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}