{"id":1064225,"date":"2023-11-26T09:06:38","date_gmt":"2023-11-26T09:06:38","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-entrenador-del-schalke-geraerts-combativo-tras-el-3-5-el-comportamiento-de-ouwejan-es-inaceptable\/"},"modified":"2023-11-26T09:06:42","modified_gmt":"2023-11-26T09:06:42","slug":"el-entrenador-del-schalke-geraerts-combativo-tras-el-3-5-el-comportamiento-de-ouwejan-es-inaceptable","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-entrenador-del-schalke-geraerts-combativo-tras-el-3-5-el-comportamiento-de-ouwejan-es-inaceptable\/","title":{"rendered":"El entrenador del Schalke, Geraerts, combativo tras el 3-5: el comportamiento de Ouwejan es inaceptable"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Hechelmann estaba \u201cavergonzado\u201d  <\/p>\n<p>Karel Geraerts se mostr\u00f3 combativo tras la amarga derrota.  \u201cNo me rendir\u00e9\u201d, afirm\u00f3 el entrenador del FC Schalke 04 tras la derrota del s\u00e1bado por la tarde por 3-5 ante el Fortuna D\u00fcsseldorf.  Esto significa que el equipo descendido de la Bundesliga est\u00e1 inmerso en la batalla por el descenso de la 2.\u00aa liga.  \u201c\u00a1No son las doce menos cinco, son las doce!\u201d, advirti\u00f3 el entrenador.  \u201cY espero que todos los jugadores lo entiendan.  Si no, te lo explico&#8221;, dijo el nuevo entrenador del Schalke, que ya suma cuatro derrotas despu\u00e9s de seis partidos.<\/p>\n<p><\/p>\n<p>Despu\u00e9s del duro partido de su equipo en la primera parte, Geraerts ten\u00eda preparadas dos recetas.  En primer lugar, cambi\u00f3 a tres jugadores a la media hora y tambi\u00e9n provoc\u00f3 el disgusto de Thomas Ouwejan.  El holand\u00e9s estaba enojado por el cambio temprano, se neg\u00f3 a estrechar la mano y no mostr\u00f3 comprensi\u00f3n.  Su entrenador estaba muy enojado.  \u201cNo aceptar\u00e9 ese comportamiento\u201d, explic\u00f3 el t\u00e9cnico y se quej\u00f3 de la falta de respeto de su jugador.<\/p>\n<p><\/p>\n<p>El belga tambi\u00e9n hizo mucho ruido en el vestuario en el descanso.  \u201cEso es normal\u201d, dijo.  Al menos su equipo, que r\u00e1pidamente perd\u00eda 3-0, entr\u00f3 mejor en el partido, anotando tres goles de Marcin Kaminski, Tomas Kalas y Bryan Lasme, pero D\u00fcsseldorf contrarrest\u00f3 el gol 3-4, devolvi\u00f3 el golpe para ganar 5-3 y asegurado una vez m\u00e1s creando un gran espect\u00e1culo en un partido del s\u00e1bado por la noche en la arena.  M\u00e1s recientemente, el equipo revirti\u00f3 un d\u00e9ficit de 3-0 contra el 1. FC Kaiserslautern en una victoria de 4-3.<\/p>\n<div class=\"img-news-container\">\n<div class=\"img-news\"><\/div>\n<\/p><\/div>\n<\/p>\n<p>Con 33 goles encajados, el Schalke es el que m\u00e1s goles ha recibido, est\u00e1 estancado en el puesto 16 y muestra pocas esperanzas de mejorar.  El goleador Kaminski, uno de los mejores jugadores del Schalke, explic\u00f3 que todos los jugadores eran conscientes de la gravedad de la situaci\u00f3n.  \u201cEsto molesta a todos y queremos hacer todo lo posible para salir de esta situaci\u00f3n\u201d, afirm\u00f3 el internacional polaco.<\/p>\n<h2>El director deportivo del Schalke, Hechelmann, pide una batalla por el descenso<\/h2>\n<p>&#8220;Yo estaba avergonzado.  Eso fue un reflejo de Elversberg.  Trabajamos en este partido durante dos semanas y lo mejoramos en los dos partidos amistosos durante el par\u00f3n internacional.  Pero eso no ayuda.  Tienes que cumplir cuando se trata de puntos.  No hay excusas.  Se trata de actitud, de tu propio honor.  Me duele el coraz\u00f3n por todos los que vinieron aqu\u00ed\u201d, explic\u00f3 el director deportivo Andr\u00e9 Hechelmann (citado v\u00eda \u201c<a rel=\"nofollow noopener\" href=\"https:\/\/www.waz.de\/sport\/fussball\/s04\/schalke-das-ist-abstiegskampf-hechelmann-schaemt-sich-id240676230.html\" target=\"_blank\">WAZ<\/a>&#8220;) tras la novena derrota de la temporada y al mismo tiempo miraba hacia adelante: &#8220;No sirve de nada quedarse petrificado.  Tengo que seguir adelante, tengo que llegar al fondo de esto\u201d. El entrenador habl\u00f3 de la batalla por el descenso: \u201cPunto.  Claramente.  Esta es una batalla por el descenso.  Tienes que estar preparado para luchar.  Eso es lo que m\u00e1s nos preocupar\u00e1 durante las pr\u00f3ximas tres semanas\u201d.<\/p>\n<p><\/p>\n<div class=\"bbcode-newsbox newsGalerie\" data-galerie-id=\"10973\" data-galerie-titel=\"Viele Schalker &amp; Herthaner: Gr\u00f6\u00dfte Verlierer im Update der 2. Bundesliga\">\n<p><h2>Muchos jugadores del Schalke y Herthan: los mayores perdedores en la segunda actualizaci\u00f3n de la Bundesliga<\/h2>\n<\/p>\n<div class=\"swiper-container news-slider\" id=\"swiper-newsGalerie\">\n<div class=\"swiper-wrapper\">\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" style=\"background-image: url(https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/paul-seguin-schalke-04-2023-24-1691787052-113934.jpg?lm=1691787070);\">\n<p>\n                        <span class=\"slider-gallery-subline\">Pablo Seguin |  FC Schalke 04 |  -700 mil \u20ac<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 1,8 millones de euros <br \/>Despu\u00e9s de la actualizaci\u00f3n del 20 de octubre de 2023<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/linus-gechter-hertha-bsc-2023-24-1693566942-115604.jpg?lm=1693566951\">\n<p>\n                        <span class=\"slider-gallery-subline\">Linus Gechter |  Hertha BSC |  -700 mil \u20ac<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 1,8 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/marc-oliver-kempf-hertha-2023-1693146077-115023.jpg?lm=1693146283\">\n<p>\n                        <span class=\"slider-gallery-subline\">Marc Oliver Kempf |  Hertha BSC |  -700 mil \u20ac<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2,8 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/cedric-brunner-fc-schalke-04-2023-1697643560-119794.jpg?lm=1697643590\">\n<p>\n                        <span class=\"slider-gallery-subline\">C\u00e9dric Brunner |  FC Schalke 04 |  -800 mil \u20ac<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 1 mill\u00f3n de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/marcel-halstenberg-hannover-96-2023-1690873453-112915.jpg?lm=1690873466\">\n<p>\n                        <span class=\"slider-gallery-subline\">Marcel Halstenberg |  Hannover 96 |  -1 mill\u00f3n de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2,5 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/marton-dardai-hertha-bsc-1617960270-60421.jpg?lm=1617960299\">\n<p>\n                        <span class=\"slider-gallery-subline\">Marton Dardai |  Hertha BSC |  -1 mill\u00f3n de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2,5 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/michael-cuisance-vfl-osnabruck-2023-1693992482-116031.jpg?lm=1693992500\">\n<p>\n                        <span class=\"slider-gallery-subline\">Michael Cuisance |  VfL Osnabr\u00fcck |  -1 mill\u00f3n de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/jonjoe-kenny-hertha-2022-1674223433-100439.jpg?lm=1674223447\">\n<p>\n                        <span class=\"slider-gallery-subline\">Jonjoe Kenny |  Hertha BSC |  -1 mill\u00f3n de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/andreas-bouchalakis-hertha-bsc-2023-1693992712-116034.jpg?lm=1693992728\">\n<p>\n                        <span class=\"slider-gallery-subline\">Andr\u00e9s Bouchalakis |  Hertha BSC |  -1 mill\u00f3n de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 2 millones de euros<\/p>\n<\/p><\/div>\n<div class=\"swiper-slide\">\n<div class=\"slider-foto swiper-lazy\" data-background=\"https:\/\/tmssl.akamaized.net\/images\/foto\/galerie\/timo-baumgartl-fc-schalke-04-2023-1693992553-116032.jpg?lm=1693992563\">\n<p>\n                        <span class=\"slider-gallery-subline\">Timo Baumgartl |  Schalke 04 |  -1,2 millones de euros<\/span>\n                    <\/p>\n<\/div>\n<p><span>&#038;Copiar<\/span> IMAGEN<\/p>\n<p class=\"newsGalerieContent\">Nuevo valor de mercado: 1,8 millones de euros<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>                        <span><\/p>\n<p>                            A la p\u00e1gina de inicio                        <\/span><br \/>\n                        <span class=\"icon-doppelpfeil-weiss\"> <\/span><\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.transfermarkt.de\/s04-coach-geraerts-nach-3-5-es-ist-zwolf-quot-wird-ouwejans-verhalten-nicht-akzeptieren-quot-\/view\/news\/430570\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-38<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hechelmann estaba \u201cavergonzado\u201d Karel Geraerts se mostr\u00f3 combativo tras la amarga derrota. \u201cNo me rendir\u00e9\u201d, afirm\u00f3 el entrenador<\/p>\n","protected":false},"author":1,"featured_media":1064226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[201084,134022,22752,3660,38,752,51711,208909,456,208908,21304,1358,180837,720],"class_list":["post-1064225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-2-a-bundesliga","tag-andre-hechelmann","tag-combativo","tag-comportamiento","tag-del","tag-entrenador","tag-fc-schalke-04","tag-geraerts","tag-inaceptable","tag-karel-geraerts","tag-ouwejan","tag-schalke","tag-thomas-ouwejan","tag-tras"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1064225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1064225"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1064225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1064226"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1064225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1064225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1064225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}