{"id":1063401,"date":"2023-11-25T16:45:19","date_gmt":"2023-11-25T16:45:19","guid":{"rendered":"https:\/\/teknomers.com\/es\/bundesliga-el-1-fc-union-berlin-marca-tarde-contra-el-fc-augsburg\/"},"modified":"2023-11-25T16:45:23","modified_gmt":"2023-11-25T16:45:23","slug":"bundesliga-el-1-fc-union-berlin-marca-tarde-contra-el-fc-augsburg","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/bundesliga-el-1-fc-union-berlin-marca-tarde-contra-el-fc-augsburg\/","title":{"rendered":"Bundesliga: el 1. FC Union Berlin marca tarde contra el FC Augsburg"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 25 de noviembre de 2023 17:42<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>La serie de quiebras del Uni\u00f3n Berl\u00edn en la Bundesliga ha terminado.  En el primer partido con el entrenador interino Marco Grote y la asistente Marie-Louise Eta, los berlineses empataron 1-1 (0-1) contra el FC Augsburg en la jornada 12.<\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Kevin Volland anot\u00f3 el empate en el minuto 88.  Ermedin Demirovic ya hab\u00eda adelantado al FCA con un penalti (39&#8242;).  Robin Knoche tambi\u00e9n fall\u00f3 un penalti para el Union (58\u00ba).<\/p>\n<div class=\"copytext-element-wrapper columns twelve\">\n<div class=\"columns twelve m-ten m-offset-one l-eight l-offset-two copytext-element-wrapper__spacing\">\n<ul class=\"buttongroup buttongroup--copytext\">\n<li class=\"buttongroup__item\">\n<p>        <span class=\"btn__label\">Al teletipo en vivo: Uni\u00f3n &#8211; Augsburgo  <\/span><br \/>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\" class=\"icon icon--arrow--right\" role=\"img\"><title>Flecha correcta<\/title>\n    <g>\n        <path d=\"M23.21,16L12.52,26.7c-0.4,0.4-1.04,0.4-1.43,0c-0.4-0.4-0.4-1.04,0-1.43L20.37,16l-9.28-9.27 c-0.4-0.4-0.4-1.04,0-1.43c0.4-0.4,1.04-0.4,1.43,0L23.21,16z\"\/>\n    <\/g>\n<\/svg><\/p>\n<\/li>\n<li class=\"buttongroup__item\">\n<p>        <span class=\"btn__label\">12\u00aa jornada<\/span><br \/>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\" class=\"icon icon--arrow--right\" role=\"img\"><title>Flecha correcta<\/title>\n    <g>\n        <path d=\"M23.21,16L12.52,26.7c-0.4,0.4-1.04,0.4-1.43,0c-0.4-0.4-0.4-1.04,0-1.43L20.37,16l-9.28-9.27 c-0.4-0.4-0.4-1.04,0-1.43c0.4-0.4,1.04-0.4,1.43,0L23.21,16z\"\/>\n    <\/g>\n<\/svg><\/p>\n<\/li>\n<\/ul><\/div>\n<\/div>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Para los berlineses fue su primera victoria tras nueve derrotas consecutivas en la liga.  Sin embargo, los berlineses llevan 15 partidos oficiales esperando una victoria.  Los berlineses subieron al puesto 17 de la clasificaci\u00f3n, la FCA se mantuvo invicta en el quinto partido con el nuevo entrenador Jess Thorup y ocupa el d\u00e9cimo lugar.<\/p>\n<h2 id=\"Torhueter-Roennow-und-Dahmen-frueh-gefordert\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">El portero R\u00f6nnow y Dahmen tuvieron problemas desde el principio<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El partido empez\u00f3 sin muchas pruebas.  Ambos equipos jugaron directo y tuvieron sus primeras oportunidades.  Pero los porteros tambi\u00e9n participaron directamente en el partido.  El portero del Union Frederik R\u00f6nnow salv\u00f3 un disparo de Demirovic (9\u00ba).  En respuesta directa, el portero del FCA, Finn Dahmen, se vio muy necesitado ante Kevin Behrens (10.\u00ba).<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El partido se estabiliz\u00f3 hasta que en el minuto 36 el \u00e1rbitro Florian Badst\u00fcbner se\u00f1al\u00f3 de repente el punto de penalti.  Robin Gosens, del Union, derrib\u00f3 a Arne Engels, del Augsburgo, en el borde del \u00e1rea.  La escena fue examinada durante mucho tiempo, pero Badst\u00fcbner mantuvo su decisi\u00f3n incluso despu\u00e9s de ver las im\u00e1genes de v\u00eddeo.  Demirovic dio un paso adelante y marc\u00f3 para darle la ventaja al Augsburgo (38\u00ba).<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>En el tiempo a\u00f1adido de la primera parte, David Fofana tuvo una gran oportunidad de empatar, pero s\u00f3lo a quemarropa golpe\u00f3 en la cara al portero del FCA Dahmen.<\/p>\n<h2 id=\"Dahmen-haelt-Elfmeter-von-Knoche\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Dahmen detiene el penalti de Knoche<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Poco despu\u00e9s del inicio de la segunda parte, el \u00e1rbitro Badst\u00fcbner volvi\u00f3 a centrarse.  Iago, del Augsburgo, derrib\u00f3 a Christopher Trimmel en un duelo a\u00e9reo en el \u00e1rea de Augsburgo.  Badst\u00fcbner inicialmente dej\u00f3 que el juego continuara pero, seg\u00fan las im\u00e1genes del v\u00eddeo, decidi\u00f3 imponer un penalti. <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Robin Knoche agarr\u00f3 el bal\u00f3n y lo apunt\u00f3 al \u00e1ngulo inferior izquierdo.  Sin embargo, Dahmen tuvo la misma idea y rasp\u00f3 el bal\u00f3n fuera de la l\u00ednea (58\u00ba). <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Unos minutos m\u00e1s tarde, el jugador de 25 a\u00f1os estaba all\u00ed de nuevo y realiz\u00f3 otra fuerte parada contra Fofana (62&#8242;).  S\u00f3lo dos minutos despu\u00e9s, Dahmen fue derrotado.  El cabezazo de Gosens, acertadamente, no cont\u00f3 por posici\u00f3n de fuera de juego (64&#8242;). <\/p>\n<h2 id=\"Volland-erloest-Union\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Volland redime a la Uni\u00f3n<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El Uni\u00f3n sigui\u00f3 corriendo y finalmente obtuvo su recompensa dos minutos antes del final.  Knoche dispar\u00f3 una falta al segundo palo para Volland, que marc\u00f3 desde corta distancia.  Fue su primer gol con la camiseta del Union y el primer gol de Berl\u00edn desde el 7 de octubre.  El Union presion\u00f3 por el gol de la victoria en el tiempo adicional, pero al final los puntos quedaron divididos.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Los berlineses se enfrentar\u00e1n ahora en la Liga de Campeones al Sporting Braga el pr\u00f3ximo mi\u00e9rcoles (29 de noviembre de 2023) (21 horas).  En la 13.\u00aa jornada de la Bundesliga, el Unioners se enfrentar\u00e1 en M\u00fanich (2 de diciembre de 2023, 15:30 horas).  El Augsburgo se enfrentar\u00e1 al Eintracht Frankfurt en casa un d\u00eda despu\u00e9s (19:30 horas).<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/fussball\/bundesliga\/bundesliga-spielbericht-fc-union-berlin-fc-augsburg-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 25 de noviembre de 2023 17:42 La serie de quiebras del Uni\u00f3n Berl\u00edn en la<\/p>\n","protected":false},"author":1,"featured_media":1063402,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9159,3231,1417,81,110,7747,6365,1529,4424,645],"class_list":["post-1063401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-1-fc-union-berlin","tag-augsburg","tag-berlin","tag-bundesliga","tag-contra","tag-fc-augsburgo","tag-futbol-americano","tag-marca","tag-tarde","tag-union"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1063401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1063401"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1063401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1063402"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1063401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1063401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1063401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}