{"id":1042581,"date":"2023-11-12T12:46:15","date_gmt":"2023-11-12T12:46:15","guid":{"rendered":"https:\/\/teknomers.com\/es\/las-leyes-de-datos-y-espionaje-de-beijing-amenazan-con-estimular-el-desacoplamiento-con-europa-dice-un-grupo-empresarial\/"},"modified":"2023-11-12T12:46:15","modified_gmt":"2023-11-12T12:46:15","slug":"las-leyes-de-datos-y-espionaje-de-beijing-amenazan-con-estimular-el-desacoplamiento-con-europa-dice-un-grupo-empresarial","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/las-leyes-de-datos-y-espionaje-de-beijing-amenazan-con-estimular-el-desacoplamiento-con-europa-dice-un-grupo-empresarial\/","title":{"rendered":"Las leyes de datos y espionaje de Beijing amenazan con estimular el desacoplamiento con Europa, dice un grupo empresarial"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Mant\u00e9ngase informado con actualizaciones gratuitas<\/p>\n<p class=\"article__content-sign-up-topic-description\"><span>Simplemente reg\u00edstrate en <!-- -->Negocios y finanzas chinos<!-- --> myFT Digest: entregado directamente a su bandeja de entrada.<\/span><\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=93bbc4ee-41ee-4552-9da0-d2cffaae0528&amp;concept-id=dd3cc5a2-d14b-4b78-811c-89c387497476\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>Las leyes modificadas contra el espionaje y los datos de China amenazan con estimular el desacoplamiento de Europa al dificultar la inversi\u00f3n de las empresas extranjeras, seg\u00fan un grupo de lobby empresarial europeo. <\/p>\n<p>Los comentarios de BusinessEurope, que representa a grupos de presi\u00f3n comerciales de toda la UE, se producen despu\u00e9s de que China intentara disipar las crecientes preocupaciones sobre el entorno de inversi\u00f3n extranjera la semana pasada con un memorando que ordenaba a las autoridades locales poner fin a las pr\u00e1cticas discriminatorias.<\/p>\n<p>La subdirectora general de BusinessEurope, Luisa Santos, advirti\u00f3 que las nuevas leyes que restringen los flujos de datos fuera de China, junto con severos castigos para los acusados \u200b\u200bbajo la legislaci\u00f3n antiespionaje enmendada, preocupaban a los inversores extranjeros. <\/p>\n<p>&#8220;Si la gente tiene miedo de ir a la c\u00e1rcel en China&#8221; por compartir datos con Europa, entonces &#8220;hay que tomar algunas decisiones muy dif\u00edciles y esto podr\u00eda conducir efectivamente al desacoplamiento que todos queremos evitar&#8221;, dijo Santos en un comunicado. entrevista en Pek\u00edn.<\/p>\n<p>Las c\u00e1maras de comercio extranjeras se han quejado de que las nuevas leyes chinas sobre flujos de datos transfronterizos son demasiado vagas, lo que dificulta que las multinacionales realicen actividades comerciales y de investigaci\u00f3n normales junto con sus operaciones internacionales.<\/p>\n<p>La C\u00e1mara de Comercio de la Uni\u00f3n Europea en China public\u00f3 recientemente un informe que detalla 1.058 recomendaciones a las autoridades chinas sobre las leyes de datos y otras pr\u00e1cticas que, seg\u00fan afirma, brindan un trato desigual a las empresas extranjeras en el pa\u00eds.<\/p>\n<p>\u201cEl objetivo principal es demostrar que todav\u00eda nos importa.  .  .  China es, junto con Estados Unidos, nuestro principal socio comercial\u201d, dijo Santos sobre su visita a Beijing.  &#8220;Al mismo tiempo, la relaci\u00f3n enfrenta muchos desaf\u00edos&#8221;.<\/p>\n<p>Dijo que las regulaciones en Europa que exigen una mayor diligencia debida en cuestiones como el trabajo forzoso significaban que las empresas necesitaban fortalecer el cumplimiento y la trazabilidad de su cadena de suministro.<\/p>\n<p>Pero China ha estado tomando medidas en\u00e9rgicas contra las empresas de diligencia debida, deteniendo a empleados locales del grupo estadounidense Mintz e investigando a otros, como la red de expertos CapVision, lo que dificulta el cumplimiento. <\/p>\n<p>Santos dijo que si las empresas tienen problemas con los requisitos de trazabilidad de la cadena de suministro, &#8220;o si esa informaci\u00f3n no es precisa o positiva, entonces existe un riesgo muy alto de desconexi\u00f3n del mercado chino&#8221;.<\/p>\n<p>Cada vez m\u00e1s, las empresas comenzar\u00edan a implementar una estrategia \u201cen China para el mercado chino\u201d, separando sus operaciones locales de las redes en el extranjero e invirtiendo en nueva capacidad de fabricaci\u00f3n para las exportaciones.<\/p>\n<p>Dijo que otras preocupaciones entre las empresas europeas inclu\u00edan la postura de China sobre la guerra de Ucrania, su insistencia en conservar el estatus de naci\u00f3n en desarrollo en la OMC, que le da derecho a un trato preferencial, y la lentitud en la emisi\u00f3n de visas.<\/p>\n<p>El Ministerio de Comercio de China ha tratado de disipar las preocupaciones de las c\u00e1maras de comercio extranjeras.  En un memorando emitido la semana pasada, orden\u00f3 la \u201climpieza\u201d de regulaciones que discriminaban a los inversores extranjeros. <\/p>\n<p>Estas inclu\u00edan medidas como obligar a las empresas a someterse a un proceso m\u00e1s largo para solicitar permisos, no permitir que las marcas extranjeras se beneficiaran de subsidios e impedirles participar en licitaciones y adquisiciones de los gobiernos locales.<\/p>\n<aside aria-labelledby=\"aside-label\" class=\"n-content-recommended--single-story\">\n<p class=\"n-content-recommended__title\">Recomendado<\/p>\n<div class=\"o-teaser o-teaser--article o-teaser--small o-teaser--stacked o-teaser--has-image js-teaser\" data-id=\"d7b9db0a-9275-48ad-be3a-99afcc6bbf4c\">\n<div class=\"o-teaser__image-container js-teaser-image-container\">\n<div class=\"o-teaser__image-placeholder\" style=\"padding-bottom:56.2500%\"><img decoding=\"async\" class=\"o-teaser__image\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/11\/Las-leyes-de-datos-y-espionaje-de-Beijing-amenazan-con.com\/__origami\/service\/image\/v2\/images\/raw\/https%3A%2F%2Fd1e.jpeg\" alt=\"Imagen de montaje de Xi Jinping, la bandera china y los gr\u00e1ficos.\"\/><\/div>\n<\/div>\n<\/div>\n<\/aside>\n<p>Al comentar sobre el memorando, la C\u00e1mara Europea dijo que &#8220;espera la publicaci\u00f3n de un cronograma y pautas de implementaci\u00f3n m\u00e1s espec\u00edficas&#8221;, mientras que el presidente de la C\u00e1mara Brit\u00e1nica, Julian Fisher, dijo que el anuncio &#8220;ayudar\u00eda a instalar la confianza en el mercado chino entre nuestros miembros&#8221;.<\/p>\n<p>Pero el presidente de AmCham China, Michael Hart, dijo que despu\u00e9s de tres a\u00f1os de restricciones de Covid, tensiones geopol\u00edticas y relaciones desafiantes entre Estados Unidos y China, lograr que las empresas vuelvan a invertir &#8220;no es como apretar un interruptor&#8221;.<\/p>\n<p>&#8220;Tendremos que ver qu\u00e9 viene despu\u00e9s en t\u00e9rminos de acciones y luego veremos si las empresas ganan suficiente confianza para aprobar nuevas inversiones&#8221;, dijo Hart.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/93bbc4ee-41ee-4552-9da0-d2cffaae0528\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mant\u00e9ngase informado con actualizaciones gratuitas Simplemente reg\u00edstrate en Negocios y finanzas chinos myFT Digest: entregado directamente a su<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[17260,72,99,1755,9415,1219,33454,10315,19679,348,2386,246,9104],"class_list":["post-1042581","post","type-post","status-publish","format-standard","hentry","category-general","tag-amenazan","tag-beijing","tag-con","tag-datos","tag-desacoplamiento","tag-dice","tag-empresarial","tag-espionaje","tag-estimular","tag-europa","tag-grupo","tag-las","tag-leyes"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042581"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042581\/revisions"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}