{"id":1042572,"date":"2023-11-12T12:39:00","date_gmt":"2023-11-12T12:39:00","guid":{"rendered":"https:\/\/teknomers.com\/es\/quizas-deberiamos-iniciar-un-boicot-contra-shell-al-estilo-de-los-anos-80\/"},"modified":"2023-11-12T12:39:03","modified_gmt":"2023-11-12T12:39:03","slug":"quizas-deberiamos-iniciar-un-boicot-contra-shell-al-estilo-de-los-anos-80","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/quizas-deberiamos-iniciar-un-boicot-contra-shell-al-estilo-de-los-anos-80\/","title":{"rendered":"\u00bfQuiz\u00e1s deber\u00edamos iniciar un boicot contra Shell al estilo de los a\u00f1os 80?"},"content":{"rendered":"\n<div id=\"\">\n<section class=\"artstyle__production artstyle__production--type-plus fu--type-plus artstyle__production--hide-author fu--hide-author artstyle__production--hide-time fu--hide-time artstyle__production--margin-bottom-s-s fu--margin-bottom-s-s artstyle__production--with-authors\" data-element-id=\"article-element-authors\"><span class=\"artstyle__production__authors\">Teun de la cocina<\/span><time class=\"artstyle__production__datetime\" datetime=\"12 november 2023\"><span class=\"artstyle__production__date\">12 de noviembre de 2023<\/span><span class=\"artstyle__production__time\">13:14<\/span><\/time><span class=\"artstyle__production-decoration\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"184\" height=\"11\" viewbox=\"0 0 184 11\" fill=\"none\"><mask id=\"path-1-inside-1\" fill=\"white\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M86.9133 5.08154L81.8318 0L76.7745 5.05725H0V5.65725H76.7288L81.8318 10.7603L86.9133 5.67871L91.9949 10.7603L96.9948 5.76038L101.995 10.7603L107.098 5.65725H184V5.05725H107.052L101.995 0L96.9948 4.99988L91.9949 0L86.9133 5.08154Z\"\/><\/mask><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M86.9133 5.08154L81.8318 0L76.7745 5.05725H0V5.65725H76.7288L81.8318 10.7603L86.9133 5.67871L91.9949 10.7603L96.9948 5.76038L101.995 10.7603L107.098 5.65725H184V5.05725H107.052L101.995 0L96.9948 4.99988L91.9949 0L86.9133 5.08154Z\" fill=\"white\"\/><path d=\"M81.8318 0L82.2122 -0.380432L81.8318 -0.760863L81.4514 -0.380432L81.8318 0ZM86.9133 5.08154L86.5329 5.46197L86.9133 5.84241L87.2938 5.46197L86.9133 5.08154ZM76.7745 5.05725V5.59526H76.9974L77.155 5.43768L76.7745 5.05725ZM0 5.05725V4.51924H-0.538012V5.05725H0ZM0 5.65725H-0.538012V6.19526H0V5.65725ZM76.7288 5.65725L77.1092 5.27682L76.9516 5.11924H76.7288V5.65725ZM81.8318 10.7603L81.4514 11.1407L81.8318 11.5211L82.2122 11.1407L81.8318 10.7603ZM86.9133 5.67871L87.2938 5.29828L86.9133 4.91785L86.5329 5.29828L86.9133 5.67871ZM91.9949 10.7603L91.6144 11.1407L91.9949 11.5211L92.3753 11.1407L91.9949 10.7603ZM96.9948 5.76038L97.3752 5.37995L96.9948 4.99951L96.6143 5.37995L96.9948 5.76038ZM101.995 10.7603L101.614 11.1407L101.995 11.5211L102.375 11.1407L101.995 10.7603ZM107.098 5.65725V5.11924H106.875L106.717 5.27682L107.098 5.65725ZM184 5.65725V6.19526H184.538V5.65725H184ZM184 5.05725H184.538V4.51924H184V5.05725ZM107.052 5.05725L106.671 5.43768L106.829 5.59526H107.052V5.05725ZM101.995 0L102.375 -0.380432L101.995 -0.760863L101.614 -0.380432L101.995 0ZM96.9948 4.99988L96.6143 5.38031L96.9948 5.76074L97.3752 5.38031L96.9948 4.99988ZM91.9949 0L92.3753 -0.380432L91.9949 -0.760863L91.6144 -0.380432L91.9949 0ZM81.4514 0.380432L86.5329 5.46197L87.2938 4.70111L82.2122 -0.380432L81.4514 0.380432ZM77.155 5.43768L82.2122 0.380432L81.4514 -0.380432L76.3941 4.67682L77.155 5.43768ZM76.7745 4.51924H0V5.59526H76.7745V4.51924ZM-0.538012 5.05725V5.65725H0.538012V5.05725H-0.538012ZM0 6.19526H76.7288V5.11924H0V6.19526ZM82.2122 10.3798L77.1092 5.27682L76.3484 6.03768L81.4514 11.1407L82.2122 10.3798ZM86.5329 5.29828L81.4514 10.3798L82.2122 11.1407L87.2938 6.05914L86.5329 5.29828ZM92.3753 10.3798L87.2938 5.29828L86.5329 6.05914L91.6144 11.1407L92.3753 10.3798ZM96.6143 5.37995L91.6144 10.3798L92.3753 11.1407L97.3752 6.14081L96.6143 5.37995ZM102.375 10.3798L97.3752 5.37995L96.6143 6.14081L101.614 11.1407L102.375 10.3798ZM106.717 5.27682L101.614 10.3798L102.375 11.1407L107.478 6.03768L106.717 5.27682ZM107.098 6.19526H184V5.11924H107.098V6.19526ZM184.538 5.65725V5.05725H183.462V5.65725H184.538ZM184 4.51924H107.052V5.59526H184V4.51924ZM101.614 0.380432L106.671 5.43768L107.432 4.67682L102.375 -0.380432L101.614 0.380432ZM97.3752 5.38031L102.375 0.380432L101.614 -0.380432L96.6143 4.61945L97.3752 5.38031ZM91.6144 0.380432L96.6143 5.38031L97.3752 4.61945L92.3753 -0.380432L91.6144 0.380432ZM87.2938 5.46197L92.3753 0.380432L91.6144 -0.380432L86.5329 4.70111L87.2938 5.46197Z\" fill=\"black\" mask=\"url(#path-1-inside-1)\"\/><\/svg><\/span><\/section>\n<p class=\"artstyle__paragraph artstyle__paragraph--drop-cap fu--drop-cap artstyle__paragraph--drop-cap-e fu--drop-cap-e\" data-element-id=\"d872-0a3e-6b13-06f1-2fd5-27ff-bdcf-2066\">\n<p>      Hace unas semanas escrib\u00ed sobre la campa\u00f1a Greenwashing de Shell, que quiere pretender ser verde con anuncios ingeniosos.  S\u00f3lo m\u00e1s tarde me di cuenta de que esos anuncios de limpieza ecol\u00f3gica tambi\u00e9n hab\u00edan aparecido en este peri\u00f3dico.  Ahora bien, no quiero escribir sobre la misma empresa una y otra vez, pero cuando cometen errores todo el tiempo, me lo ponen muy dif\u00edcil.  Especialmente cuando lo hacen con tanta frecuencia y tan sucio como Shell.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"845b-28bf-77f1-c329-de46-3c18-8873-2416\">\n      <a rel=\"nofollow noopener\" href=\"https:\/\/www.rtlnieuws.nl\/economie\/artikel\/5417909\/shell-cpc-rusland-samenwerking-rosneft-sancties-oorlog\" target=\"_blank\">la semana pasada llego <i>noticias RTL<\/i> con una revelaci\u00f3n<\/a> Lo cual es tan impactante que vuelvo a escribir sobre esta c\u00ednica y destructiva compa\u00f1\u00eda petrolera.  \u00bfLo que parece?  \u00a1Shell todav\u00eda hace negocios con Rusia!  En el sitio web de RTL le\u00ed que la propia empresa no ve el problema.  Despu\u00e9s de todo, s\u00f3lo hab\u00eda prometido &#8220;retirarse completamente de todo el petr\u00f3leo y gas rusos de acuerdo con las regulaciones gubernamentales&#8221;.  En otras palabras: todo lo que no est\u00e9 expresamente prohibido est\u00e1 permitido.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"6b49-6b91-893e-1451-6399-9f98-6905-4346\">\n<p>      Lim\u00f3n fresco para todos.  Shell gana mucho dinero con esta dudosa posici\u00f3n moral y el r\u00e9gimen ruso tambi\u00e9n se beneficia de ella: &#8216;Rosneft, el socio comercial de Shell, incluso afirma con orgullo en su sitio web que es el mayor contribuyente de Rusia.  La empresa en s\u00ed no est\u00e1 sancionada por la UE, pero s\u00ed el director ejecutivo, Igor Sechin.  Seg\u00fan la UE, Sechin es uno de los asesores m\u00e1s importantes de Vladimir Putin.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"6a26-d978-f18b-a83b-42b0-fbcd-9a84-61c1\">\n<p>      No deber\u00eda sorprender que Shell tenga una br\u00fajula moral tan mal ajustada.  Ese siempre ha sido el caso.  En la d\u00e9cada de 1980, hubo una presi\u00f3n considerable sobre las empresas para que abandonaran Sud\u00e1frica con su r\u00e9gimen de apartheid.  Shell simplemente se qued\u00f3 quieto.  Los llamados a boicotear la compa\u00f1\u00eda petrolera se hicieron cada vez m\u00e1s feroces.  La pegatina se volvi\u00f3 legendaria con una referencia al lema &#8220;Shell ayuda&#8221; de esa \u00e9poca: debajo de una imagen del caparaz\u00f3n amarillo del que goteaba sangre, el texto dec\u00eda: &#8220;Shell ayuda al apartheid en Sud\u00e1frica&#8221;.  Estaba en todas partes en los c\u00edrculos en los que crec\u00ed.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"20f1-6be4-6664-1800-261b-09b0-1428-d565\">\n<p>      Shell tambi\u00e9n lleva a\u00f1os desempe\u00f1ando un mal papel en Nigeria.  Desde finales de los a\u00f1os cincuenta, Shell ha estado bombeando petr\u00f3leo en el delta del N\u00edger con consecuencias devastadoras.  Las fugas de tuber\u00edas viejas y rotas provocaron una de las peores contaminaci\u00f3n ambiental del mundo, provocando pobreza y enfermedades, obstaculizando la pesca y haciendo que gran parte de la regi\u00f3n fuera inhabitable.  Cuando la poblaci\u00f3n se rebel\u00f3, nueve activistas fueron ahorcados por el r\u00e9gimen militar.  Shell fue declarada responsable de los da\u00f1os causados \u200b\u200bpor las filtraciones en 2021 y condenada a pagar una indemnizaci\u00f3n.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"954a-4e1d-50de-4d4b-fd72-2b1f-9615-008d\">\n<p>      Shell encuentra dif\u00edciles los movimientos de protesta y trata de silenciarlos con la ayuda de costosos abogados. <a rel=\"nofollow noopener\" href=\"https:\/\/www.theguardian.com\/business\/2023\/nov\/09\/shell-sues-greenpeace-over-fossil-fuel-protest-in-north-sea?CMP=Share_iOSApp_Other\" target=\"_blank\">Esto es lo que exige la empresa a Greenpeace <\/a>una asombrosa indemnizaci\u00f3n de 2,1 millones de d\u00f3lares porque los activistas hab\u00edan ocupado una plataforma petrolera en el mar.  Shell quiere prohibir a Greenpeace en todo el mundo protestar contra la infraestructura de Shell en el mar y en los puertos.  Si esto sucede, las reclamaciones podr\u00edan ascender a hasta 8,6 millones de d\u00f3lares.  Las cantidades astron\u00f3micas parecen destinadas principalmente a eliminar el molesto movimiento ambiental.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"e96c-2982-b8e3-c93e-1b15-da10-02ed-71f9\">\n<p>      Bombear millones de litros de combustible f\u00f3sil, maquillar de verde su historia, apoyar reg\u00edmenes b\u00e9licos equivocados y silenciar a activistas;  No me gustar\u00eda publicitarlo.  \u00bfQuiz\u00e1s deber\u00edamos boicotearlo en el esp\u00edritu de los a\u00f1os 80?\n    <\/p>\n<div class=\"artstyle__container\" data-element-id=\"9768e8f9-d4c1-46f9-a67f-beee1b8f0aa5\">\n<div class=\"artstyle__container__body\">\n<p class=\"artstyle__container__text\" data-element-id=\"9f0b-9ac9-579c-ed1d-bb7d-6d5f-f958-7900\">\n<p>      En De Consumer, Teun van de Keuken busca cada semana la verdad detr\u00e1s de la campa\u00f1a de marketing.\n    <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><iframe id=\"sim_4121986485_1\" width=\"100%\" frameborder=\"0\" src=\"https:\/\/ims.volkskrant.nl\/optiext\/optiextension.dll?ID=MofMcIOTGz4_eO12zRZyy3_k1B2_oXSIXiWIOsaTs8K2w3C2xx7aMAL2GEFRfcLU_jR7lp0eNt4zq8CfIX&amp;guid=DEDB27FA-C4BD-43D5-A84C-75B3780396F7&amp;frameid=sim_4121986485_1&amp;reference=\" loading=\"lazy\"><\/iframe> <\/p>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lea tambi\u00e9n<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.volkskrant.nl\/columns-van-de-dag\/misschien-moeten-we-in-de-geest-van-de-jaren-tachtig-een-boycotje-tegen-shell-beginnen~bf5b8047\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-23<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teun de la cocina12 de noviembre de 202313:14 Hace unas semanas escrib\u00ed sobre la campa\u00f1a Greenwashing de Shell,<\/p>\n","protected":false},"author":1,"featured_media":1042573,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[205,1584,110,6630,2946,4216,36,5867,11330],"class_list":["post-1042572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-anos","tag-boicot","tag-contra","tag-deberiamos","tag-estilo","tag-iniciar","tag-los","tag-quizas","tag-shell"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042572"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042573"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}