{"id":1042457,"date":"2023-11-12T10:34:08","date_gmt":"2023-11-12T10:34:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/grito-desde-el-corazon-de-nikita-21-gravemente-enferma-de-zuidwolde-se-siente-desesperado\/"},"modified":"2023-11-12T10:34:12","modified_gmt":"2023-11-12T10:34:12","slug":"grito-desde-el-corazon-de-nikita-21-gravemente-enferma-de-zuidwolde-se-siente-desesperado","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/grito-desde-el-corazon-de-nikita-21-gravemente-enferma-de-zuidwolde-se-siente-desesperado\/","title":{"rendered":"Grito desde el coraz\u00f3n de Nikita (21), gravemente enferma, de Zuidwolde: &#8220;Se siente desesperado&#8221;"},"content":{"rendered":"\n<div __component=\"api.api-text\" type=\"text\" id=\"3c8e8550-f8d4-4aa6-83fd-acc1d3d1892d\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>Mensajes tristes de Zuidwolde.  La situaci\u00f3n de salud de Nikita Heuvelman, de 21 a\u00f1os, no quiere mejorar.  Sufre EDS, un raro trastorno gen\u00e9tico del tejido conectivo que no se trata en los Pa\u00edses Bajos.  Hace poco m\u00e1s de un a\u00f1o, con la ayuda de una exitosa campa\u00f1a de crowdfunding, realiz\u00f3 dos operaciones en Estados Unidos.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"d22d8d0b-2ba4-457e-ba8e-dca5466a1a67\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>Las operaciones parecen haber tenido \u00e9xito, pero el s\u00edndrome de Ehlers-Danlos (SED) ha contraatacado con fuerza y \u200b\u200bha provocado muchas m\u00e1s quejas.  La grave inestabilidad en todas sus articulaciones lo hace especialmente dif\u00edcil.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"08d9a37d-7261-4a5e-910f-588a7583b67b\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>El drenaje colocado en su cabeza tampoco ha mejorado a\u00fan la presi\u00f3n y, por lo tanto, pronto tendr\u00e1 que ser tratada nuevamente en B\u00e9lgica.  Adem\u00e1s, tiene graves molestias debido a compresiones vasculares (venas que se presionan para cerrarlas).  Esto requerir\u00e1 una operaci\u00f3n importante en el futuro.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"3bdfb0a2-6b53-45e4-b645-dfd94065ace1\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>Debido a todas estas quejas, Nikita est\u00e1 pasando por un momento muy dif\u00edcil mentalmente, dice.  &#8220;Cansado de la vida, de no dormir sino de caer, completamente agotado. Se siente desesperado, sin saber por d\u00f3nde empezar, d\u00edas y noches enteros con miedo. Se siente tan solo e injusto. \u00bfPor qu\u00e9? \u00bfQu\u00e9 hice para merecer esto? Y No, ya no soy (espero) la valiente, valiente y fuerte Nikita&#8221;.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"54d368f3-5d8a-441b-b0bc-95676206c105\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>La Madre Brenda Huisjes dice: &#8220;Espero poder darles otra actualizaci\u00f3n dentro de un tiempo, pero por ahora necesitamos toda la energ\u00eda para pasar los d\u00edas&#8221;.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"a405bdb5-79a3-4c8e-9096-11fcb5c9737f\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<div class=\"text\" data-v-52a59154=\"\">Con muchos tratamientos por delante, la familia a\u00fan puede necesitar todo el apoyo.  Puedes donar a trav\u00e9s del sitio web. <a rel=\"nofollow noopener\" href=\"https:\/\/nikitawilweerleven.nl\/doneer\/\" class=\"external\" target=\"_blank\">Nikita quiere vivir de nuevo.<\/a>.<\/div>\n<p> <!----><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rtvdrenthe.nl\/nieuws\/16033822\/hartekreet-van-doodzieke-nikita-21-uit-zuidwolde-het-voelt-uitzichtloos\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-41<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mensajes tristes de Zuidwolde. La situaci\u00f3n de salud de Nikita Heuvelman, de 21 a\u00f1os, no quiere mejorar. Sufre<\/p>\n","protected":false},"author":1,"featured_media":1042458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2390,2479,13760,215341,6530,8249,12893,6757,113781,8939,202379,40271],"class_list":["post-1042457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-corazon","tag-desde","tag-desesperado","tag-eds","tag-enferma","tag-gravemente","tag-grito","tag-nikita","tag-nikita-heuvelman","tag-siente","tag-surwolde","tag-zuidwolde"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042457"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042458"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}