{"id":1042294,"date":"2023-11-12T07:37:10","date_gmt":"2023-11-12T07:37:10","guid":{"rendered":"https:\/\/teknomers.com\/es\/la-maldicion-de-cervinia-continua-el-segundo-descenso-tambien-ha-sido-cancelado\/"},"modified":"2023-11-12T07:37:14","modified_gmt":"2023-11-12T07:37:14","slug":"la-maldicion-de-cervinia-continua-el-segundo-descenso-tambien-ha-sido-cancelado","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/la-maldicion-de-cervinia-continua-el-segundo-descenso-tambien-ha-sido-cancelado\/","title":{"rendered":"La maldici\u00f3n de Cervinia contin\u00faa: el segundo descenso tambi\u00e9n ha sido cancelado"},"content":{"rendered":"\n<p><h2 class=\"is-subtitle\">Otra fuerte nevada y otro fuerte viento a gran altura: se ha decidido la cancelaci\u00f3n del descenso de hoy.  El pr\u00f3ximo fin de semana en Gran Becca ser\u00e1 el turno de las mujeres: pero \u00bfhabr\u00e1 esqu\u00ed?<\/h2>\n<\/p>\n<div>\n<p>  La nieve ca\u00edda durante la noche y el fuerte viento a gran altura obligaron a los organizadores a cancelar tambi\u00e9n la segunda Copa del Mundo de descenso masculino en Zermatt\/Cervinia.  Por segundo a\u00f1o consecutivo los jet men no correr\u00e1n en la pista <i class=\"italic\">gran beca<\/i> al pie del Matterhorn, una ruta en la que desde hace a\u00f1os parece acecharse una peque\u00f1a maldici\u00f3n entre el mal tiempo y las dificultades constructivas.<\/p>\n<\/div>\n<div>\n<p>Ahora la esperanza de celebrar la primera carrera transfronteriza entre dos naciones diferentes -en este caso Suiza e Italia- en la historia de la Copa del Mundo de esqu\u00ed alpino est\u00e1 puesta en el pr\u00f3ximo fin de semana, cuando est\u00e9n previstas dos carreras de descenso femenino.  La Federaci\u00f3n Internacional de Esqu\u00ed (Fis) decidir\u00e1 en las pr\u00f3ximas semanas las posibles fechas y lugares para las dos pruebas masculinas reprogramadas.<\/p>\n<\/div>\n<div>\n<div class=\"bck-copyright\">\n<p class=\"is-above-copyright\"><time datetime=\"2023-11-12T07:45:07+01:00\"><\/p>\n<p>            12 de noviembre &#8211; 7:45 a.m.<br \/>\n          <\/time><\/p>\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Sport-Invernali\/Sci-Alpino\/Coppa-Mondo-Sci\/12-11-2023\/coppa-mondo-sci-cancellata-anche-seconda-discesa-zermatt-cervinia-4701641037202.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Otra fuerte nevada y otro fuerte viento a gran altura: se ha decidido la cancelaci\u00f3n del descenso de<\/p>\n","protected":false},"author":1,"featured_media":1042295,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[215304,4982,212320,718,29251,1122,215305,28030,930,1382,733,119127],"class_list":["post-1042294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-ascendencia-cerviniana","tag-cancelado","tag-cervinia","tag-continua","tag-copa-del-mundo-de-esqui","tag-descenso","tag-descenso-zermatt","tag-maldicion","tag-segundo","tag-sido","tag-tambien","tag-zermatt-cervinia"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042294"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042295"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}