{"id":1042199,"date":"2023-11-12T05:41:02","date_gmt":"2023-11-12T05:41:02","guid":{"rendered":"https:\/\/teknomers.com\/es\/mundial-de-clubes-de-balonmano-en-arabia-saudita-fuchse-berlin-en-la-final-contra-el-sc-magdeburg\/"},"modified":"2023-11-12T05:41:06","modified_gmt":"2023-11-12T05:41:06","slug":"mundial-de-clubes-de-balonmano-en-arabia-saudita-fuchse-berlin-en-la-final-contra-el-sc-magdeburg","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/mundial-de-clubes-de-balonmano-en-arabia-saudita-fuchse-berlin-en-la-final-contra-el-sc-magdeburg\/","title":{"rendered":"Mundial de clubes de balonmano en Arabia Saudita: F\u00fcchse Berlin en la final contra el SC Magdeburg"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 11 de noviembre de 2023 20:40<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>El campe\u00f3n defensor SC Magdeburg hizo perfecta la final germano-alemana en el IHF Super Globe en Arabia Saudita contra el F\u00fcchse Berlin.  Berl\u00edn elimin\u00f3 sorprendentemente al FC Barcelona.<\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>En la nueva edici\u00f3n de la final de la Liga de Campeones de junio, los jugadores de balonmano de Magdeburgo ganaron el s\u00e1bado (11 de noviembre de 2023) la segunda semifinal contra el Barlinek Industria Kielce con 28:24 (15:14).<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>La final tendr\u00e1 lugar el domingo (18:15 horas).  El mejor tirador del SCM fue Omar Ingi Magnusson con seis goles.  Magdeburgo tuvo un mejor comienzo contra Andreas Wolff y compa\u00f1\u00eda, tom\u00f3 una ventaja de dos goles, pero no logr\u00f3 ampliarla.  El SCM se adelant\u00f3 brevemente con cuatro goles gracias a las paradas de Nikola Portner, pero tras la falta de concentraci\u00f3n del Magdeburgo, Kielce inmediatamente redujo la ventaja a dos goles.  Al final de un tiempo equilibrado, Magdeburg se fue al descanso con una ventaja de un gol. <\/p>\n<h2 id=\"Konzentrierte-Abwehrarbeit\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Trabajo defensivo concentrado<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Ambos equipos mostraron un trabajo defensivo concentrado, el partido se mantuvo relativamente bajo en goles: solo se marcaron cinco goles en los primeros diez minutos despu\u00e9s del descanso.  A las 18:19 (42), Kielce lideraba por primera vez y hab\u00eda realizado algunos cambios defensivos.  Magdeburgo necesit\u00f3 tiempo para adaptarse y recuper\u00f3 la ventaja (21:20\/46).  Poco antes del final el SCM aument\u00f3 su ventaja a dos goles (25:23\/57) y finalmente gan\u00f3 con claridad. <\/p>\n<h2 id=\"Kampf-der-Fuechse-wird-belohnt\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">La lucha de los zorros tiene recompensa<\/h2>\n<p class=\"textabsatz--contains-image  m-six l-five textabsatz columns twelve\">\n<p>El F\u00fcchse Berlin ya hab\u00eda dado una gran sorpresa en la primera semifinal contra el favorito FC Barcelona con 35:34 (16:16, 29:29) despu\u00e9s de la pr\u00f3rroga.  Los mejores lanzadores berlineses fueron Mathias Gidsel con diez goles y Hans Lindberg con ocho goles. <\/p>\n<h2 id=\"Von-Beginn-an-ausgeglichen\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">Equilibrado desde el principio<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>Desde el principio el partido estuvo igualado entre el l\u00edder de la Bundesliga y el once veces campe\u00f3n de la Liga de Campeones.  Los berlineses lograron repetidamente realizar ataques r\u00e1pidos.  A mitad de la primera mitad, los Foxes consiguieron por primera vez alejarse con 12:8.  Pero dos penaltis desviaron al equipo del entrenador Jaron Siewert.  El Barcelona respondi\u00f3 con un parcial de 4-0.<\/p>\n<p>Los Fox tambi\u00e9n desaprovecharon demasiadas oportunidades de primer nivel.  Nada cambi\u00f3 al inicio de la segunda parte.  El Barcelona no s\u00f3lo tom\u00f3 la ventaja por primera vez tras el descanso, sino que la ampli\u00f3 hasta el 20:17.  Pero los Foxes se defendieron y empataron 70 segundos antes del final para poner el marcador 29:29.  Seis segundos antes del final, Lasse Ludwig incluso detuvo un pol\u00e9mico penalti.<\/p>\n<p>La pr\u00f3rroga tambi\u00e9n sigui\u00f3 siendo emocionante.  Nils Lichtlein marc\u00f3 el gol de la victoria 29 segundos antes del final.  El \u00faltimo lanzamiento de los espa\u00f1oles fue bloqueado.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/handball\/fuechse-berlin-im-finale-der-klub-wm-gegen-sc-magdeburg-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 11 de noviembre de 2023 20:40 El campe\u00f3n defensor SC Magdeburg hizo perfecta la final<\/p>\n","protected":false},"author":1,"featured_media":1042200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[20957,1226,1417,1899,110,463,2781,9256,2282,20958,2097,2095],"class_list":["post-1042199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-arabia","tag-balonmano","tag-berlin","tag-clubes","tag-contra","tag-final","tag-fuchse","tag-magdeburg","tag-mundial","tag-saudita","tag-sc-magdeburgo","tag-zorros-berlin"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042199"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042200"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}