{"id":1042152,"date":"2023-11-12T04:29:08","date_gmt":"2023-11-12T04:29:08","guid":{"rendered":"https:\/\/teknomers.com\/es\/jacques-dancona-regresa-a-la-television\/"},"modified":"2023-11-12T04:29:12","modified_gmt":"2023-11-12T04:29:12","slug":"jacques-dancona-regresa-a-la-television","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jacques-dancona-regresa-a-la-television\/","title":{"rendered":"Jacques d&#8217;Ancona regresa a la televisi\u00f3n"},"content":{"rendered":"\n<div __component=\"api.api-text\" type=\"text\" id=\"d52d2e5b-3e68-43fd-923d-fdfe9bb79c8d\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>Jacques d&#8217;Ancona regresa esta noche a la televisi\u00f3n nacional en su papel familiar.  Toma asiento en el jurado del programa <em>Clasificaci\u00f3n del talento<\/em> en SBS6.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"55ea3e35-4c33-425b-9225-a2ab4c3f8ca0\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>D&#8217;Ancona, de 86 a\u00f1os, que vive desde hace a\u00f1os en Paterswolde, forma pareja con Henny Huisman detr\u00e1s de la mesa del jurado.  Los dos aparecieron juntos en De Soundmixshow durante a\u00f1os.  D&#8217;Ancona tambi\u00e9n era miembro del jurado en ese momento, Huisman era el presentador en ese momento.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"2ce04228-aec1-4a33-b612-fbc8b3da550d\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>Esta noche el d\u00fao competir\u00e1 contra el cantante Jeangu Macrooy y la comediante y presentadora Carolien Borgers.  El programa presenta cinco actos de variedades y cinco actos de canto.  El jurado p\u00fablico otorga puntos y esto tambi\u00e9n se aplica a los d\u00faos formados por famosos holandeses.<\/p>\n<p> <!----><\/div>\n<div __component=\"api.api-text\" type=\"text\" id=\"f4e99ab0-fcd9-4618-be72-1fa22ab502e6\" data-v-52a59154=\"\" data-v-e9df7484=\"\">\n<p>D&#8217;Ancona ha aparecido en televisi\u00f3n dos veces recientemente.  Entonces hizo su aparici\u00f3n. <em>la tierra plana<\/em> y luego tambi\u00e9n en <em>Hotel Holanda.<\/em><\/p>\n<p> <!----><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.rtvdrenthe.nl\/nieuws\/16032352\/jacques-dancona-maakt-comeback-op-televisie\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-41<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jacques d&#8217;Ancona regresa esta noche a la televisi\u00f3n nacional en su papel familiar. Toma asiento en el jurado<\/p>\n","protected":false},"author":1,"featured_media":1042153,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[215282,16627,16626,88414,17059,15344,6805,95093,2198],"class_list":["post-1042152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-clasificacion-del-talento","tag-dancona","tag-jacques","tag-jacques-dancona","tag-municipio-de-tynaarlo","tag-paterswolde","tag-regresa","tag-sbs6","tag-television"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042152"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042153"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}