{"id":1042130,"date":"2023-11-12T03:51:16","date_gmt":"2023-11-12T03:51:16","guid":{"rendered":"https:\/\/teknomers.com\/es\/miss-italia-2023-gano-francesca-bergesio-piamontesa-de-19-anos\/"},"modified":"2023-11-12T03:51:19","modified_gmt":"2023-11-12T03:51:19","slug":"miss-italia-2023-gano-francesca-bergesio-piamontesa-de-19-anos","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/miss-italia-2023-gano-francesca-bergesio-piamontesa-de-19-anos\/","title":{"rendered":"Miss Italia 2023: gan\u00f3 Francesca Bergesio, piamontesa de 19 a\u00f1os"},"content":{"rendered":"\n<p><h2 class=\"is-subtitle\">\u00bfQui\u00e9n es la chica que gan\u00f3 el t\u00edtulo de m\u00e1s bella de Italia en la final del s\u00e1bado 11 de noviembre?<\/h2>\n<\/p>\n<div id=\"m33148-33147-33149\">\n<p class=\"paragraph\" spellcheck=\"true\">ella fue elegida <b>Miss Italia 2023<\/b>: se trata de <b>francesca bergesio<\/b>, 19 a\u00f1os, natural de Bra y residente en Cervere, en la zona de Cuneo.  Cabello largo, casta\u00f1o, graduado de la Escuela Secundaria Cl\u00e1sica Europea, reci\u00e9n matriculado en la Facultad de Medicina de Roma.  Empez\u00f3 con la banda <b>Se\u00f1orita Piamonte<\/b>. <\/p>\n<\/div>\n<div id=\"m33169-33168-33170\">\n<h2 class=\"is-h5 is-inline is-uppercase is-mr-r-4 \" spellcheck=\"true\" id=\"m33233-33232-33234\">Miss Italia 2023: la ganadora es Francesca Bergesio<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">&#8220;<b>Me gustar\u00eda especializarme en cirug\u00eda card\u00edaca.<\/b>&#8220;, explic\u00f3 en su hoja de presentaci\u00f3n. Pero adem\u00e1s de su pasi\u00f3n por la medicina, Francesca Bergesio tambi\u00e9n combina una gran<b> amor por actuar<\/b>: &#8220;Me gustar\u00eda ser m\u00e9dico, pero tambi\u00e9n compaginar mi trabajo con el mundo de la moda o el cine, algo que no abandonar\u00e9&#8221;, explic\u00f3 la joven de 19 a\u00f1os.  Sobre el <b>podio<\/b> junto a Francesca Bergesio <b>Ver\u00f3nica Lasa\u00f1a<\/b>Se\u00f1orita Lombard\u00eda de 20 a\u00f1os, e <b>Siria Pozzi<\/b>22 a\u00f1os Miss Cerde\u00f1a 2023.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/attualita\/11-11-2023\/miss-italia-2023-vincitrice-e-francesca-bergesio-tutto-su-di-lei.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es la chica que gan\u00f3 el t\u00edtulo de m\u00e1s bella de Italia en la final del s\u00e1bado<\/p>\n","protected":false},"author":1,"featured_media":1042131,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[205,215278,6685,5575,1275,215279],"class_list":["post-1042130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-anos","tag-bergesio","tag-francesca","tag-gano","tag-italia","tag-piamontesa"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1042130"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1042130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1042131"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1042130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1042130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1042130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}