{"id":1041941,"date":"2023-11-11T23:12:47","date_gmt":"2023-11-11T23:12:47","guid":{"rendered":"https:\/\/teknomers.com\/es\/gran-incendio-en-waste-energy-company-en-la-zona-portuaria-occidental-de-amsterdam\/"},"modified":"2023-11-11T23:12:51","modified_gmt":"2023-11-11T23:12:51","slug":"gran-incendio-en-waste-energy-company-en-la-zona-portuaria-occidental-de-amsterdam","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/gran-incendio-en-waste-energy-company-en-la-zona-portuaria-occidental-de-amsterdam\/","title":{"rendered":"Gran incendio en Waste Energy Company en la zona portuaria occidental de \u00c1msterdam"},"content":{"rendered":"\n<div>\n<p>Esta tarde, alrededor de las 7 p.m., se produjo un incendio en el b\u00fanker de AEB en Waste Energy Company (AEB) en Australiahavenweg en Western Docklands.  All\u00ed se realiza el procesamiento de residuos residuales.  &#8220;Hemos escalado el incendio a un gran incendio para disponer de recursos suficientes para extinguirlo&#8221;, afirm\u00f3 un portavoz de los bomberos. <\/p>\n<\/div>\n<div>\n<p>No est\u00e1 claro qu\u00e9 provoc\u00f3 el incendio en el b\u00fanker de la AEB.  Los bomberos, junto con la AEB, est\u00e1n trabajando para desmantelar la monta\u00f1a de residuos con grandes gr\u00faas.  &#8220;Entonces podremos empezar a extinguir el fuego de forma eficaz, ya que se necesita mucha agua&#8221;, afirm\u00f3 el portavoz.  El fuego fue controlado alrededor de las 21:40 horas y a\u00fan se estaba extinguiendo. <\/p>\n<p>Seg\u00fan el portavoz, pasar\u00e1 alg\u00fan tiempo antes de que se extinga el incendio.  &#8220;En el b\u00fanker hay poca visibilidad y eso dificulta el paso de las gr\u00faas&#8221;.  Los bomberos recomiendan cerrar ventanas y puertas y desconectar la ventilaci\u00f3n en caso de humo.  La formaci\u00f3n de humo se produce principalmente en el edificio, aunque a primera hora de la noche se liber\u00f3 algo de humo.  Nadie sali\u00f3 herido. <\/p>\n<p>No es la primera vez que se produce un incendio en la AEB.  El 3 de mayo de este a\u00f1o se produjo un incendio en la empresa. <a rel=\"nofollow noopener\" href=\"https:\/\/www.at5.nl\/artikelen\/220272\/explosie-bij-aeb-brandweer-kan-nog-niet-naar-binnen\" target=\"_blank\">una explosi\u00f3n<\/a> lugar. <\/p>\n<\/div>\n<p><i>Para ver este contenido debes aceptar las cookies.<!-- --> <button>Administrar cookies<\/button><\/i><\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/327501\/grote-brand-bij-afval-energie-bedrijf-in-westelijk-havengebied-amsterdam\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tarde, alrededor de las 7 p.m., se produjo un incendio en el b\u00fanker de AEB en Waste<\/p>\n","protected":false},"author":1,"featured_media":1041942,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1966,23556,6310,92,8745,4592,17619,49382,1182],"class_list":["post-1041941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-amsterdam","tag-company","tag-energy","tag-gran","tag-incendio","tag-occidental","tag-portuaria","tag-waste","tag-zona"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1041941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1041941"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1041941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1041942"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1041941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1041941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1041941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}