{"id":1041477,"date":"2023-11-11T14:58:03","date_gmt":"2023-11-11T14:58:03","guid":{"rendered":"https:\/\/teknomers.com\/es\/jorginho-esta-de-vuelta-capitan-con-el-arsenal-y-recuperando-la-camiseta-azul\/"},"modified":"2023-11-11T14:58:08","modified_gmt":"2023-11-11T14:58:08","slug":"jorginho-esta-de-vuelta-capitan-con-el-arsenal-y-recuperando-la-camiseta-azul","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/jorginho-esta-de-vuelta-capitan-con-el-arsenal-y-recuperando-la-camiseta-azul\/","title":{"rendered":"Jorginho est\u00e1 de vuelta: capit\u00e1n con el Arsenal y recuperando la camiseta azul"},"content":{"rendered":"\n<div>\n<p><h2 class=\"is-subtitle\">El excelente inicio de temporada con los Gunners, donde Arteta ahora lo considera indispensable, convenci\u00f3 a Spalletti para convocarlo nuevamente a la selecci\u00f3n despu\u00e9s de no haber sido convocado para los dos \u00faltimos partidos.<\/h2>\n<\/p>\n<div class=\"content not-selectable-js\">\n<p class=\"is-author\">De nuestro corresponsal Davide Chinellato<a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/dchinellato\" class=\"author-twitter \" id=\"m12095-12094-12096\" target=\"_blank\"><br \/>\n                <i class=\"icon-gazzetta-g-social-twitter-circle fa-1-2x\"><br \/>\n                    <span class=\"path1\"\/><span class=\"path2\"\/><br \/>\n                <\/i><\/p>\n<p>                @<br \/>\n            <span spellcheck=\"true\" id=\"m12197-12196-12198\">dchinellato<\/span><\/a><\/p>\n<p>        <time class=\"article-date\" datetime=\"2023-11-11\" content=\"2023-11-11T15:51:18+01:00\">11 de noviembre &#8211; 15.51 h<\/p>\n<p>            <span class=\"from-location\">&#8211; Londres<\/span><\/time><\/p>\n<\/div>\n<div class=\"content \" id=\"m12110-12109-12111\">\n<p class=\"paragraph\" spellcheck=\"true\">El Emirates Stadium aplaude y grita su nombre mientras regresa lentamente del banquillo tras la sustituci\u00f3n.  Es el minuto 90 del Arsenal-Sevilla, los Gunners dominaron y Jorginho se mostr\u00f3 gladiador en el centro del campo, iniciando la acci\u00f3n para el primer gol.  Con el brazalete de capit\u00e1n en el brazo, el que luci\u00f3 por la ausencia del titular Martin Odegaard a pesar de llevar s\u00f3lo desde el pasado mes de enero en el Arsenal.  La ovaci\u00f3n de pie forma parte del plato fuerte de este estupendo inicio de temporada para el centrocampista de 31 a\u00f1os, colecci\u00f3n a la que se suma tambi\u00e9n el regreso a la selecci\u00f3n para los partidos decisivos contra Macedonia del Norte y Ucrania en los que Italia A la caza del pase a la Eurocopa 2024. <\/p>\n<\/div>\n<p><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic --><\/p>\n<div class=\"content \" id=\"m12134-12133-12135\">\n<h2 class=\"native-summary-content paragraph-summary is-h5 is-uppercase is-mr-r-4 is-inline \" spellcheck=\"true\" id=\"m12216-12215-12217\">devolver<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Jorginho no hab\u00eda sido considerado por Spalletti para las dos primeras convocatorias, incluida la del partido contra Inglaterra del 17 de octubre.  El centrocampista fue una piedra angular de la gesti\u00f3n de Mancini, uno de los h\u00e9roes del triunfo de la Eurocopa 2020, pero su n\u00famero de partidos con la selecci\u00f3n nacional se qued\u00f3 estancado en 48, perdiendo su \u00faltima aparici\u00f3n el 15 de junio en la semifinal de la Liga de las Naciones contra Espa\u00f1a. 2-1.  Uno en el que Jorginho hab\u00eda sido titular, siendo sustituido en el minuto 60.  Las primeras elecciones del nuevo t\u00e9cnico, combinadas con el reducido tiempo de juego que iba acumulando el centrocampista en el Arsenal, parec\u00edan apuntar en direcciones diferentes.  Pero en las \u00faltimas semanas Jorginho ha encontrado constantemente el campo con los Gunners, donde se le aprecia mucho m\u00e1s all\u00e1 de la contribuci\u00f3n que hace cuando juega.  Y actuaciones como la del Sevilla convencieron a Spalletti para incluirlo en el 29 que intentar\u00e1 conseguir el pase a la Eurocopa de 2024.<\/p>\n<\/div>\n<div class=\"content \" id=\"m12144-12143-12145\">\n<h2 class=\"native-summary-content paragraph-summary is-h5 is-uppercase is-mr-r-4 is-inline \" spellcheck=\"true\" id=\"m12222-12221-12223\">renacimiento<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Arteta siempre ha sido un gran admirador de Jorginho, a quien considera el centrocampista ideal para desplegar al frente de la defensa en su m\u00f3dulo de juego.  A principios de temporada, el papel lo ocupaba Declan Rice, el gran fichaje del verano del Arsenal, eje de una formaci\u00f3n fluida en la que Alex Zinchenko le echaba una mano en el centro del campo, centralizando desde la posici\u00f3n de lateral izquierdo, con Odegaard y Kai Havertz. , nominalmente sus otros dos centrocampistas, para apoyar el ataque.  Las dificultades del alem\u00e1n, sin embargo, empujaron a Arteta a cambiar su formaci\u00f3n, para insertar un mediocampista extra, moviendo a Rice al puesto de n\u00famero 8 que ten\u00eda Grant Xhaka el a\u00f1o pasado.  Y aqu\u00ed es donde Jorginho entr\u00f3 en escena.  \u201cEs un jugador incre\u00edble, un l\u00edder, una persona muy inteligente con cualidades para mejorar nuestro equipo.  Y tiene una gran experiencia, habiendo ganado una Eurocopa y una Liga de Campeones entre otras cosas\u201d, dijo Arteta sobre el italiano.<\/p>\n<\/div>\n<div class=\"content \" id=\"m12160-12159-12161\">\n<h2 class=\"native-summary-content paragraph-summary is-h5 is-uppercase is-mr-r-4 is-inline \" spellcheck=\"true\" id=\"m12231-12230-12232\">l\u00edder<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Arteta ve en Jorginho un l\u00edder, un general en el campo, alguien capaz de transmitir tranquilidad a sus compa\u00f1eros y gestionar el ritmo del equipo.  Lo vio enseguida, desde que el Arsenal lo fich\u00f3 procedente del Chelsea, donde era capit\u00e1n, al final del pasado mercado de fichajes de enero.  El azulgrana se abri\u00f3 paso inmediatamente en el vestuario de los gunners, gan\u00e1ndose a sus compa\u00f1eros con su personalidad.  \u201cTiene una gran experiencia, nos aporta muchas cosas dentro del campo pero tambi\u00e9n fuera de \u00e9l &#8211; dijo de \u00e9l Takehiro Tomiyasu, elegido mejor jugador del Arsenal en octubre por la afici\u00f3n -.  Es uno de los mejores ejemplos posibles para todos nosotros y personalmente aprend\u00ed muchas cosas de \u00e9l&#8221;.  Jorginho volvi\u00f3 al once titular en el s\u00faper partido contra el Manchester City el 8 de octubre y no ha vuelto a estar de baja desde entonces.  Y en los \u00faltimos tres partidos hered\u00f3 la capitan\u00eda de Odegaard.  En el campo manda, dirige, crea.  Ayuda al Arsenal a mejorar.  Es una de las razones por las que Arteta lo aprecia tanto.  Y son las mismas cualidades las que empujaron a Spalletti a llamarlo de nuevo a la selecci\u00f3n nacional.<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js\">\n<div class=\"bck-copyright\">\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/div><\/div>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Europei\/11-11-2023\/jorginho-e-tornato-capitano-con-l-arsenal-e-convocato-da-spalletti-in-nazionale.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El excelente inicio de temporada con los Gunners, donde Arteta ahora lo considera indispensable, convenci\u00f3 a Spalletti para<\/p>\n","protected":false},"author":1,"featured_media":1041478,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[4673,1015,1381,3066,99,97,22757,11805,344],"class_list":["post-1041477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-arsenal","tag-azul","tag-camiseta","tag-capitan","tag-con","tag-esta","tag-jorginho","tag-recuperando","tag-vuelta"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1041477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1041477"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1041477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1041478"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1041477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1041477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1041477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}