{"id":1037752,"date":"2023-11-09T07:39:27","date_gmt":"2023-11-09T07:39:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/tim-stutzle-realmente-fuerte-en-la-victoria-de-los-senadores-en-toronto\/"},"modified":"2023-11-09T07:39:31","modified_gmt":"2023-11-09T07:39:31","slug":"tim-stutzle-realmente-fuerte-en-la-victoria-de-los-senadores-en-toronto","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/tim-stutzle-realmente-fuerte-en-la-victoria-de-los-senadores-en-toronto\/","title":{"rendered":"Tim St\u00fctzle realmente fuerte en la victoria de los Senadores en Toronto"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<div class=\"seitenkopf\">\n<div class=\"seitenkopf__data columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n<div class=\"seitenkopf__title\">\n<p class=\"metatextline\">A partir de: 9 de noviembre de 2023 7:43 a.m.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"textabsatz columns twelve  m-ten  m-offset-one l-eight l-offset-two\">\n        <strong>El profesional alem\u00e1n del hockey sobre hielo Tim St\u00fctzle llev\u00f3 a los Ottawa Senators a la victoria contra los Toronto Maple Leafs con cuatro goles.<\/strong>\n    <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>El jugador nacional de hockey prepar\u00f3 tres goles en el 6:3 del mi\u00e9rcoles por la tarde (8 de noviembre de 2023, hora local) y marc\u00f3 \u00e9l mismo el gol del 5:3.<\/p>\n<div class=\"copytext-element-wrapper columns twelve\">\n<div class=\"columns twelve m-ten m-offset-one l-eight l-offset-two copytext-element-wrapper__spacing\">\n<ul class=\"buttongroup buttongroup--copytext\">\n<li class=\"buttongroup__item\">\n<p>        <span class=\"btn__label\">5ta semana de juego<\/span><br \/>\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\" class=\"icon icon--arrow--right\" role=\"img\"><title>Flecha correcta<\/title>\n    <g>\n        <path d=\"M23.21,16L12.52,26.7c-0.4,0.4-1.04,0.4-1.43,0c-0.4-0.4-0.4-1.04,0-1.43L20.37,16l-9.28-9.27 c-0.4-0.4-0.4-1.04,0-1.43c0.4-0.4,1.04-0.4,1.43,0L23.21,16z\"\/>\n    <\/g>\n<\/svg><\/p>\n<\/li>\n<\/ul><\/div>\n<\/div>\n<h2 id=\"Stuetzle-mit-guter-Scorerbilanz\" class=\"meldung__subhead columns twelve  m-ten  m-offset-one l-eight l-offset-two liveblog--anchor\">St\u00fctzle con un buen r\u00e9cord goleador<\/h2>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>St\u00fctzle suma doce asistencias y tres goles esta temporada en la NHL.  Para los Senadores, fue un alivio muy necesario en Toronto despu\u00e9s de s\u00f3lo una victoria en seis partidos. <\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">\n<p>&#8220;Son dos jugadores excepcionales. Todos sabemos lo que G y Timmy pueden hacer en el hielo&#8221;, dijo Mathieu Joseph sobre St\u00fctzle y Claude Giroux, que anotaron dos goles y una asistencia.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sportschau.de\/eishockey\/nhl\/eishockey-nhl-stuetzle-toronto-100.html\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de: 9 de noviembre de 2023 7:43 a.m. El profesional alem\u00e1n del hockey sobre hielo Tim<\/p>\n","protected":false},"author":1,"featured_media":1037753,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[453,3390,36,7452,1663,39251,22049,10527,12321,2242],"class_list":["post-1037752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-fuerte","tag-hockey-sobre-hielo","tag-los","tag-nhl","tag-realmente","tag-senadores","tag-stutzle","tag-tim","tag-toronto","tag-victoria"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1037752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1037752"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1037752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1037753"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1037752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1037752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1037752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}