{"id":1031841,"date":"2023-11-05T15:01:07","date_gmt":"2023-11-05T15:01:07","guid":{"rendered":"https:\/\/teknomers.com\/es\/en-vivo-chiefs-y-dolphins-en-frankfurt\/"},"modified":"2023-11-05T15:01:11","modified_gmt":"2023-11-05T15:01:11","slug":"en-vivo-chiefs-y-dolphins-en-frankfurt","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/en-vivo-chiefs-y-dolphins-en-frankfurt\/","title":{"rendered":"EN VIVO: Chiefs y Dolphins en Frankfurt"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:57<\/p>\n<p>&#8220;Inicio en falso&#8221;<\/p>\n<div class=\"liveticker-content\">\u00a1Idioma alem\u00e1n, lenguaje sencillo!  Al menos para el \u00e1rbitro principal Clay Martin.<\/div>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:55<\/p>\n<p>Tercero hasta Kelce, pero no es suficiente<\/p>\n<p>Mahomes le sirve brevemente el tercer intento a Kelce, pero antes de que pueda despegar para el primer intento, dos jugadores defensivos ya est\u00e1n sobre \u00e9l y Miami env\u00eda la ofensiva del oponente fuera del campo.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:52<\/p>\n<p>El turno de Kansas otra vez<\/p>\n<p>Es importante para los Chiefs poder establecer el juego terrestre temprano.  La semana pasada Pacheco tambi\u00e9n fue responsable de una p\u00e9rdida de bal\u00f3n, aqu\u00ed logr\u00f3 \u00e9l solo el primer intento en dos intentos.  Despu\u00e9s de eso, la defensa de los Dolphins finalmente puede lucirse por primera vez y presionar decisivamente a Mahomes para que su pase no llegue.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:51<\/p>\n<p>\u00a1Ponerse a cubierto!<\/p>\n<div class=\"liveticker-content\">\u00a1Es mejor agacharse que ser atropellado!<\/div>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:45<\/p>\n<p>\u00a1Tua Tagovailoa cae!<\/p>\n<p>La defensa de los Chiefs detiene bien dos jugadas terrestres de los Dolphins, y el invitado nominal se enfrenta a un tercer intento largo.  El entrenador Mike McDaniel se toma un tiempo muerto para preparar a su equipo, pero el receptor Claypool est\u00e1 demasiado impaciente y le impone a Miami una penalizaci\u00f3n por salida en falso.  Pero como el mismo paso en falso tambi\u00e9n les ocurri\u00f3 a los Chiefs, las cinco yardas fueron devueltas de inmediato.  Cuando finalmente comienza la jugada, el cornerback Jaylen Watson corre desde la derecha hacia Tua Tagovailoa, desbloqueado, y este voluntariamente se tira al suelo para evitar recibir el fuerte golpe.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:43<\/p>\n<p>\u00bfC\u00f3mo reacciona Miami?<\/p>\n<p>Kansas City s\u00f3lo necesit\u00f3 siete jugadas para anotar un touchdown.  Veamos qu\u00e9 tiene para ofrecer ahora la ofensiva m\u00e1s potente de la liga.  Tua tambi\u00e9n tuvo un comienzo seguro con un pase para el primer intento.  Despu\u00e9s de eso hay un breve descanso porque Waddle se lesiona del lado de los Dolphins durante la siguiente jugada.  El receptor tuvo un desafortunado choque con un oponente.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\" data-event_action=\"goal\" data-event_kind=\"extrakick\">\n<p>15:41<\/p>\n<p>Punto extra de H. Butker (Chiefs) para poner el 0:7<\/p>\n<div class=\"person-image person-image-\"><\/div>\n<p>\u00a1El intento de punto extra de H. Butker es bueno!<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\" data-event_action=\"goal\" data-event_kind=\"touchdown\">\n<p>15:41<\/p>\n<p>Touchdown de R. Rice (Chiefs) para poner el 0:6<\/p>\n<div class=\"person-image person-image-\"><img decoding=\"async\" onerror=\"this.style.display='none'\" data-gender=\"male\" loading=\"lazy\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/11\/1699196467_343_EN-VIVO-Chiefs-y-Dolphins-en-Frankfurt.png\" alt=\"Arroz Rashee\" title=\"Arroz Rashee\"\/><\/div>\n<div class=\"liveticker-content\">\u00a1Qu\u00e9 declaraci\u00f3n en el ataque inicial de los Chiefs!  Los pases vuelan a trav\u00e9s de la defensa como un cuchillo caliente a trav\u00e9s de la mantequilla y antes de que Miami se d\u00e9 cuenta, Rice es bloqueado por la izquierda y corre f\u00e1cilmente hacia la zona de anotaci\u00f3n para un touchdown.  Para lo que les est\u00e1 sucediendo a los Dolphins en este momento, &#8220;superaci\u00f3n&#8221; es quedarse corto.  Los \u00e1rbitros hab\u00edan indicado previamente un touchdown cuando Mahomes pas\u00f3 el bal\u00f3n a Watson, pero seg\u00fan las im\u00e1genes, revocaron la decisi\u00f3n porque el receptor fall\u00f3 por poco atrapar el bal\u00f3n.<\/div>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>3:36 p.m.<\/p>\n<p>Siguiente bomba adelante<\/p>\n<div class=\"liveticker-content\">\u00a1Los Jefes no toman prisioneros!  El siguiente pase ya est\u00e1 hecho, esta vez a Gray.  Hasta ahora, Mahomes ha estado distribuyendo bien el cuero, lo que no ha sido consistente a lo largo de la temporada.<\/div>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>3:34 p.m.<\/p>\n<p>Los jefes comienzan<\/p>\n<p>Los Chiefs est\u00e1n iniciando su ofensiva&#8230; Y est\u00e1 bastante animada.  Llegan los dos primeros pases a Vald\u00e9s-Scantling y Kelce y luego Pacheco corre unos metros m\u00e1s.  No es suficiente para otro primer intento, pero eso lo logra Moore, quien se desv\u00eda hacia la derecha con Mahomes y recoge el pase con seguridad.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\" data-event_action=\"match\" data-event_kind=\"game-start\">\n<p>3:32 p.m.<\/p>\n<p>Empezar juego<\/p>\n<p>Inicio del partido entre los Miami Dolphins y los Kansas City Chiefs.  El juego est\u00e1 en marcha.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>3:08 p.m.<\/p>\n<p>Suenan los himnos nacionales<\/p>\n<p>Est\u00e1 empezando a hacer calor ah\u00ed abajo, en el c\u00e9sped.  Los himnos nacionales se interpretar\u00e1n con el habitual patetismo y luego el deporte podr\u00e1 comenzar de inmediato.  A Gregor H\u00e4gele se le permite tomar el micr\u00f3fono en representaci\u00f3n de Alemania.  \u00bfTienes que saberlo?<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>15:05<\/p>\n<p>\u00a1Travic Kelce est\u00e1 listo!<\/p>\n<div class=\"liveticker-content\">Al parecer, Kelce est\u00e1 ansioso por el enfrentamiento en Frankfurt.  \u00bfT\u00fa tambi\u00e9n?<\/div>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>3:01 p.m.<\/p>\n<p>Tagovailoa sigue sin signo de exclamaci\u00f3n<\/p>\n<p>Una prueba contra una buena defensa es perfecta para la mejor ofensiva estad\u00edstica de Miami.  Porque a Tagovailoa todav\u00eda le falta un \u00e9xito real y prestigioso contra un equipo de primer nivel.  Cayeron silenciosamente contra los Bills y los Eagles, y solo hubo explosiones ofensivas contra jugadores inesperados como Denver o los Panthers.  En este sentido, ser\u00e1 emocionante ver si realmente podemos unirnos hoy a las filas de los candidatos al t\u00edtulo o si nuevamente perderemos en un duelo a la altura de los ojos.  \u00a1Nos comunicaremos con usted de inmediato con el inicio!<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>14:56<\/p>\n<p>Tyreek Hill ahora con los Dolphins<\/p>\n<p>Algunos aficionados de la Champions recordar\u00e1n con dolor que antes de la temporada tuvieron que entregar a uno de sus mejores jugadores, Tyreek Hill, al rival de hoy por motivos econ\u00f3micos.  Y hasta ahora, ha atrapado m\u00e1s de 1,000 yardas, casi tanto como todos los receptores abiertos de los Chiefs combinados.  Pero Hill cree que su ex equipo podr\u00e1 superar estos problemas a lo largo de la temporada.  Adem\u00e1s, Kansas City pudo construir una defensa superior con las selecciones del draft y los jugadores del intercambio.  En este sentido, si se analiza detenidamente, ciertamente se puede hablar de una situaci\u00f3n en la que todos ganan.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>14:52<\/p>\n<p>\u00bfDeslices o problemas reales contra Denver?<\/p>\n<p>Muchos factores se juntaron para los Chiefs la semana pasada.  Mahomes estaba enfermo y muchas p\u00e9rdidas de bal\u00f3n le complicaron la vida a la ofensiva.  Pero para ser honesto, los problemas que hab\u00edan sido evidentes a lo largo de la temporada se acumularon en el juego contra los Broncos, naturalmente motivados.  Aunque Mahomes todav\u00eda puede ser considerado uno de los tres mejores mariscales de campo estad\u00edsticamente, su ofensiva parece un poco vulnerable a veces.  Esto se debe principalmente a que los Chiefs tienen que depender de su juego a\u00e9reo y este a\u00f1o, aparte de Travis Kelce, ning\u00fan receptor ha podido pasar a primer plano.<\/p>\n<\/div>\n<div class=\"liveticker\" data-topic_ids=\"5322\" data-sport_id=\"16\" data-competition_id=\"494\">\n<p>14:48<\/p>\n<p>Mahomes contra Tua<\/p>\n<p>Realmente no es un partido como cualquier otro en Frankfurt a partir de las 15:30 horas.  Cuando la Serie Internacional se detenga en Alemania despu\u00e9s de tres semanas en Londres, los Chiefs y Dolphins, quiz\u00e1s los mejores equipos de la AFC en este momento, competir\u00e1n entre s\u00ed.  Un duelo directo como este podr\u00eda ser decisivo en la decisi\u00f3n final por la corona de la conferencia.  Adem\u00e1s, Miami todav\u00eda tiene un desaf\u00edo en su propia divisi\u00f3n, porque con solo una derrota menos, tanto los Bills como los Jets est\u00e1n al acecho.  Kansas City no tiene estos problemas en la AFC Oeste, pero despu\u00e9s de una actuaci\u00f3n sorprendentemente d\u00e9bil en Denver recientemente, el campe\u00f3n tiene hoy la oportunidad de redimirse en el gran escenario.<\/p>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne5804150\/live-in-frankfurt-chiefs-fordern-dolphins-im-top-duell\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>15:57 &#8220;Inicio en falso&#8221; \u00a1Idioma alem\u00e1n, lenguaje sencillo! Al menos para el \u00e1rbitro principal Clay Martin. 15:55 Tercero<\/p>\n","protected":false},"author":1,"featured_media":999073,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[154314,1407,105760,34422,78091,8762,5624,6363,6366,202981,214031,1402,302],"class_list":["post-1031841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-2023-2024","tag-alemania","tag-chiefs","tag-delfines-de-miami","tag-dolphins","tag-francfort-del-meno","tag-frankfurt","tag-jefes-de-kansas-city","tag-nfl","tag-parque-del-deutsche-bank","tag-semana-9","tag-teletipo-en-vivo","tag-vivo"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1031841"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/999073"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1031841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1031841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1031841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}