{"id":1031773,"date":"2023-11-05T13:52:13","date_gmt":"2023-11-05T13:52:13","guid":{"rendered":"https:\/\/teknomers.com\/es\/por-que-lo-pequeno-no-es-bello-cuando-se-trata-de-desarrollo\/"},"modified":"2023-11-05T13:52:13","modified_gmt":"2023-11-05T13:52:13","slug":"por-que-lo-pequeno-no-es-bello-cuando-se-trata-de-desarrollo","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/por-que-lo-pequeno-no-es-bello-cuando-se-trata-de-desarrollo\/","title":{"rendered":"Por qu\u00e9 lo peque\u00f1o no es bello cuando se trata de desarrollo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desbloquea el Editor&#8217;s Digest gratis<\/p>\n<p class=\"article__content-sign-up-topic-description\"><span>Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/span><\/p>\n<p><iframe class=\"article__content-sign-up-iframe close\" scrolling=\"no\" id=\"signUpIframe\" data-prev-url=\"\/register\/in-article-sign-up?ft-content-uuid=90b13a05-0d91-4aac-9faf-738900c1389c\"><\/iframe><\/div>\n<div id=\"article-body\">\n<p>Se podr\u00eda llamar \u201cel culto a lo peque\u00f1o\u201d, la idea de que las peque\u00f1as empresas y los peque\u00f1os agricultores son la columna vertebral de las econom\u00edas pobres, la clave para la resiliencia social y la mejor esperanza para eliminar la pobreza.  Lo ves en el \u00e9nfasis en los microcr\u00e9ditos, las peque\u00f1as empresas y la financiaci\u00f3n de proyectos comunitarios. <\/p>\n<p>Todas estas intervenciones est\u00e1n muy bien.  Las redes de seguridad, la banca telef\u00f3nica y los caminos rurales pueden mejorar las perspectivas de ingresos de los m\u00e1s pobres.  por algunos <a rel=\"nofollow noopener\" href=\"https:\/\/www.csis.org\/analysis\/supporting-small-and-medium-enterprises-sub-saharan-africa-through-blended-finance#:~:text=In%20Africa%2C%20SMEs%20provide%20an,all%20of%20which%20are%20micro.\" data-trackable=\"link\" target=\"_blank\">estimados<\/a>, las peque\u00f1as y medianas empresas representan el 80 por ciento de la producci\u00f3n econ\u00f3mica de \u00c1frica.  Pero el culto a lo peque\u00f1o necesita un correctivo.  \u00c1frica necesita pensar en grande.<\/p>\n<p>En las ciudades de todo el continente, un \u201cmicroempresario\u201d, como se dice en la jerga del desarrollo, podr\u00eda ser simplemente el propietario de una curtidur\u00eda, una f\u00e1brica de metales o una f\u00e1brica de tejas.  Lo m\u00e1s probable es que sea una mujer que esquiva el tr\u00e1fico con una bandeja en la cabeza vendiendo comida a una peque\u00f1a \u00e9lite propietaria de veh\u00edculos con tracci\u00f3n en las cuatro ruedas.  O un hombre con un \u201cnegocio de lustrabotas\u201d compuesto por un trapo, una caja rota y media lata de bet\u00fan.<\/p>\n<p>Las ciudades de la regi\u00f3n est\u00e1n llenas de gente sin empleo formal que lucha por ganarse la vida.  Son supervivientes que trabajan muchas horas para ganar una miseria.  Si el futuro de \u00c1frica depende de su trabajo, entonces \u00c1frica est\u00e1 en problemas.  Ning\u00fan acceso a la financiaci\u00f3n convertir\u00e1 a esas \u201cempresas\u201d en los pilares de una econom\u00eda moderna.<\/p>\n<p>Paul Collier, autor de <em>Los mil millones inferiores<\/em>dice de la <a rel=\"nofollow noopener\" href=\"https:\/\/www.thetimes.co.uk\/article\/if-you-want-to-help-africa-let-business-lead-the-way-kc8md0dhg\" data-trackable=\"link\" target=\"_blank\">efecto transformador<\/a> de empresas complejas: \u201cLas empresas realizan un milagro de productividad al organizar a los trabajadores para obtener beneficios de la escala y la especializaci\u00f3n\u201d.  El estafador de carretera no es especializado ni productivo.  Idealizar una fuerza laboral tan atomizada es aceptar la pobreza a perpetuidad. <\/p>\n<p>Si muchos empleos urbanos son tan improductivos, \u00bfquiz\u00e1s la gente deber\u00eda quedarse en el campo?  Esa fue la opini\u00f3n de Muhammadu Buhari, ex presidente de Nigeria, quien dijo a los j\u00f3venes \u201cque volvieran a la granja\u201d. <\/p>\n<p>Pero la vida de la mayor\u00eda de los peque\u00f1os agricultores es menos la de Thomas Hardy y m\u00e1s la de John Steinbeck.  Sin irrigaci\u00f3n, fertilizantes, semillas modernas o tractores, la productividad en todo el continente es lamentablemente baja.  Los agricultores m\u00e1s pobres no pueden cultivar lo suficiente para alimentar adecuadamente a sus familias, y mucho menos enviar a sus hijos a la escuela. <\/p>\n<p>Aubrey Hruby, un inversor experimentado en \u00c1frica, <a rel=\"nofollow noopener\" href=\"https:\/\/www.atlanticcouncil.org\/in-depth-research-reports\/issue-brief\/unlocking-africas-agricultural-potential\/\" data-trackable=\"link\" target=\"_blank\">defensores<\/a> el uso intenso de la tecnolog\u00eda para liberar a la agricultura de su dominio de subsistencia.  Los agricultores africanos, dice, normalmente cultivan menos de dos hect\u00e1reas y producen un valor agregado bruto de alrededor de 2.000 d\u00f3lares, una quincuag\u00e9sima parte del agricultor estadounidense promedio.  El \u201cculto al peque\u00f1o agricultor\u201d, afirma, es tan da\u00f1ino como el culto al microempresario.<\/p>\n<p>El milagro econ\u00f3mico de China se bas\u00f3 en trasladar a los agricultores improductivos a las f\u00e1bricas.  Investigaci\u00f3n por el <a rel=\"nofollow noopener\" href=\"https:\/\/acetforafrica.org\/ati\/\" data-trackable=\"link\" target=\"_blank\">Centro Africano para la Transformaci\u00f3n Econ\u00f3mica<\/a>, un grupo de expertos con sede en Accra, muestra c\u00f3mo las econom\u00edas africanas no han logrado hacer esto.  Muchos no s\u00f3lo obtienen malos resultados sino que est\u00e1n retrocediendo.  La medida de diversidad econ\u00f3mica de Acet cay\u00f3 casi 6 puntos entre 2000 y 2020, mientras que la competitividad de las exportaciones no logr\u00f3 aumentar durante ese per\u00edodo desde un sombr\u00edo 13,8.  En promedio, los cinco principales productos de exportaci\u00f3n de los pa\u00edses africanos representan un peligrosamente concentrado 70 por ciento del total.<\/p>\n<p>Las econom\u00edas asi\u00e1ticas y latinoamericanas exitosas construyeron redes industriales complejas.  A veces estaban vinculados a materias primas como el cobre chileno o el aceite de palma de Malasia, pero a menudo a una fuerza laboral educada, una infraestructura confiable y grandes reservas de ahorro.<\/p>\n<p>En \u00c1frica, Lesotho y Mauricio desarrollaron industrias textiles competitivas, Etiop\u00eda estableci\u00f3 una industria de calzado y prendas de vestir basada en cuero de producci\u00f3n nacional y Benin est\u00e1 tratando de transformar anacardos crudos en art\u00edculos que puedan colocarse en los estantes de los supermercados.  Pero esos esfuerzos son muy pocos.<\/p>\n<p>Si el ant\u00eddoto contra lo peque\u00f1o es grande y complejo, al continente no le va bien.  No hay una sola empresa africana en la lista Fortune 500 del mundo. A\u00fan as\u00ed, hay empresas m\u00e1s grandes de lo que parece, muchas de ellas de propiedad familiar.  McKinsey enumer\u00f3 400 empresas africanas con ingresos anuales superiores a mil millones de d\u00f3lares en 2018. Yasmin Kumi <a rel=\"nofollow noopener\" href=\"https:\/\/africaforesight.com\/\" data-trackable=\"link\" target=\"_blank\">Grupo Africano de Prospectiva<\/a> tiene una base de datos de 2.000 empresas con ingresos de entre 20 y 100 millones de d\u00f3lares.<\/p>\n<p>Se necesitan m\u00e1s.  Tambi\u00e9n lo es una ley de competencia agresiva para garantizar que no se duerman en los laureles ni estafen a los clientes.  Las pol\u00edticas necesarias para facilitar las empresas creadoras de empleo no son la pol\u00edtica normal de desarrollo.  Implican tareas como racionalizar el suministro de electricidad, profundizar los mercados de capital, reducir el costo del capital mediante el establecimiento de fondos de pensiones, canalizar el desarrollo hacia empresas a gran escala y fomentar granjas administradas profesionalmente.<\/p>\n<p>Un punto de partida puede ser deshacerse de las nociones rom\u00e1nticas de que los peque\u00f1os agricultores y los microempresarios son la ruta para salir de la pobreza.  Ellos no son.  Su existencia en gran n\u00famero es la definici\u00f3n misma de la pobreza. <\/p>\n<p><em>david.pilling@ft.com<\/em><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ft.com\/content\/90b13a05-0d91-4aac-9faf-738900c1389c\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-56<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desbloquea el Editor&#8217;s Digest gratis Roula Khalaf, editora del FT, selecciona sus historias favoritas en este bolet\u00edn semanal.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[29786,2577,857,1347,231,387,6460],"class_list":["post-1031773","post","type-post","status-publish","format-standard","hentry","category-general","tag-bello","tag-cuando","tag-desarrollo","tag-pequeno","tag-por","tag-que","tag-trata"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1031773"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031773\/revisions"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1031773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1031773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1031773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}