{"id":1031480,"date":"2023-11-05T08:43:56","date_gmt":"2023-11-05T08:43:56","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-principe-william-sorprende-a-todos-durante-el-show-benefico\/"},"modified":"2023-11-05T08:44:00","modified_gmt":"2023-11-05T08:44:00","slug":"el-principe-william-sorprende-a-todos-durante-el-show-benefico","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-principe-william-sorprende-a-todos-durante-el-show-benefico\/","title":{"rendered":"El pr\u00edncipe William sorprende a todos durante el show ben\u00e9fico"},"content":{"rendered":"\n<div id=\"\">\n<p class=\"artstyle__paragraph \" data-element-id=\"1c1a-f94d-5efd-dbff-4c23-3bae-8aee-babf\">\n<p>      En un mensaje en v\u00eddeo, el pr\u00edncipe rindi\u00f3 homenaje a la fallecida periodista brit\u00e1nica Deborah James, fallecida el a\u00f1o pasado a causa de un c\u00e1ncer de colon a la edad de 40 a\u00f1os.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"b176-376b-7922-8fef-f729-e0d7-9e24-0c35\">\n<p>      D\u00e9bora James<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"00b9-8e48-4d5d-1599-94b0-cded-c1a9-1813\">\n<p>      Deborah James fue una periodista y activista brit\u00e1nica que habl\u00f3 p\u00fablicamente sobre su batalla personal contra el c\u00e1ncer de colon.  Se hizo conocida a nivel nacional por su trabajo para crear conciencia sobre el c\u00e1ncer de colon y recaudar dinero para la investigaci\u00f3n de la enfermedad.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"33b8-c8a9-a404-18ba-9a63-d2f5-9599-5e01\">\n<p>      James comparti\u00f3 abiertamente sus experiencias a trav\u00e9s de las redes sociales y varias apariciones en los medios para inspirar, alentar a otros a hacerse controles y estar alerta a los s\u00edntomas.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"b7e1-1bdd-ccca-60bb-4d7f-5c6d-4a5e-7856\">\n<p>      Enfrentarse al c\u00e1ncer<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"503b-130d-d476-c754-11d7-c461-8682-c465\">\n      <i>Enfrentarse al c\u00e1ncer<\/i> es una organizaci\u00f3n ben\u00e9fica global centrada en financiar investigaciones innovadoras sobre el c\u00e1ncer y acelerar el desarrollo de nuevos tratamientos contra el c\u00e1ncer.  La organizaci\u00f3n se fund\u00f3 en el Reino Unido en 2008 y trabaja con varios pa\u00edses para generar conciencia y recaudar fondos para la investigaci\u00f3n del c\u00e1ncer.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"4521-1fcd-3b5b-4703-beb0-461a-53f2-c0da\">\n<p>      Una caracter\u00edstica notable de sus esfuerzos son los programas ben\u00e9ficos de televisi\u00f3n, en los que personalidades conocidas, artistas y pacientes con la enfermedad se re\u00fanen para recaudar fondos y crear conciencia en la lucha contra el c\u00e1ncer.  Estos programas suelen compartir historias personales y rendir homenaje a las personas afectadas por esta enfermedad.\n    <\/p>\n<h3 class=\"artstyle__title \" data-element-id=\"d200-9122-8f8c-f13e-6fda-15cb-1720-4969\">\n<p>      Un mensaje en v\u00eddeo del pr\u00edncipe William<br \/>\n    <\/h3>\n<p class=\"artstyle__paragraph \" data-element-id=\"dd27-8e6d-989a-1d41-d3ed-fdc0-8bb2-698d\">\n<p>      Durante la visita sorpresa del Pr\u00edncipe William, honr\u00f3 a la periodista brit\u00e1nica Deborah James a trav\u00e9s de un mensaje de video.  Destac\u00f3 c\u00f3mo Deborah ha contribuido significativamente a la vida de innumerables personas, rompiendo tab\u00faes que a veces impiden que las personas controlen sus s\u00edntomas.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"9f1a-089a-c041-c2fc-f2a6-136e-df2c-ef95\">\n<p>      El pr\u00edncipe destac\u00f3 que tras la muerte del periodista muchas m\u00e1s personas se sometieron a pruebas de c\u00e1ncer de colon y que se hicieron importantes donaciones a organizaciones dedicadas a la investigaci\u00f3n de la enfermedad.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"01ed-58db-ed75-f8b6-397b-d446-2c15-a04e\">\n<p>      William se sinti\u00f3 honrado de haber conocido a Deborah y de haberla llamado &#8220;Dama&#8221;.  \u201cNunca olvidar\u00e9 su amabilidad, calidez, honestidad y el humor que ten\u00eda en la adversidad.  Aprendamos todos de su pasi\u00f3n por la vida y nos inspiremos en ella\u201d, concluye.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"9a01-f6f1-c18c-cbd4-336b-29d0-91ac-9cd7\">\n      <i>Despu\u00e9s de la muerte de la difunta reina Isabel II, el pr\u00edncipe Carlos pas\u00f3 a llamarse rey Carlos.  Como resultado, William y Kate tambi\u00e9n recibieron un nuevo t\u00edtulo: Pr\u00edncipe y Princesa de Gales.  Esta es la raz\u00f3n por:<\/i>\n    <\/p>\n<p><iframe id=\"sim_7358135032_1\" width=\"100%\" frameborder=\"0\" src=\"https:\/\/simservice.dpgmm.nl\/\/optiext\/optiextension.dll?ID=lq4n2QcnV4324RWkOna0fO1fDJ8z%2B5vz%2BhUB%2BVAXZi4BuMmvUey2GTsQLyRrnnjyb48mnHEJff7m7e&amp;guid=B1F2227C-2983-455F-90AC-50237D6A5DA1&amp;frameid=sim_7358135032_1&amp;reference=\" loading=\"lazy\"><\/iframe> <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"fcde042b-b731-4bd6-9298-0888af604615\">\n      <b>Fuente:<\/b> <a rel=\"nofollow noopener\" href=\"https:\/\/www.welingelichtekringen.nl\/anp\/prins-william-eert-overleden-britse-journaliste-bij-benefietshow\" target=\"_blank\">C\u00edrculos bien informados<\/a>\n    <\/p>\n<section class=\"artstyle__publication-date \" data-element-id=\"article-element-publication-date\"><time class=\"artstyle__publication-date__datetime\" datetime=\"5 november 2023\"><span class=\"artstyle__publication-date__date\">5 de noviembre de 2023<\/span><\/time><\/section>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lea tambi\u00e9n<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.libelle.nl\/actueel\/prins-william-verrast-iedereen-met-een-mooie-boodschap-tijdens-benefietshow~bc9af055b\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-46<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mensaje en v\u00eddeo, el pr\u00edncipe rindi\u00f3 homenaje a la fallecida periodista brit\u00e1nica Deborah James, fallecida el<\/p>\n","protected":false},"author":1,"featured_media":1031481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[13202,885,2091,2186,5459,468,10257],"class_list":["post-1031480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-benefico","tag-durante","tag-principe","tag-show","tag-sorprende","tag-todos","tag-william"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1031480"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1031481"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1031480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1031480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1031480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}