{"id":1031025,"date":"2023-11-04T23:16:04","date_gmt":"2023-11-04T23:16:04","guid":{"rendered":"https:\/\/teknomers.com\/es\/br-volleys-gana-el-thriller-de-cinco-sets-en-friedrichshafen\/"},"modified":"2023-11-04T23:16:08","modified_gmt":"2023-11-04T23:16:08","slug":"br-volleys-gana-el-thriller-de-cinco-sets-en-friedrichshafen","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/br-volleys-gana-el-thriller-de-cinco-sets-en-friedrichshafen\/","title":{"rendered":"BR Volleys gana el thriller de cinco sets en Friedrichshafen"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"post-4715256\">\n<figure class=\"position-relative mb-3\"><figcaption class=\"small fw-bold mt-1\">\n<p>         Us\u00f3 el bal\u00f3n del partido para ganar: Marek Sotola (foto de archivo)                      <span class=\"fw-normal\">Foto: Andreas Gora\/dpa<\/span><br \/>\n            <\/figcaption><\/figure>\n<div class=\"entry-content col-auto col-lg-8 mx-auto\" style=\"min-width: 70%\">\n<p class=\"fw-bold\">\n<p>    De BZ\/dpa\n<\/p>\n<div class=\"w-auto d-flex flex-column-reverse d-lg-block w-mrec\">\n<p class=\"fw-bold\">Los Berlin Volleys se clasificaron para los cuartos de final de la Copa Alemana de Voleibol despu\u00e9s de un emocionante partido de cinco sets.<\/p>\n<\/div>\n<p>El s\u00e1bado, ante su eterno rival, el VfB Friedrichshafen, el defensor de copa de la capital gan\u00f3 3-2 (25:20, 22:25, 26:28, 25:19, 15:13) despu\u00e9s de estar perdiendo 1-2.  El atacante de Diagonal Marek Sotola aprovech\u00f3 el segundo punto de partido para ganar.<\/p>\n<p>Las voleas inicialmente tuvieron el control con su fuerte juego de servicio.  Pero el equipo tuvo problemas cuando en la tercera ronda no s\u00f3lo perdi\u00f3 una ventaja de cinco puntos (13:8) y luego una ventaja de 20:17, sino que al final tampoco pudo utilizar dos puntos de set.  Al final se decidi\u00f3 el desempate, en el que el VfB estuvo constantemente hasta dos puntos por detr\u00e1s.<\/p>\n<p>El SC Potsdam tambi\u00e9n lleg\u00f3 a los cuartos de final en el voleibol femenino.  El equipo del entrenador Riccardo Boieri gan\u00f3 claramente el s\u00e1bado por 3-0 (25:13, 25:21, 25:21) al colista de la Bundesliga, el VC Neuwied 77. <\/p>\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-b-z-die-stimme-berlins wp-block-embed-b-z-die-stimme-berlins\"\/>\n<p><strong>Ante s\u00f3lo 150 espectadores en Neuwied, la estadounidense Danielle Harbin fue la atacante m\u00e1s exitosa del ganador con diez puntos.<\/strong><\/p>\n<\/p><\/div>\n<section data-type=\"tag-links\" class=\"d-flex align-items-center gap-2 mt-4 mb-2\">\n            <span class=\"fw-bold text-nowrap\">Asignaturas: <\/span><br \/>\n            <span class=\"d-flex gap-2 overflow-scroll hide-scrollbar\" data-actions=\"scroll-horizontal\"><\/p>\n<p>                            Balonmano VfB Friedrichshafen<br \/>\n                        <\/span><br \/>\n        <\/section>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.bz-berlin.de\/berlin-sport\/volleys\/br-volleys-gewinnen-fuenf-satz-krimi-in-friedrichshafen\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Us\u00f3 el bal\u00f3n del partido para ganar: Marek Sotola (foto de archivo) Foto: Andreas Gora\/dpa De BZ\/dpa Los<\/p>\n","protected":false},"author":1,"featured_media":1031026,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3370,9107,1418,2994,6693,4057],"class_list":["post-1031025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-cinco","tag-friedrichshafen","tag-gana","tag-sets","tag-thriller","tag-volleys"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1031025"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1031025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1031026"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1031025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1031025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1031025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}