{"id":1030937,"date":"2023-11-04T21:38:04","date_gmt":"2023-11-04T21:38:04","guid":{"rendered":"https:\/\/teknomers.com\/es\/monique-westenberg-bajo-fuego-por-su-opinion-sobre-gaza-maldita-sea\/"},"modified":"2023-11-04T21:38:07","modified_gmt":"2023-11-04T21:38:07","slug":"monique-westenberg-bajo-fuego-por-su-opinion-sobre-gaza-maldita-sea","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/monique-westenberg-bajo-fuego-por-su-opinion-sobre-gaza-maldita-sea\/","title":{"rendered":"Monique Westenberg bajo fuego por su opini\u00f3n sobre Gaza: &#8216;\u00a1Maldita sea!&#8217;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Monique Westenberg est\u00e1 una vez m\u00e1s bajo fuego por su opini\u00f3n sobre la guerra de Gaza y ahora est\u00e1 completamente fuera de su piel de influencer.  &#8220;\u00a1Lo siento con mi coraz\u00f3n!&#8221;<\/p>\n<div class=\"entry__thumb\">\n <span class=\"entry__thumb-description\">\u00a9 RTL<\/span> <\/div>\n<p>Si le piden a Monique Westenberg que se\u00f1ale Israel y la Franja de Gaza en el mapa, probablemente terminar\u00e1 cerca de Curazao.  O cerca de la costa de Espa\u00f1a.  Al menos ella lo sabe.  Sin embargo, ahora expresa su opini\u00f3n d\u00eda tras d\u00eda sobre lo que est\u00e1 sucediendo en la guerra entre Israel y Ham\u00e1s, algo de lo que no sab\u00eda nada hasta hace poco.<\/p>\n<h2 class=\"wp-block-heading\">Donuts y guerra<\/h2>\n<p>Todo comenz\u00f3 hace tres semanas, cuando Monique public\u00f3 un coraz\u00f3n roto por las v\u00edctimas en Israel, junto con la bandera del pa\u00eds.  Dijo que luego el pueblo palestino la llam\u00f3 basura.  \u201cNo tengo conocimiento de que esto tambi\u00e9n haya estado sucediendo en Palestina (durante a\u00f1os).  Dif\u00edcilmente llegamos a ver esto\u201d, dijo luego.<\/p>\n<p>Ahora Monique publica principalmente en Instagram.<em>cuentos<\/em> que destacan el lado palestino.  Entre todo tipo de fotos de los alegres donuts de su hijo, tambi\u00e9n vemos declaraciones en las que habla en contra de la violencia.  \u201cCreo que es una locura\u201d, se lee encima de uno de los mensajes.<\/p>\n<h2 class=\"wp-block-heading\">Fuertes cr\u00edticas<\/h2>\n<p>Monique tambi\u00e9n ha sido objeto de duras cr\u00edticas por esto.  \u201c\u00bfCompartir\u00e1s esto tambi\u00e9n?  \u00bfO menos malo?\u201d, dice uno de sus seguidores con un titular sobre 32 ni\u00f1os israel\u00edes inocentes secuestrados por los terroristas de Ham\u00e1s.<\/p>\n<p>A Monique le resulta realmente molesto.  A ella ya no le gusta.  \u201c\u00a1Todo lo que publico sobre la guerra recibo mensajes directos en los que no parece que me est\u00e9 yendo bien a los ojos de otras personas y s\u00e9 que no soy el \u00fanico!\u201d<\/p>\n<h2 class=\"wp-block-heading\">&#8216;\u00a1MALDITA*MME!&#8217;<\/h2>\n<p>La talla es realmente completa para Monique.  \u201cGente, no me importa de qu\u00e9 lado de la frontera.  \u00a1Se trata de vidas inocentes (de ni\u00f1os)!  \u00a1As\u00ed que tambi\u00e9n creo que esto es terrible!  \u00a1Maldita sea, todos sentimos con el coraz\u00f3n y no con la cabeza!<\/p>\n<p>Todas estas declaraciones de celebridades molestan a cr\u00edticos como Marcel van Roosmalen.  Tiene la idea de que las estrellas muestran su l\u00e1stima principalmente por vanidad e incluso tuvo una peque\u00f1a discusi\u00f3n televisiva con Dolf Jansen.<\/p>\n<h2 class=\"wp-block-heading\">&#8220;Qu\u00e9 verg\u00fcenza&#8221;<\/h2>\n<p>\u00bfQu\u00e9 piensa la haz\u00f3loga Yvonne Coldeweijer de que Monique hable as\u00ed?  &#8220;Es tan <em>avergonzarse<\/em>.  Es muy vergonzoso.  \u00bfQu\u00e9 piensa ella? <em>Me importa un carajo<\/em> sobre esta guerra.  Me importa un carajo.  Me importan una mierda los &#8220;me gusta&#8221; y quiero ser amado, querido y popular y quiero que todos me vean como una persona emp\u00e1tica, porque en realidad no lo soy&#8221;.<\/p>\n<p>A Yvonne le resulta vergonzoso que Monique admitiera inicialmente que no sab\u00eda nada sobre el conflicto.  Ella decide <a rel=\"nofollow noopener\" href=\"https:\/\/podimo.com\/nl\/shows\/de-juice-show\" target=\"_blank\">El espect\u00e1culo del jugo<\/a>: \u201cEs realmente jodidamente est\u00fapido.  Monique, volvamos a hornear croissants.  \u00bfSeguramente a nadie le interesa lo que Monique piensa de Israel?  Por favor, ni\u00f1a\u201d.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.mediacourant.nl\/2023\/11\/monique-westenberg-onder-vuur-om-gaza-mening-verdmme\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-48<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monique Westenberg est\u00e1 una vez m\u00e1s bajo fuego por su opini\u00f3n sobre la guerra de Gaza y ahora<\/p>\n","protected":false},"author":1,"featured_media":1030938,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[5200,658,51742,23893,25981,213872,6178,231,15,131,25982],"class_list":["post-1030937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-bajo","tag-fuego","tag-gaza","tag-maldita","tag-monique","tag-monique-westenberg","tag-opinion","tag-por","tag-sea","tag-sobre","tag-westenberg"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1030937"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1030938"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1030937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1030937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1030937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}