{"id":1030867,"date":"2023-11-04T20:26:17","date_gmt":"2023-11-04T20:26:17","guid":{"rendered":"https:\/\/teknomers.com\/es\/lizzi-19-anos-comio-comida-rapida-con-su-hermana-aun-sufre-las-terribles-consecuencias\/"},"modified":"2023-11-04T20:26:22","modified_gmt":"2023-11-04T20:26:22","slug":"lizzi-19-anos-comio-comida-rapida-con-su-hermana-aun-sufre-las-terribles-consecuencias","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/lizzi-19-anos-comio-comida-rapida-con-su-hermana-aun-sufre-las-terribles-consecuencias\/","title":{"rendered":"Lizzi, 19 a\u00f1os, comi\u00f3 comida r\u00e1pida con su hermana &#8211; A\u00fan sufre las terribles consecuencias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<p>Lizzi Jordan comi\u00f3 comida r\u00e1pida y se qued\u00f3 ciega. <\/p>\n<div itemprop=\"image\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<div class=\"article-image-container\" style=\"height:;padding-bottom:66.66666666666666%\"><img decoding=\"async\" class=\"image image-show\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/11\/1699129577_67_Lizzi-19-anos-comio-comida-rapida-con-su-hermana.jpg\" alt=\"\"\/><\/div>\n<p><meta itemprop=\"url\" content=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/11\/1699129577_67_Lizzi-19-anos-comio-comida-rapida-con-su-hermana.jpg\"\/><meta itemprop=\"width\" content=\"3000\"\/><meta itemprop=\"height\" content=\"2000\"\/><\/p>\n<p><meta itemprop=\"description\" content=\"Lizzi Jordan sokeutui, kun s\u00f6i pikaruokaa ulkona vietetyn illan j\u00e4lkeen. Kuvituskuva.\"\/><span class=\"caption-text\" itemprop=\"description\">Lizzi Jordan qued\u00f3 ciega despu\u00e9s de comer comida r\u00e1pida despu\u00e9s de una noche de fiesta.  Imagen de ilustraci\u00f3n.<!-- --> <\/span><span class=\"media-source\">DOP<\/span><\/p>\n<\/div>\n<div itemprop=\"articleBody\">\n<p class=\"paragraph\"><strong>Lizzi Jordan<\/strong> No adivinaba lo que vendr\u00eda.<\/p>\n<p class=\"paragraph\">Jordan, que estudi\u00f3 psicolog\u00eda, fue a comer comida r\u00e1pida despu\u00e9s de una noche de fiesta en 2017. Contrajo una infecci\u00f3n por colibacter a causa de la comida y, por lo tanto, se intoxic\u00f3.  Su hermana tambi\u00e9n sufri\u00f3 una intoxicaci\u00f3n alimentaria, pero se recuper\u00f3 r\u00e1pidamente.<\/p>\n<p class=\"paragraph\">Fue peor para Jordan.  Fue inducido al coma y luch\u00f3 por su vida.<\/p>\n<p class=\"paragraph\">Cuando Jordan despert\u00f3, estaba ciego.  Ten\u00eda s\u00f3lo 19 a\u00f1os en ese momento.<\/p>\n<p class=\"paragraph\">&#8211; Estaba en muy, muy mal estado.  Sufr\u00ed de insuficiencia org\u00e1nica m\u00faltiple y los m\u00e9dicos advirtieron muchas veces a mis padres que tal vez no lo lograr\u00eda, Jordan <a rel=\"noopener nofollow\" href=\"https:\/\/www.bbc.com\/sport\/disability-sport\/67288807\" target=\"_blank\">recordado a la BBC<\/a>.<\/p>\n<p class=\"paragraph\">A Jordan le dieron un medicamento raro y costoso.  Eso ayudo.<\/p>\n<p class=\"paragraph\">&#8211; Consiguieron despertarme del coma.  Cuando despert\u00e9, hab\u00eda perdido completamente la visi\u00f3n.  Fue aterrador, dijo Jordan.<\/p>\n<p class=\"paragraph\">Jordan se pregunt\u00f3 c\u00f3mo se las arreglar\u00eda sin la vista.  Era su ventana al mundo.  Con la ayuda de la vista, experiment\u00f3 todo.<\/p>\n<p class=\"paragraph\">&#8211; Me dije a m\u00ed mismo que tengo dos opciones: puedo sentarme y hundirme en la autocompasi\u00f3n o puedo intentar vivir mi vida y lograr algo que no habr\u00eda podido hacer con mi vista.<\/p>\n<p class=\"paragraph\">Si la inserci\u00f3n no est\u00e1 visible en tu dispositivo, puedes verla <a rel=\"noopener nofollow\" href=\"https:\/\/www.instagram.com\/p\/CzD7kZDo1cp\/\" target=\"_blank\">de aqu\u00ed<\/a>.<\/p>\n<h3 class=\"subheadline\">\u00c9xito<\/h3>\n<p class=\"paragraph\">Jordan eligi\u00f3 la \u00faltima opci\u00f3n.  Corri\u00f3 el marat\u00f3n de Londres apenas dos a\u00f1os despu\u00e9s, en 2019. Hab\u00eda aprendido a caminar de nuevo apenas unos meses antes.  Con su Run recaud\u00f3 15.000 libras o unos 17.000 euros para fines ben\u00e9ficos.<\/p>\n<p class=\"paragraph\">Un a\u00f1o m\u00e1s tarde asisti\u00f3 a una jornada de pruebas de la Asociaci\u00f3n Brit\u00e1nica de Ciclismo y convenci\u00f3.  No hab\u00eda practicado ciclismo antes de perder la vista, pero aun as\u00ed se abri\u00f3 camino en el ciclismo paracompetitivo.  R\u00e1pidamente ascendi\u00f3 a la cima del deporte y gan\u00f3 el oro y el bronce en el Campeonato Mundial a principios de este a\u00f1o.<\/p>\n<p class=\"paragraph\">Ahora es oficialmente miembro del equipo ciclista nacional de carreras de Gran Breta\u00f1a.<\/p>\n<p class=\"paragraph\">Jordan le dijo a la BBC que lo sucedido lo convirti\u00f3 en una persona mejor, m\u00e1s abierta y m\u00e1s valiente.<\/p>\n<p class=\"paragraph\">Todav\u00eda depende de otros para trasladarse de un lugar a otro.  Se ha apuntado a una formaci\u00f3n en el uso del bast\u00f3n blanco para personas ciegas.<\/p>\n<p class=\"paragraph\">&#8211; Fue un duro golpe cuando perd\u00ed la vista, porque era una persona muy independiente y quer\u00eda conservarla.  Pedir ayuda y depender de otra persona me quit\u00f3 parte de mi orgullo.<\/p>\n<p class=\"paragraph\">Si la inserci\u00f3n no est\u00e1 visible en tu dispositivo, puedes verla <a rel=\"noopener nofollow\" href=\"https:\/\/www.instagram.com\/p\/Cr-bBCzIiz1\/?img_index=2\" target=\"_blank\">de aqu\u00ed<\/a>.<\/p>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.iltalehti.fi\/muutlajit\/a\/12b029ad-7519-4b4d-a369-0f04d22d9c82\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-49<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lizzi Jordan comi\u00f3 comida r\u00e1pida y se qued\u00f3 ciega. Lizzi Jordan qued\u00f3 ciega despu\u00e9s de comer comida r\u00e1pida<\/p>\n","protected":false},"author":1,"featured_media":1030868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[84803,12132,205,174,215,216,1210,99,3911,3819,14765,246,213860,22341,10863,1109,13712,13511],"class_list":["post-1030867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-24-horas","tag-alimento","tag-anos","tag-aun","tag-comida","tag-comida-y-bebida","tag-comio","tag-con","tag-consecuencias","tag-ejercicio-y-deportes","tag-hermana","tag-las","tag-lizzi","tag-medicamentos-y-estupefacientes","tag-rapida","tag-salud","tag-sufre","tag-terribles"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1030867"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1030868"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1030867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1030867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1030867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}