{"id":1030177,"date":"2023-11-04T09:08:27","date_gmt":"2023-11-04T09:08:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/tonali-y-la-investigacion-inglesa-que-puede-pasar-ahora\/"},"modified":"2023-11-04T09:08:31","modified_gmt":"2023-11-04T09:08:31","slug":"tonali-y-la-investigacion-inglesa-que-puede-pasar-ahora","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/tonali-y-la-investigacion-inglesa-que-puede-pasar-ahora\/","title":{"rendered":"Tonali y la investigaci\u00f3n inglesa: qu\u00e9 puede pasar ahora"},"content":{"rendered":"\n<div>\n<p><h2 class=\"is-subtitle\">Sandro corre el riesgo de recibir m\u00e1s sanciones: lo que dicen las reglas del primer ministro y el precedente de Toney.  Tambi\u00e9n es posible una reducci\u00f3n salarial.<\/h2>\n<\/p>\n<div class=\"content not-selectable-js\">\n<p class=\"is-author\">De nuestro corresponsal Davide Chinellato<\/p>\n<p>        <time class=\"article-date\" datetime=\"2023-11-04\" content=\"2023-11-04T09:28:24+01:00\">4 de noviembre<\/p>\n<p>            <span class=\"from-location\">&#8211; Londres<\/span><\/time><\/p>\n<\/div>\n<div class=\"content \" id=\"m13046-13045-13047\">\n<p class=\"paragraph\" spellcheck=\"true\">Los problemas de Sandro Tonali corren el riesgo de no terminar.  La Football Association, la federaci\u00f3n inglesa, ha abierto una investigaci\u00f3n para entender si durante sus tres meses en Inglaterra el joven de 23 a\u00f1os apost\u00f3 por la Premier League o, peor a\u00fan, por su Newcastle.  El jugador italiano, que comenz\u00f3 la semana pasada a cumplir la sanci\u00f3n de 10 meses que le impuso la FIGC y que la FIFA extendi\u00f3 al mundo entero, ya ha sido escuchado y ha ofrecido a la FA la misma colaboraci\u00f3n que ha dado a los investigadores italianos.  La investigaci\u00f3n se basa en el hecho de que Tonali admiti\u00f3 ser un adicto al juego: la federaci\u00f3n inglesa quiere saber si cometi\u00f3 violaciones mientras estaba bajo su jurisdicci\u00f3n.  Lo que podr\u00eda dar lugar a nuevas sanciones. <\/p>\n<\/div>\n<p><!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/adv\/component\/bottom1\/default.shtml]@ --><!--@ESI generic --><\/p>\n<div class=\"content \" id=\"m13070-13069-13071\">\n<h2 class=\"native-summary-content paragraph-summary is-h5 is-uppercase is-mr-r-4 is-inline \" spellcheck=\"true\" id=\"m13123-13122-13124\">opciones<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph\" spellcheck=\"true\">En Inglaterra, como en Italia, los futbolistas (pero tambi\u00e9n cualquier persona relacionada con el f\u00fatbol, \u200b\u200bdesde el cuerpo t\u00e9cnico hasta los directivos y agentes) tienen prohibido apostar en su deporte.  Sin embargo, existe una cierta tolerancia si las apuestas no son sobre tu propio equipo o sobre las competiciones en las que participas.  De lo contrario, se desencadenan sanciones: como la sanci\u00f3n de ocho meses que cumple Ivan Toney del Brentford, la sanci\u00f3n m\u00e1xima jam\u00e1s impuesta a un jugador de la Premier League.  Este precedente sugiere que, si se estableciera que Tonali jug\u00f3 mientras estaba en Inglaterra, la FA podr\u00eda decidir que los 10 meses que ya cumple el joven de 23 a\u00f1os son suficientes, sin necesidad de ampliarlos.  Sin embargo, la FA podr\u00eda a\u00f1adir sanciones como suspender el entrenamiento.  Fue parte del castigo a Toney, que no pudo poner un pie en las instalaciones de su club durante los primeros cuatro meses. <\/p>\n<\/div>\n<div class=\"content \" id=\"m13080-13079-13081\">\n<h2 class=\"native-summary-content paragraph-summary is-h5 is-uppercase is-mr-r-4 is-inline \" spellcheck=\"true\" id=\"m13129-13128-13130\">Newcastle<\/h2>\n<p>\u2014  <\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Tonali, sin embargo, reanud\u00f3 los entrenamientos el jueves, tras superar una peque\u00f1a tarjeta amarilla dada por la forma incorrecta en la que la FIFA hab\u00eda transmitido la descalificaci\u00f3n italiana a la Premier League.  El gobierno mundial del f\u00fatbol habl\u00f3 de una parada gen\u00e9rica &#8220;para cualquier actividad relacionada con el f\u00fatbol&#8221;, pero la descalificaci\u00f3n de la FIGC es muy espec\u00edfica y no incluye los entrenamientos, por ejemplo.  &#8220;Sandro est\u00e1 entrenando y seguir\u00e1 haci\u00e9ndolo solo o en peque\u00f1os grupos &#8211; dijo ayer Howe -. Su objetivo debe ser salir mejorado, pero ser\u00e1 duro para \u00e9l, sobre todo a nivel mental&#8221;.  Dan Ashworth, director deportivo del Newcastle, tambi\u00e9n habl\u00f3 ayer y en un rar\u00edsimo encuentro con los medios de comunicaci\u00f3n explic\u00f3 durante 45 minutos las implicaciones del asunto Tonali, incluido el hecho de que los Magpies han abierto una investigaci\u00f3n interna para entender por qu\u00e9 la adicci\u00f3n al juego no ha surgido. durante el proceso de reclutamiento.  El t\u00e9cnico no neg\u00f3 que el Newcastle pudiera intentar vengarse del Mil\u00e1n, pero los rossoneri siguen repitiendo que se enteraron de los problemas de Tonali por la prensa, cuando la historia se hizo p\u00fablica.  El Club ingl\u00e9s tambi\u00e9n est\u00e1 considerando reducir el salario de Tonali: seg\u00fan el reglamento, puede ser sancionado con una multa equivalente a dos semanas de salario, que puede ampliarse a seis s\u00f3lo con la aprobaci\u00f3n del sindicato de futbolistas ingleses.  Sin embargo, el italiano podr\u00eda aceptar una reducci\u00f3n salarial durante la suspensi\u00f3n como gesto de buena voluntad.<\/p>\n<\/div>\n<div class=\"container-last-content-desktop\">\n<div class=\"content not-selectable-js\">\n<div class=\"bck-copyright\">\n<p class=\"is-above-copyright\">\n            <time datetime=\"2023-11-04T09:28:24+01:00\">4 de noviembre &#8211; 09:28<\/time>\n        <\/p>\n<p class=\"is-copyright\">\u00a9 TODOS LOS DERECHOS RESERVADOS<\/p>\n<\/p><\/div>\n<\/div>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/service-includes\/2019\/SSI\/taboola\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;path=\/service-includes\/2019\/SSI\/taboola\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SERVICE_PATH\/taboola\/default.shtml\" --><\/p>\n<p>                                        <!--@ REQUEST URI :  \/fe-includes\/2019\/SSI\/external-template\/gazzetta\/generic.shtml?env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml--><!--@GLOBAL CONFIG prd--><!--@ fe-include \/fe-includes\/2019\/SSI--><!--@ service-include \/service-includes\/2019\/SSI--><!--@ Type: article--><!--@ Device: desktop--><!--@ESI for [\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml] --><!--@ESI @querystring=[env=prd&amp;device=desktop&amp;cmsType=xalok&amp;type=article&amp;EXT_COMMENTS=xalok&amp;path=\/fe-includes\/2019\/SSI\/components\/comments\/list\/default.shtml]@ --><!--@ESI generic --><br \/>\n                                        <!-- include virtual=\"$SSI_PATH\/components\/comments\/list\/default.shtml\" --><\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.gazzetta.it\/Calcio\/Premier-League\/04-11-2023\/tonali-e-le-scommesse-l-indagine-inglese-cosa-puo-accadere-adesso.shtml\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sandro corre el riesgo de recibir m\u00e1s sanciones: lo que dicen las reglas del primer ministro y el<\/p>\n","protected":false},"author":1,"featured_media":1030178,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[191,3907,1034,8149,149,387,20541],"class_list":["post-1030177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-ahora","tag-inglesa","tag-investigacion","tag-pasar","tag-puede","tag-que","tag-tonali"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1030177"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1030178"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1030177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1030177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1030177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}