{"id":1030174,"date":"2023-11-04T09:07:27","date_gmt":"2023-11-04T09:07:27","guid":{"rendered":"https:\/\/teknomers.com\/es\/aston-martin-lo-hace-como-magnussen\/"},"modified":"2023-11-04T09:07:31","modified_gmt":"2023-11-04T09:07:31","slug":"aston-martin-lo-hace-como-magnussen","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/aston-martin-lo-hace-como-magnussen\/","title":{"rendered":"Aston Martin lo hace como Magnussen"},"content":{"rendered":"\n<div>\n<p>\u00bfQui\u00e9n hubiera apostado a que Aston Martin estar\u00eda en la segunda fila de la parrilla con Lance Stroll y Fernando Alonso en la carrera de F\u00f3rmula 1 en Brasil?  Despu\u00e9s de los desastrosos fines de semana en Estados Unidos y M\u00e9xico, tal escenario parec\u00eda improbable.<\/p>\n<p>Tres de cada cuatro veces la salida fue desde el pit lane mientras el equipo intentaba descubrir m\u00e1s sobre el paquete de actualizaci\u00f3n presentado en Austin.  Para empeorar las cosas, Alonso se retir\u00f3 de ambas carreras por da\u00f1os en los bajos.<\/p>\n<p>El jefe del equipo, Mike Krack, prometi\u00f3 despu\u00e9s de la carrera en M\u00e9xico que Aston Martin confiar\u00eda en los datos para decidir qu\u00e9 correr en Brasil durante el fin de semana y no necesariamente usar\u00eda el paquete completamente nuevo solo para demostrar que funciona.<\/p>\n<p>Los ingenieros decidieron qu\u00e9 funcionar\u00eda mejor para los desaf\u00edos espec\u00edficos en Interlagos, combinando elementos antiguos y nuevos.<\/p>\n<h2>F\u00f3rmula 1: el jefe de Aston Martin &#8220;muy satisfecho&#8221; tras la clasificaci\u00f3n de Brasil<\/h2>\n<p>Hubo se\u00f1ales alentadoras ya que Stroll termin\u00f3 sexto en la pr\u00e1ctica.  Por supuesto, nunca se puede estar seguro de lo que har\u00e1n todos en los entrenamientos, pero esta actuaci\u00f3n se confirm\u00f3 en la clasificaci\u00f3n.<\/p>\n<p>Stroll y Alonso terminaron sexto y s\u00e9ptimo en la Q1 en condiciones normales, y cuando hubo amenaza de lluvia pero la pista a\u00fan estaba seca, el espa\u00f1ol incluso termin\u00f3 cuarto en la Q2, mientras que su compa\u00f1ero de equipo s\u00f3lo fue d\u00e9cimo.<\/p>\n<p><interaction id=\"65436d84cade5d002a239349\" class=\"apester-container hs-socialmedia-container hs-socialmedia-container--type-apester hs-socialmedia-container--orientation-center hs-socialmedia-container--width-max\"\/><\/p>\n<p>El ritmo era realmente bueno y Aston Martin sent\u00eda que s\u00f3lo Red Bull y McLaren ten\u00edan coches m\u00e1s r\u00e1pidos.  En la Q3 todo fue cuesti\u00f3n de cronometrar y aprovechar al m\u00e1ximo la situaci\u00f3n cuando empez\u00f3 a llover.  El equipo de Silverstone y sus pilotos hicieron exactamente lo correcto.<\/p>\n<p>&#8220;Hoy es un buen resultado, creo que todos podemos estar muy contentos con lo que hemos logrado&#8221;, dijo Krack a la voz global de Motorsport.com despu\u00e9s de la sesi\u00f3n.<\/p>\n<p>&#8220;Hoy realmente tenemos que clasificar todo como trabajo en equipo. Desde el an\u00e1lisis que hicimos hasta la elecci\u00f3n del paquete que trajimos aqu\u00ed, la implementaci\u00f3n, la conducci\u00f3n y luego estar all\u00ed al final&#8221;.<\/p>\n<p>\u201cAqu\u00ed las distancias son muy cercanas\u201d, a\u00f1ade el director de interpretaci\u00f3n Tom McCullough.  &#8220;Pero el equipo puso en pista el mejor auto que tenemos con todo lo que hemos aprendido en las \u00faltimas carreras. Y manejaron bien cada sesi\u00f3n. Para ser honesto, qued\u00e9 realmente impresionado con el desempe\u00f1o&#8221;.<\/p>\n<h2>S\u00e9 el primero en salir de boxes<\/h2>\n<p>La clave en la Q3 era llevar ambos coches a la salida de boxes antes que los dem\u00e1s para poder completar una vuelta lo m\u00e1s r\u00e1pido posible.  Si bien esto parece una obviedad en retrospectiva, otros prefirieron salir un poco m\u00e1s tarde, con la esperanza de aprovechar el tiempo justo antes de que llegara la lluvia.<\/p>\n<p>Esto tambi\u00e9n evit\u00f3 que los neum\u00e1ticos perdieran temperatura mientras los pilotos al final del pit lane esperaban que el sem\u00e1foro se pusiera en verde.<\/p>\n<p>Inspirado por lo que Kevin Magnussen hizo con Haas el a\u00f1o pasado cuando sali\u00f3 primero de boxes y consigui\u00f3 la pole position, la estrategia de Aston Martin result\u00f3 correcta a pesar del problema con la temperatura de los neum\u00e1ticos.<\/p>\n<p>McCullough, que era el ingeniero de Nico Hulkenberg en Williams cuando el alem\u00e1n consigui\u00f3 la pole en una pista seca en Brasil hace 13 a\u00f1os, dice que la estrategia era clara.<\/p>\n<p>&#8220;Si tienes los dos primeros coches en la Q3, obviamente tienes m\u00e1s posibilidades de hacer una vuelta antes de que llegue la lluvia&#8221;, enfatiza.  &#8220;Las condiciones eran dif\u00edciles. Las temperaturas de los neum\u00e1ticos tampoco eran \u00f3ptimas. Pero no se puede tener todo&#8221;.<\/p>\n<h2>Magnussen como buen ejemplo<\/h2>\n<p>&#8220;Tambi\u00e9n tuvimos tr\u00e1fico en la vuelta porque algunos de los muchachos que salieron m\u00e1s tarde tambi\u00e9n estorbaron un poco. Pero bueno, segunda fila, tercer y cuarto lugar, un resultado fant\u00e1stico&#8221;.<\/p>\n<p>&#8220;Es como en 2010, cuando Nico consigui\u00f3 la pole. No sabes qu\u00e9 tiempo va a hacer aqu\u00ed, as\u00ed que sales&#8221;, dijo McCullough.  &#8220;Lo vimos con Kevin el a\u00f1o pasado: est\u00e1s por delante, la lluvia llega m\u00e1s r\u00e1pido de lo que te indica el radar y simplemente das una vuelta&#8221;.<\/p>\n<p>&#8220;Est\u00e1bamos bastante decepcionados con las vueltas, no fueron muy buenas, los pilotos tuvieron dificultades. Pero es un juego relativo, \u00bfno? Mucha gente detr\u00e1s de nosotros hizo trompos en el c\u00e9sped y luego lleg\u00f3 la lluvia. Eso fue realmente fant\u00e1stico.&#8221;<\/p>\n<p>Krack est\u00e1 de acuerdo en que la pole de salida de Magnussen en 2022 fue un buen ejemplo de qu\u00e9 hacer cuando se acumulan nubes oscuras en Brasil: &#8220;Aprendimos el a\u00f1o pasado con Kevin que hay que ser el primero en un clima tan amenazador&#8221;, dice.<\/p>\n<p>&#8220;Es cierto que pierdes la temperatura de los neum\u00e1ticos. Pero si est\u00e1s un poco por delante de la lluvia y alguien m\u00e1s recibe la lluvia, eso tiene un impacto mucho mayor que la temperatura de los neum\u00e1ticos&#8221;.<\/p>\n<p>&#8220;As\u00ed que es una decisi\u00f3n que tienes que tomar. El trabajo en el muro de boxes hoy fue realmente de primera clase. Y luego los pilotos hicieron un trabajo fant\u00e1stico, pero tambi\u00e9n fue muy, muy fuerte en el garaje&#8221;, elogia.<\/p>\n<p>&#8220;Y creo que los pilotos tambi\u00e9n tuvieron que implementar eso, y lo hicieron muy bien. Creo que es un gran alivio estar en una mejor posici\u00f3n que la \u00faltima vez&#8221;.<\/p>\n<h2>Nunca el mismo coche en 21 carreras<\/h2>\n<p>Pero, \u00bfqu\u00e9 especificaci\u00f3n del AMR23 utiliz\u00f3 realmente el equipo?  &#8220;Esta configuraci\u00f3n nunca antes se hab\u00eda utilizado&#8221;, dice Krack.  &#8220;Es una mezcla. Siempre digo que los autos son muy complicados, muy complejos, y hay que tratar de entender eso&#8221;.<\/p>\n<p>&#8220;Grandes felicitaciones a todos en la f\u00e1brica y aqu\u00ed, por lo duro que todos han trabajado en las \u00faltimas semanas para definir todo esto, pero tambi\u00e9n para establecer una direcci\u00f3n para el pr\u00f3ximo a\u00f1o. Creo que esto es una recompensa para todos&#8221;.<\/p>\n<p>Tendemos a analizar el impacto inmediato de las actualizaciones, ya sean positivas o negativas, y el mundo inevitablemente ha tenido la impresi\u00f3n de que Aston no ha dado en el blanco con el paquete Austin.  Pero no es tan f\u00e1cil.<\/p>\n<p>\u201cPara ser honesto, nunca hemos usado el mismo paquete en 21 carreras\u201d, dice McCollough, contando la carrera cancelada en Imola.  &#8220;Tenemos una combinaci\u00f3n de piezas que se adapta mejor a esta pista. Y hay muchas piezas en el coche. Aprendimos en la pista a entender el coche y simplemente intentamos ir lo m\u00e1s r\u00e1pido posible&#8221;.<\/p>\n<p>&#8220;Todo el coche es una mezcla de todo lo que haces durante todo el a\u00f1o. Debajo del cap\u00f3 se encuentran los inconvenientes de estos coches de F\u00f3rmula 1. Son los detalles, las peque\u00f1as cosas que la gente no ve. Es una combinaci\u00f3n de muchas partes y, en general, Fue realmente bueno en las condiciones actuales en esta pista&#8221;.<\/p>\n<p>&#8220;La realidad aqu\u00ed es que las diferencias son muy estrechas, pero en seco, creo que Fernando s\u00f3lo fue superado por Red Bull y McLaren. As\u00ed que las diferencias son muy, muy estrechas, como siempre aqu\u00ed. Pero lo que cuenta son los puntos&#8221;. &#8220;<\/p>\n<h2>Stroll \u201chizo un gran trabajo\u201d<\/h2>\n<p>El domingo se ha vuelto muy importante, especialmente para Stroll.  Por supuesto, no ser\u00e1 f\u00e1cil para el canadiense defender su tercer puesto (los McLaren son muy r\u00e1pidos y Lewis Hamilton y Carlos Sainz tambi\u00e9n tienen coches r\u00e1pidos), pero puede dar un gran paso para cambiar la temporada.<\/p>\n<p>&#8220;Hizo un gran trabajo&#8221;, elogia Krack.  &#8220;Quiero decir, no hay nada que decir. Estuvo all\u00ed desde los entrenamientos, estaba contento con el coche. E incluso pas\u00f3 la Q1. De hecho, quer\u00edamos correr tres veces, seg\u00fan los resultados de las \u00faltimas semanas. Pero No era necesario, as\u00ed que se detuvo.&#8221;<\/p>\n<p>&#8220;Y creo que se sinti\u00f3 muy c\u00f3modo. Creo que tuvimos mucha suerte de entrar en la Q3 con ambos coches, porque las diferencias son extremadamente peque\u00f1as. Y luego fue una gran vuelta al final&#8221;, dijo Crack.<\/p>\n<p>&#8220;Al final fue muy dif\u00edcil con el viento cambiante y el tiempo que se avecinaba, pero creo que en general podemos estar contentos y estoy muy feliz por Lance&#8221;, dijo Krack.<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.sport.de\/news\/ne5799380\/formel-1-in-brasilien-aston-martin-schnitt-sich-scheibe-bei-magnussen-ab\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-52<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n hubiera apostado a que Aston Martin estar\u00eda en la segunda fila de la parrilla con Lance Stroll<\/p>\n","protected":false},"author":1,"featured_media":1030175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[8004,6860,440,203901,4644,25371,276,76463,1740,22495,4574,12770],"class_list":["post-1030174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte","tag-aston","tag-automovilismo","tag-como","tag-deportes-en-general","tag-equipo-aston-martin-f1","tag-fernando-alonso","tag-formula-1","tag-gran-premio-de-brasil","tag-hace","tag-magnussen","tag-martin","tag-paseo-de-lanza"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1030174"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1030174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1030175"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1030174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1030174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1030174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}